{"id":401009,"date":"2025-05-22T11:15:07","date_gmt":"2025-05-22T18:15:07","guid":{"rendered":"https:\/\/seewhatgrows.org\/?p=401009"},"modified":"2025-05-22T11:15:12","modified_gmt":"2025-05-22T18:15:12","slug":"learning-to-live-in-the-present","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/us\/es\/learning-to-live-in-the-present\/","title":{"rendered":"Aprendiendo a vivir en el presente"},"content":{"rendered":"<h1 class=\"wp-block-heading has-text-align-center\">Aprendiendo a vivir en el presente: Una gu\u00eda diaria para su hijo<\/h1>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00a1Haz que hoy brille!\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/hxe8M0O53UE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las semanas, los meses y los a\u00f1os parecen pasar volando a medida que envejecemos, \u00bfverdad? Mientras tanto, cuando somos j\u00f3venes, parece que toma toda una vida para que cambie el calendario. En realidad, hay ciencia (\u00bfo es matem\u00e1ticas?) detr\u00e1s de este fen\u00f3meno. Ver\u00e1s, para un ni\u00f1o de 10 a\u00f1os, un a\u00f1o es el 10 por ciento de toda su vida, lo cual es una proporci\u00f3n muy significativa. Pero para alguien que tiene 50 a\u00f1os, un a\u00f1o es solo el 2 por ciento del tiempo que ha pasado en la tierra. Por esto es que el cerebro percibe que el tiempo es m\u00e1s fugaz a medida que envejecemos. El punto de esta lecci\u00f3n es que el tiempo es precioso y, aunque los ni\u00f1os generalmente quieren acelerarlo, nosotros como padres y tutores debemos animarlos a calmar las cosas y vivir el momento. Si supi\u00e9ramos entonces lo que sabemos ahora, sin duda har\u00edamos lo mismo por nuestro yo adolescente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De lo que estamos hablando aqu\u00ed es del concepto de <strong>aprendiendo a vivir en el presente<\/strong>. Implica comprometerse plenamente con el entorno y las experiencias de uno, en lugar de rumiar sobre el pasado o preocuparse por el futuro. Se trata de estar consciente y atento a lo que sucede en este preciso momento, todos y cada uno de los d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas personas confunden el concepto de vivir el momento presente como uno que fomenta el comportamiento caprichoso, ya que uno nunca sabe lo que traer\u00e1 el ma\u00f1ana. Si bien tomarse el tiempo para disfrutar el d\u00eda es absolutamente un componente, no es todo el meollo de vivir en el presente. Como indica la cita de Dale Carnegie del video anterior, <em>hoy es nuestra posesi\u00f3n m\u00e1s preciada<\/em>, y debemos usarlo para esforzarnos al m\u00e1ximo hacia metas que mejoren a\u00fan m\u00e1s nuestras vidas y las de los dem\u00e1s. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, presentamos una gu\u00eda pr\u00e1ctica pero eficaz que le ayudar\u00e1 a fomentar un entorno diario que le ayudar\u00e1 a su hijo a aprender a vivir y prosperar en el momento presente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Gu\u00eda diaria que ayudar\u00e1 a su hijo a aprender a prosperar en el momento presente<\/strong><\/h2>\n\n\n\n<!--more-->\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>I. Despi\u00e9rtate con atenci\u00f3n plena<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Academia de Medicina del Sue\u00f1o, junto con otros expertos en el sue\u00f1o, <a href=\"https:\/\/jcsm.aasm.org\/doi\/10.5664\/jcsm.5866\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">sugiere<\/a> que los ni\u00f1os de 6 a 12 a\u00f1os de edad deben dormir un m\u00ednimo de 9 horas por ciclo de 24 horas de manera regular para promover una salud \u00f3ptima. Los adolescentes de 13 a 18 a\u00f1os deben dormir entre 8 y 10 horas, aunque estamos seguros de que muchos hogares no est\u00e1n acostumbrados a ver a los adolescentes salir tambale\u00e1ndose y refunfu\u00f1ando de sus habitaciones hasta el mediod\u00eda. En cualquier caso, una vez que su hijo haya cumplido con las horas requeridas, h\u00e1gale el h\u00e1bito de despertarse temprano para que pueda aprovechar al m\u00e1ximo su d\u00eda. Por supuesto, esto ocurre por defecto en los d\u00edas de escuela, pero es importante que se levanten temprano los fines de semana y durante las vacaciones escolares. Irse a la cama a una hora razonable por la noche es el catalizador para que ocurra la parte de \u201clevantarse\u201d temprano, \u00bfpero qu\u00e9 pasa con la parte de \u201cbrillar\u201d?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed es donde entra la atenci\u00f3n plena matutina. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La atenci\u00f3n plena matutina consiste en ense\u00f1arle a tu hijo a prestar atenci\u00f3n al presente desde el momento en que se despierta, sin juzgar (a quien sea que lo haya despertado) y a ser consciente de sus pensamientos, sentimientos y del mundo que lo rodea. Le ayuda a desarrollar la autoconciencia, a gestionar esas emociones matutinas, a mejorar la concentraci\u00f3n y a desarrollar resiliencia. En esencia, se trata de desacelerar y notar lo que est\u00e1 sucediendo en el momento, en lugar de apresurarse o quedar atrapado en lo que pudo haber sucedido ayer o lo que suceder\u00e1 ma\u00f1ana. Para introducir la atenci\u00f3n plena en la rutina matutina de tu hijo, comienza con <strong>respiraci\u00f3n consciente<\/strong>, lo cual implica prestar atenci\u00f3n a las sensaciones de inhalar y exhalar, sin tratar de cambiar ni controlar la respiraci\u00f3n. A partir de ah\u00ed, pueden sentarse en la cama y practicar <strong>exploraci\u00f3n sensorial<\/strong>, lo que implica una atenci\u00f3n deliberada a las vistas (es decir, el sol entrando por las persianas), los sonidos (es decir, los p\u00e1jaros cantando), el tacto (es decir, la sensaci\u00f3n de su edred\u00f3n) y el olfato (es decir, el desayuno cocin\u00e1ndose en la cocina) para cultivar la conciencia y la conexi\u00f3n con el momento presente. Tambi\u00e9n es una buena idea incorporar <strong>caminata consciente<\/strong> poco despu\u00e9s de despertar. En un d\u00eda de escuela, esto \u00faltimo puede implicar simplemente salir al patio, y el fin de semana (o durante las vacaciones escolares) puede ser dar un paseo contigo (<a href=\"https:\/\/seewhatgrows.org\/us\/es\/my-child-wants-a-pet-but-we-cant-get-one\/\">o el perro<\/a>) alrededor de la manzana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo esto preparar\u00e1 el terreno para un d\u00eda gratificante que tienes por delante.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>II. Carga combustible para el d\u00eda<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que se hayan levantado y est\u00e9n llenos de energ\u00eda con una atenci\u00f3n plena constante, es hora de recargar energ\u00edas con <strong><a href=\"https:\/\/seewhatgrows.org\/us\/es\/nourish-to-flourish-embracing-the-power-of-food-for-better-health\/\">alimentos saludables, integrales y naturales<\/a><\/strong> que est\u00e1n llenos de nutrientes esenciales. Esto apoyar\u00e1 un mejor rendimiento acad\u00e9mico, creativo y f\u00edsico, la concentraci\u00f3n y el bienestar general para el d\u00eda que se avecina. Establece un plan de comidas que tambi\u00e9n incorpore refrigerios y almuerzos listos para cuando est\u00e9n fuera de casa, y ten una cena nutritiva planeada de antemano (ya sea en casa o fuera) para que no est\u00e9s a las carreras y cedas ante la comida r\u00e1pida conveniente pero poco saludable. Sin una nutrici\u00f3n adecuada desde la ma\u00f1ana hasta la noche, no podr\u00e1n vivir plenamente en el presente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>III. Sigue su lista de prioridades<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de iniciar este itinerario para vivir en el momento presente, deber\u00e1 trabajar con su hijo para establecer una lista de prioridades que se apliquen a su <strong>autodeterminado<\/strong> (para fomentar la participaci\u00f3n) metas acad\u00e9micas, creativas y de actividad f\u00edsica. Juntos crear\u00e1n una hoja de ruta definida que cubra las tareas requeridas en orden de prioridad desde el principio hasta el final de un proyecto o meta. Pueden consultar esta lista al comienzo del d\u00eda, despu\u00e9s del desayuno, para que puedan identificar instant\u00e1neamente qu\u00e9 tarea espec\u00edfica completar para lograr la meta del d\u00eda en cuesti\u00f3n. Algunos d\u00edas, las tareas pueden aplicarse a las tres metas (acad\u00e9mica, creativa, atl\u00e9tica) y otros d\u00edas puede ser solo a una o dos. Para ayudarles a ambos sobre c\u00f3mo integrar esto exactamente en la rutina diaria de su hijo o hija, lean nuestra gu\u00eda sobre <a href=\"https:\/\/seewhatgrows.org\/us\/es\/teaching-kids-to-prioritize\/\"><strong>Ense\u00f1ar a los ni\u00f1os a priorizar<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 pasa si ya han desarrollado el h\u00e1bito de la procrastinaci\u00f3n? Tambi\u00e9n te cubrimos en eso, a trav\u00e9s de esta gu\u00eda para <strong><a href=\"https:\/\/seewhatgrows.org\/us\/es\/how-children-can-learn-to-stop-procrastinating\/\">C\u00f3mo los ni\u00f1os pueden aprender a dejar de procrastinar<\/a><\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-color has-link-color wp-elements-1\" style=\"color:#009860\"><strong>CONSEJO EXTRA: Haga una pausa para momentos de atenci\u00f3n plena (y tonter\u00edas) durante el d\u00eda<\/strong><\/h3>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-2 wp-block-paragraph\" style=\"color:#009860\">Volviendo a la definici\u00f3n de atenci\u00f3n plena anterior (que es realmente lo que significa vivir en el presente), anime a su hijo a seguir el dicho <em>\u201cdetente a oler las rosas\u201d<\/em> durante varios momentos del d\u00eda, tomando nota mental de las vistas, los sonidos, las texturas, los olores y los sabores con los que se encuentran. \u00a1Y an\u00edmalos a hacer tonter\u00edas! Son ni\u00f1os y deben sentirse totalmente libres de tomarse un descanso de alcanzar metas para detenerse y apreciar la alegr\u00eda de la vida cotidiana. Aseg\u00farate de unirte tambi\u00e9n cuando est\u00e9s con ellos, ya sea para perseguir una mariposa, saltar en un charco o mont\u00f3n de hojas, o fingir que el piso es lava al caminar de una habitaci\u00f3n a otra.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos que todo lo anterior haya sido \u00fatil. Mientras tanto, tenga en cuenta que la Fundaci\u00f3n Plant a Seed &amp; See What Grows inspira y promueve una vida y un aprendizaje saludables para los ni\u00f1os en todo Canad\u00e1. \u00a1Puede ayudarnos a ayudar a la pr\u00f3xima generaci\u00f3n comprometiendo tambi\u00e9n su apoyo! Ver m\u00e1s en\u00a0<a href=\"https:\/\/seewhatgrows.org\/us\/es\/get-involved\/\">c\u00f3mo puedes involucrarte<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"785\" src=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg\" alt=\"Learning to Live in the Present for Kids\" class=\"wp-image-401027\" srcset=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg 1200w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids-300x196.jpg 300w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids-1024x670.jpg 1024w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids-768x502.jpg 768w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids-1080x707.jpg 1080w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids-980x641.jpg 980w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids-480x314.jpg 480w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Learning to Live in the Present: A Daily Guide for Your Child The weeks, months, and years seem to fly by as we get older, don&#8217;t they? Meanwhile, when we&#8217;re young, it feels like it takes a lifetime for the calendar to change. There&#8217;s actually science (or is it math?) behind behind this phenomenon. You [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":401027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[912,911,910],"class_list":["post-401009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-learn-to-live-in-the-present-moment","tag-learning-to-be-present-in-the-moment","tag-learning-to-live-in-the-present"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Learning to Live in the Present | Daily Guide for Kids<\/title>\n<meta name=\"description\" content=\"Daily guide that will help your child learn to thrive in the present moment while reaching for their academic, creative, and athletic goals.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/us\/es\/learning-to-live-in-the-present\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Learning to Live in the Present | Daily Guide for Kids\" \/>\n<meta property=\"og:description\" content=\"Daily guide that will help your child learn to thrive in the present moment while reaching for their academic, creative, and athletic goals.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/us\/es\/learning-to-live-in-the-present\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-22T18:15:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-22T18:15:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"785\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/person\\\/2941b91ddd9a26badc98aadef946056c\"},\"headline\":\"Learning to Live in the Present\",\"datePublished\":\"2025-05-22T18:15:07+00:00\",\"dateModified\":\"2025-05-22T18:15:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/\"},\"wordCount\":1222,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg\",\"keywords\":[\"Learn to Live in the Present Moment\",\"Learning to be Present in the Moment\",\"Learning to Live in the Present\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/\",\"name\":\"Learning to Live in the Present | Daily Guide for Kids\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg\",\"datePublished\":\"2025-05-22T18:15:07+00:00\",\"dateModified\":\"2025-05-22T18:15:12+00:00\",\"description\":\"Daily guide that will help your child learn to thrive in the present moment while reaching for their academic, creative, and athletic goals.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg\",\"width\":1200,\"height\":785,\"caption\":\"Learning to Live in the Present for Kids\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/learning-to-live-in-the-present\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learning to Live in the Present\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/person\\\/2941b91ddd9a26badc98aadef946056c\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/es\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Learning to Live in the Present | Daily Guide for Kids","description":"Daily guide that will help your child learn to thrive in the present moment while reaching for their academic, creative, and athletic goals.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/us\/es\/learning-to-live-in-the-present\/","og_locale":"es_MX","og_type":"article","og_title":"Learning to Live in the Present | Daily Guide for Kids","og_description":"Daily guide that will help your child learn to thrive in the present moment while reaching for their academic, creative, and athletic goals.","og_url":"https:\/\/seewhatgrows.org\/us\/es\/learning-to-live-in-the-present\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2025-05-22T18:15:07+00:00","article_modified_time":"2025-05-22T18:15:12+00:00","og_image":[{"width":1200,"height":785,"url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"Escrito por":"Dennis Charland","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/person\/2941b91ddd9a26badc98aadef946056c"},"headline":"Learning to Live in the Present","datePublished":"2025-05-22T18:15:07+00:00","dateModified":"2025-05-22T18:15:12+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/"},"wordCount":1222,"publisher":{"@id":"https:\/\/seewhatgrows.org\/us\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg","keywords":["Learn to Live in the Present Moment","Learning to be Present in the Moment","Learning to Live in the Present"],"articleSection":["Blogs"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/","url":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/","name":"Learning to Live in the Present | Daily Guide for Kids","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/us\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg","datePublished":"2025-05-22T18:15:07+00:00","dateModified":"2025-05-22T18:15:12+00:00","description":"Daily guide that will help your child learn to thrive in the present moment while reaching for their academic, creative, and athletic goals.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/#primaryimage","url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg","contentUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/05\/Learning-to-Live-in-the-Present-Daily-Guide-for-Kids.jpg","width":1200,"height":785,"caption":"Learning to Live in the Present for Kids"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/us\/learning-to-live-in-the-present\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/us\/"},{"@type":"ListItem","position":2,"name":"Learning to Live in the Present"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/us\/#website","url":"https:\/\/seewhatgrows.org\/us\/","name":"Conectando a las comunidades con la tierra","description":"Cultivando comunidades m\u00e1s saludables, una semilla a la vez con la Fundaci\u00f3n Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/us\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/us\/#organization","name":"Conectando a las comunidades con la tierra","url":"https:\/\/seewhatgrows.org\/us\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/person\/2941b91ddd9a26badc98aadef946056c","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/us\/es\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts\/401009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/comments?post=401009"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts\/401009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/media\/401027"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/media?parent=401009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/categories?post=401009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/tags?post=401009"}],"curies":[{"name":"\u00a1Buen juego!","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}