{"id":31375,"date":"2020-07-16T19:35:21","date_gmt":"2020-07-17T02:35:21","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=31375"},"modified":"2020-07-16T19:35:25","modified_gmt":"2020-07-17T02:35:25","slug":"featured-funded-projects-on-the-horizon-for-2020-21","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/us\/es\/featured-funded-projects-on-the-horizon-for-2020-21\/","title":{"rendered":"Proyectos financiados destacados en el horizonte para 2020-21"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Recientemente compartimos una actualizaci\u00f3n sobre la Fundaci\u00f3n <strong>Semillas de inspiraci\u00f3n<\/strong> <strong>(SOI)<\/strong> programa de recursos educativos que a la fecha ha llegado <a href=\"https:\/\/seewhatgrows.org\/us\/es\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/\">cerca de 100,000 estudiantes en todo Canad\u00e1<\/a>. Si bien estamos sumamente orgullosos de nuestro equipo y agradecidos con todos los socios que han ayudado a construir el \u00e9xito de SOI, es solo la punta del iceberg de lo que esperamos lograr en el pr\u00f3ximo a\u00f1o con nuestros otros <a href=\"https:\/\/seewhatgrows.org\/us\/es\/programs\/\">programas financiados<\/a>. Las semillas (proverbiales y literales) de estas iniciativas ya han sido sembradas y los proyectos est\u00e1n cobrando impulso en este mismo momento. Aqu\u00ed se presentan algunos de los puntos destacados que est\u00e1n en marcha este verano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Proyectos intergeneracionales y sostenibles que la Fundaci\u00f3n Plant a Seed &amp; See What Grows est\u00e1 ayudando a crecer en 2020 y m\u00e1s all\u00e1<\/strong><\/h2>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Maple Ridge, Pitt Meadows, Katzie, Seniors Network<\/strong> <strong>Jard\u00edn Intergeneracional, Maple Ridge, BC<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0482.jpg\" alt=\"\" class=\"wp-image-31399\" srcset=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0482.jpg 640w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0482-300x225.jpg 300w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0482-510x382.jpg 510w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0482-24x18.jpg 24w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0482-36x27.jpg 36w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0482-48x36.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Se oye mucho sobre lo que nuestra fundaci\u00f3n est\u00e1 haciendo para ayudar a brindar experiencias de aprendizaje saludables al aire libre para la juventud en todo Canad\u00e1, pero tambi\u00e9n participamos con todos los grupos de edad en la comunidad. Nuestra meta de crear un mundo m\u00e1s sostenible para todas las generaciones est\u00e1 dando un gran paso adelante gracias a nuestra participaci\u00f3n actual en el Jard\u00edn Intergeneracional en Maple Ridge. <a href=\"https:\/\/www.mapleridgenews.com\/community\/intergenerational-garden-in-maple-ridge-set-to-close-if-funding-not-found\/\">Tras perder la financiaci\u00f3n<\/a> Al perder a su principal patrocinador, se nos pidi\u00f3 a nuestra Fundaci\u00f3n que brind\u00e1ramos apoyo financiero para mantener en marcha este valioso proyecto. Y eso fue precisamente lo que hicimos, con una contribuci\u00f3n de $2,500 para apoyar a la organizaci\u00f3n dirigida por personas mayores (y para personas mayores), \u00a1muchas de las cuales son expertas en jardiner\u00eda!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que hace que esta iniciativa sea tan atractiva para nuestra Fundaci\u00f3n es su aspecto intergeneracional. Desde 2012, el programa del Jard\u00edn Intergeneracional ha brindado a las personas mayores participantes la oportunidad de interactuar con las generaciones m\u00e1s j\u00f3venes y compartir sus conocimientos y habilidades. Anualmente, m\u00e1s de 400 estudiantes de escuela primaria y de 15 a 20 voluntarios de la tercera edad participan en las actividades del jard\u00edn, centr\u00e1ndose en el cultivo de alimentos nutritivos y en todo el proceso desde la semilla hasta la mesa:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cEstas intergeneracionales interacciones son un gran beneficio para ambos extremos del espectro de edad y son un aspecto de una comunidad saludable. El intercambio de conocimientos es importante para fomentar nuevas generaciones de jardineros que entiendan de d\u00f3nde viene su comida y la importancia de esta sostenibilidad. Las clases de preescolar, los grupos de educaci\u00f3n en el hogar, los clientes de la Asociaci\u00f3n de Vida Comunitaria de Ridge Meadows y varias organizaciones juveniles tambi\u00e9n visitan y trabajan regularmente en el jard\u00edn.<\/em><a href=\"http:\/\/seniors-network.ca\"><em>seniors-network.ca<\/em><\/a><em>)<\/em><\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0499-rotated.jpg\" alt=\"\" class=\"wp-image-31401\" srcset=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0499-rotated.jpg 480w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0499-225x300.jpg 225w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0499-18x24.jpg 18w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0499-27x36.jpg 27w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0499-36x48.jpg 36w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><figcaption>El Jard\u00edn Intergeneracional cuenta con camas de cultivo espec\u00edficas para los bancos de alimentos.\r\n<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"431\" height=\"601\" src=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0457.jpg\" alt=\"\" class=\"wp-image-31400\" srcset=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0457.jpg 431w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0457-215x300.jpg 215w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0457-17x24.jpg 17w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0457-26x36.jpg 26w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/IMG_0457-34x48.jpg 34w\" sizes=\"auto, (max-width: 431px) 100vw, 431px\" \/><figcaption>Dennis Charland, director ejecutivo de la Fundaci\u00f3n, admir\u00f3 los frondosos huertos familiares.   \r\n<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos muy entusiasmados de ver c\u00f3mo avanza este programa en los meses y a\u00f1os venideros.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Grow Calgary, AB<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"433\" src=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-PAS-2.jpg\" alt=\"Funded Programs PAS 2\" class=\"wp-image-31377\" srcset=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-PAS-2.jpg 900w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-PAS-2-300x144.jpg 300w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-PAS-2-768x369.jpg 768w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-PAS-2-24x12.jpg 24w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-PAS-2-36x17.jpg 36w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-PAS-2-48x23.jpg 48w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.growcalgary.ca\/\">Grow Calgary<\/a> es la granja urbana comunitaria m\u00e1s grande de Canad\u00e1. Son una organizaci\u00f3n sin fines de lucro que cultiva productos frescos para agencias sociales en Calgary, Alberta, con programas de acceso a alimentos. En respuesta a <a href=\"https:\/\/www.instagram.com\/p\/CAEDjrghLjO\/?igshid=eeb2tnhxn13j\">su llamado a donaciones<\/a> la Fundaci\u00f3n Plant a Seed &amp; See What Grows suministr\u00f3 <a href=\"https:\/\/shop.seewhatgrows.flywheelstaging.com\/product\/seed-packs\/\">paquetes de semillas org\u00e1nicas<\/a> Para Grow Calgary:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cGrow Calgary est\u00e1 sumamente agradecido por haber recibido un patrocinio de la Fundaci\u00f3n Plant A Seed &amp; See What Grows. Desde BC, generosamente nos enviaron 40 paquetes de semillas org\u00e1nicas, que incluyen frijoles arbustivos, lechuga, r\u00e1banos, guisantes verdes y equin\u00e1cea. Todos los productos cosechados ser\u00e1n donados directamente a las agencias de acceso a alimentos en Calgary, las cuales sirven a nuestras comunidades m\u00e1s vulnerables. \u00a1Gracias por ayudarnos a fomentar un sistema alimentario m\u00e1s sostenible! (Chelsea Klinke, Directora Ejecutiva, <a href=\"https:\/\/www.growcalgary.ca\/\">Grow Calgary<\/a>)<\/em><\/p><\/blockquote>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"498\" src=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantaSeed-1.jpg\" alt=\"\" class=\"wp-image-31382\" srcset=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantaSeed-1.jpg 900w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantaSeed-1-300x166.jpg 300w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantaSeed-1-768x425.jpg 768w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantaSeed-1-24x13.jpg 24w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantaSeed-1-36x20.jpg 36w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantaSeed-1-48x27.jpg 48w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos ansiosos por ver los frutos (este... \u00a1verduras!) de este programa financiado a medida que se aproxima la pr\u00f3xima cosecha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.kikinoschool.ca\/\">Escuela Kikino, AB<\/a><\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"278\" src=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-Kikino-School-1.jpg\" alt=\"\" class=\"wp-image-31379\" srcset=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-Kikino-School-1.jpg 604w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-Kikino-School-1-300x138.jpg 300w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-Kikino-School-1-24x11.jpg 24w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-Kikino-School-1-36x17.jpg 36w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/Funded-Programs-Kikino-School-1-48x22.jpg 48w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que un gran n\u00famero de escuelas en todo Canad\u00e1, esta instituci\u00f3n del centro de Alberta (al noroeste de Edmonton) contaba con un programa de almuerzos para ayudar a combatir la inseguridad alimentaria en los hogares con ni\u00f1os en edad escolar. Sin embargo, tras sufrir una falta de financiamiento debido a los recortes del gobierno, Kikino perdi\u00f3 su programa de almuerzos. Las consecuencias fueron traum\u00e1ticas, ya que aproximadamente 75% de los ni\u00f1os de Kikino depend\u00edan de los refrigerios y almuerzos que les proporcionaba la escuela.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para crear un programa m\u00e1s sostenible, la escuela decidi\u00f3 ampliar las iniciativas previas de jardiner\u00eda en el campus. Aprovecharon el conocimiento, las habilidades, el entusiasmo y la determinaci\u00f3n tanto de maestros como de estudiantes para comenzar a cultivar alimentos que pudieran servirse como parte de su programa de almuerzos escolares. Hasta la fecha, han adquirido tres invernaderos y tienen un espacio para un nuevo jard\u00edn. Para prepararse para el pr\u00f3ximo a\u00f1o escolar, Kikino desea ofrecer verduras frescas en el oto\u00f1o, cuando las clases se reanuden. Presentaron una solicitud de asistencia a trav\u00e9s de nuestro programa financiado, y nuestra Fundaci\u00f3n respondi\u00f3 de inmediato donando paquetes de semillas org\u00e1nicas para sus 130 estudiantes y miembros del personal. Este jard\u00edn escolar y programa de almuerzos sirve como un ejemplo perfecto de lo que nuestra Fundaci\u00f3n busca lograr de comunidad en comunidad en todo Canad\u00e1. \u00a1Nos honra poder ayudar!<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Obt\u00e9n m\u00e1s informaci\u00f3n sobre <a href=\"https:\/\/seewhatgrows.org\/us\/es\/programs\/\">nuestros proyectos financiados<\/a>, y si desea participar donando su tiempo, talento y\/o recursos, <a href=\"https:\/\/seewhatgrows.org\/us\/es\/get-involved\/\">haga clic aqu\u00ed<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>We recently shared an update on the Foundation\u2019s Seeds of Inspiration (SOI) educational resources program which to date has reached nearly 100,000 students across Canada. While we\u2019re extremely proud of our team and grateful to all of the partners who have helped build the success of SOI, it\u2019s just the tip of the iceberg for [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":31383,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Featured Funded Projects on the Horizon for 2020-21<\/title>\n<meta name=\"description\" content=\"Cross-generational and sustainable projects that the Plant a Seed &amp; See What Grows Foundation Is helping to grow in 2020 and beyond.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/us\/es\/featured-funded-projects-on-the-horizon-for-2020-21\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Featured Funded Projects on the Horizon for 2020-21\" \/>\n<meta property=\"og:description\" content=\"Cross-generational and sustainable projects that the Plant a Seed &amp; See What Grows Foundation Is helping to grow in 2020 and beyond.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/us\/es\/featured-funded-projects-on-the-horizon-for-2020-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-17T02:35:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-17T02:35:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantASeedAndSeeWhatGrows.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1139\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/person\\\/2941b91ddd9a26badc98aadef946056c\"},\"headline\":\"Featured Funded Projects on the Horizon for 2020-21\",\"datePublished\":\"2020-07-17T02:35:21+00:00\",\"dateModified\":\"2020-07-17T02:35:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/\"},\"wordCount\":816,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/PlantASeedAndSeeWhatGrows.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/\",\"name\":\"Featured Funded Projects on the Horizon for 2020-21\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/PlantASeedAndSeeWhatGrows.jpg\",\"datePublished\":\"2020-07-17T02:35:21+00:00\",\"dateModified\":\"2020-07-17T02:35:25+00:00\",\"description\":\"Cross-generational and sustainable projects that the Plant a Seed & See What Grows Foundation Is helping to grow in 2020 and beyond.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/PlantASeedAndSeeWhatGrows.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/PlantASeedAndSeeWhatGrows.jpg\",\"width\":2200,\"height\":1139,\"caption\":\"Garden Programs Canada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/featured-funded-projects-on-the-horizon-for-2020-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Featured Funded Projects on the Horizon for 2020-21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/person\\\/2941b91ddd9a26badc98aadef946056c\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/es\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyectos financiados destacados en el horizonte para 2020-21","description":"Cross-generational and sustainable projects that the Plant a Seed & See What Grows Foundation Is helping to grow in 2020 and beyond.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/us\/es\/featured-funded-projects-on-the-horizon-for-2020-21\/","og_locale":"es_MX","og_type":"article","og_title":"Featured Funded Projects on the Horizon for 2020-21","og_description":"Cross-generational and sustainable projects that the Plant a Seed & See What Grows Foundation Is helping to grow in 2020 and beyond.","og_url":"https:\/\/seewhatgrows.org\/us\/es\/featured-funded-projects-on-the-horizon-for-2020-21\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2020-07-17T02:35:21+00:00","article_modified_time":"2020-07-17T02:35:25+00:00","og_image":[{"width":2200,"height":1139,"url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantASeedAndSeeWhatGrows.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"Escrito por":"Dennis Charland","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/person\/2941b91ddd9a26badc98aadef946056c"},"headline":"Featured Funded Projects on the Horizon for 2020-21","datePublished":"2020-07-17T02:35:21+00:00","dateModified":"2020-07-17T02:35:25+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/"},"wordCount":816,"publisher":{"@id":"https:\/\/seewhatgrows.org\/us\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantASeedAndSeeWhatGrows.jpg","articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/","url":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/","name":"Proyectos financiados destacados en el horizonte para 2020-21","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/us\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantASeedAndSeeWhatGrows.jpg","datePublished":"2020-07-17T02:35:21+00:00","dateModified":"2020-07-17T02:35:25+00:00","description":"Cross-generational and sustainable projects that the Plant a Seed & See What Grows Foundation Is helping to grow in 2020 and beyond.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/#primaryimage","url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantASeedAndSeeWhatGrows.jpg","contentUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2020\/07\/PlantASeedAndSeeWhatGrows.jpg","width":2200,"height":1139,"caption":"Garden Programs Canada"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/us\/featured-funded-projects-on-the-horizon-for-2020-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/us\/"},{"@type":"ListItem","position":2,"name":"Featured Funded Projects on the Horizon for 2020-21"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/us\/#website","url":"https:\/\/seewhatgrows.org\/us\/","name":"Conectando a las comunidades con la tierra","description":"Cultivando comunidades m\u00e1s saludables, una semilla a la vez con la Fundaci\u00f3n Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/us\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/us\/#organization","name":"Conectando a las comunidades con la tierra","url":"https:\/\/seewhatgrows.org\/us\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/person\/2941b91ddd9a26badc98aadef946056c","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/us\/es\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts\/31375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/comments?post=31375"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts\/31375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/media\/31383"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/media?parent=31375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/categories?post=31375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/tags?post=31375"}],"curies":[{"name":"\u00a1Buen juego!","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}