{"id":2043,"date":"2015-10-20T07:59:19","date_gmt":"2015-10-20T14:59:19","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=2043"},"modified":"2015-10-20T07:59:19","modified_gmt":"2015-10-20T14:59:19","slug":"5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/us\/es\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/","title":{"rendered":"5 experiencias y actividades de aprendizaje al aire libre para ni\u00f1os en la temporada de oto\u00f1o"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2047\" src=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg\" alt=\"Outdoor Learning Experiences for Kids in the Fall\" width=\"640\" height=\"290\" srcset=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg 1024w, https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM-300x136.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>El verano es <a href=\"https:\/\/seewhatgrows.org\/us\/es\/5-outdoor-learning-experiences-activities-kids-summer\/\">un momento perfecto del a\u00f1o para el aprendizaje al aire libre<\/a>. Pero el hecho de que la temperatura haya bajado y las hojas hayan cambiado de color no significa que las experiencias de aprendizaje de sus hijos deban relegarse a un sal\u00f3n de clases. De hecho, el oto\u00f1o es una \u00e9poca maravillosa del a\u00f1o para la educaci\u00f3n y las actividades al aire libre en Canad\u00e1. Echemos un vistazo a algunas experiencias divertidas pero instructivas que puede planificar para sus hijos este oto\u00f1o.<\/p>\n<h2>Cinco conceptos divertidos y educativos de aprendizaje al aire libre para el oto\u00f1o<\/h2>\n<p><!--more--><\/p>\n<p><strong>1. Experimente la cosecha de un jard\u00edn comunitario local<\/strong><\/p>\n<p>El oto\u00f1o es una \u00e9poca verdaderamente emocionante para los huertos comunitarios y urbanos. Los ni\u00f1os llegan a experimentar los frutos literarios del trabajo a medida que llega el tiempo de la cosecha. Las frutas y verduras sembradas y cuidadas durante la primavera y el verano est\u00e1n listas para ser cosechadas. Este evento permite a los ni\u00f1os aprender todo sobre el proceso, incluyendo c\u00f3mo recolectar y conservar los productos agr\u00edcolas y <a href=\"https:\/\/seewhatgrows.org\/us\/es\/seed-preservation-methods-home-community-garden\/\">almacenar semillas<\/a> mientras comprenden c\u00f3mo preparar la tierra para la siembra del pr\u00f3ximo a\u00f1o. Pero no se detiene ah\u00ed. Los ni\u00f1os tambi\u00e9n pueden aprender sobre c\u00f3mo un huerto urbano sustentable sirve a la comunidad. Estas iniciativas (<a href=\"https:\/\/seewhatgrows.org\/us\/es\/how-to-get-more-out-of-your-community-garden-program\/\">detallado m\u00e1s a fondo aqu\u00ed<\/a>) incluye llevar los productos a un mercado de agricultores para generar ingresos que se destinan nuevamente al programa y\/o entregar la cosecha a un banco de alimentos local para ayudar a combatir\u00a0<a href=\"http:\/\/www.statcan.gc.ca\/pub\/82-624-x\/2015001\/article\/14138-eng.htm\" target=\"_blank\">inseguridad alimentaria<\/a>.<\/p>\n<p><strong>2. Experimenta la cosecha de una granja local<\/strong><\/p>\n<p>Lleve la experiencia de aprendizaje sobre la cosecha un paso m\u00e1s all\u00e1 llevando a sus hijos a una granja o huerto local. Por ejemplo, si reside en el \u00e1rea de Okanagan, BC, puede aprovechar programas como el\u00a0<a href=\"https:\/\/seewhatgrows.org\/us\/es\/our-causes\/outdoor-learning-experiences\/\">Visitas a las granjas de Natural Factors<\/a>. Una visita a una granja en oto\u00f1o les brindar\u00e1 a sus hijos una comprensi\u00f3n de la cosecha de oto\u00f1o a mayor escala. All\u00ed, no solo pueden aprender sobre el proceso de recolecci\u00f3n de productos \u00fanicos de su regi\u00f3n, sino que tambi\u00e9n pueden aprender c\u00f3mo se empaquetan, conservan y distribuyen a zonas fuera de su \u00e1rea directa. Adem\u00e1s, algunos lugares cuentan con animales de granja en el lugar, lo cual no solo es un deleite para los ni\u00f1os (por razones obvias), sino que les permite aprender c\u00f3mo intervienen (productos l\u00e1cteos, compostaje, etc.) en la producci\u00f3n sostenible de alimentos.<\/p>\n<p><strong>3. Juega y aprende en un campo de calabazas<\/strong><\/p>\n<p>Para los ni\u00f1os, el oto\u00f1o es la temporada de los campos de calabazas. Este nutritivo cultivar de la planta de calabaza se exhibe en todas las verduler\u00edas y mercados de agricultores de la zona durante octubre y noviembre. Brinde a sus hijos la oportunidad de aprender m\u00e1s sobre este popular producto de oto\u00f1o. Ll\u00e9velos a un campo de calabazas local donde puedan informarse sobre c\u00f3mo se plantan, cuidan y cosechan las calabazas. Adem\u00e1s de la recompensa educativa, pueden elegir una para llevar a casa. Muchas granjas de calabazas tambi\u00e9n ofrecen zool\u00f3gicos interactivos, paseos en carreta de heno y cabalgatas en esta \u00e9poca del a\u00f1o. Si vive en el Lower Mainland de BC, ambos <a href=\"http:\/\/www.southlandsfarms.com\" target=\"_blank\">Granja Southland<\/a> y <a href=\"http:\/\/maplewoodfarm.bc.ca\" target=\"_blank\">Granja Maplewood<\/a> son excelentes opciones.<\/p>\n<p><strong>4. Pi\u00e9rdete y aprende en un laberinto de ma\u00edz local<\/strong><\/p>\n<p>Los laberintos de ma\u00edz abundan en Canad\u00e1 en esta \u00e9poca del a\u00f1o. Si bien el factor de diversi\u00f3n es sumamente alto, muchos no se dan cuenta de las oportunidades educativas de estos m-<em>ma\u00edz<\/em>-ing (disculpen, no pudimos resistir la oportunidad del doble juego de palabras) destinos. Una vez m\u00e1s, los ni\u00f1os pueden aprender todo sobre la cosecha de una de las verduras m\u00e1s populares del continente, pero hay m\u00e1s. Los laberintos de ma\u00edz locales, como el famoso de BC\u00a0<strong>Laberinto de ma\u00edz de Chilliwack<\/strong> (y granja de calabazas) usan su zona de actividad para educar al p\u00fablico <a href=\"http:\/\/chilliwackcornmaze.com\/2015\/10\/08\/canucks-autism-network-day-2\/\">sobre el autismo<\/a>\u00a0y otras causas, mientras se gestiona un <a href=\"http:\/\/chilliwackcornmaze.com\/education\/\" target=\"_blank\">centro de educaci\u00f3n agr\u00edcola<\/a>. Dondequiera que est\u00e9s en Canad\u00e1, probablemente haya un laberinto de ma\u00edz cerca de ti para entretener y mantener ocupados a tus hijos este oto\u00f1o.<\/p>\n<p><strong>5. Camina y aprende por un sendero natural<\/strong><\/p>\n<p>A veces todo lo que se necesita es un mapa de senderos para salir al aire libre con tus hijos y disfrutar de las vistas y los sonidos mientras reciben una experiencia educativa improvisada. Ya sean humedales locales o un sendero \u00e1rido tierra adentro, la temporada de oto\u00f1o evidencia el ciclo de la vida en estas zonas. Muchas \u00e1reas protegidas tienen letreros que detallan la flora y la fauna locales que t\u00fa y tus hijos pueden buscar. Divi\u00e9rtanse con el concepto y creen una lista de verificaci\u00f3n para anotar cada elemento que encuentren, y t\u00f3mense una foto de cada uno para crear un registro al que puedan recurrir al volver a casa, donde podr\u00e1n conectarse a internet y aprender m\u00e1s. Aseg\u00farate de llevar algunos bocadillos saludables (\u00a1productos agr\u00edcolas locales!) porque tus hijos no querr\u00e1n irse hasta que el sol de oto\u00f1o descienda.<\/p>\n<p>\u00bfTienes alguna idea de experiencias de aprendizaje al aire libre para ni\u00f1os en esta temporada? Sigue a nuestra fundaci\u00f3n\u00a0<a href=\"https:\/\/www.facebook.com\/Plant-A-Seed-Foundation-264903080380435\/timeline\/\">Facebook<\/a>,\u00a0<a href=\"https:\/\/twitter.com\/seewhatgrows\">Twitter<\/a>, y\/o\u00a0<a href=\"https:\/\/plus.google.com\/+SeewhatgrowsOrg\/posts\">Google+<\/a>\u00a0y comparte tus comentarios con nosotros.<\/p>","protected":false},"excerpt":{"rendered":"<p>Summer is a perfect time of the year for outdoor learning. But just because the temperature has dropped and leaves have changed their tone doesn&#8217;t mean that your kids&#8217; learning experiences need to be relegated to a classroom setting. In fact, autumn is a wondrous time of the year for outdoor education and activities in [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[100,101,98,99],"class_list":["post-2043","post","type-post","status-publish","format-standard","hentry","category-blogs","tag-autumn-harvest","tag-fall-harvesting","tag-outdoor-education","tag-outdoor-learning-experiences-for-kids"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 Outdoor Learning Experiences for Kids in the Fall \/ Autumn<\/title>\n<meta name=\"description\" content=\"Five Fun and Educational Outdoor Learning Concepts for Your Kids in the Autumn Season, Courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/us\/es\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Outdoor Learning Experiences for Kids in the Fall \/ Autumn\" \/>\n<meta property=\"og:description\" content=\"Five Fun and Educational Outdoor Learning Concepts for Your Kids in the Autumn Season, Courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/us\/es\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-20T14:59:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2514\" \/>\n\t<meta property=\"og:image:height\" content=\"1138\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/person\\\/2941b91ddd9a26badc98aadef946056c\"},\"headline\":\"5 Outdoor Learning Experiences and Activities for Kids in the Fall Season\",\"datePublished\":\"2015-10-20T14:59:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/\"},\"wordCount\":790,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg\",\"keywords\":[\"Autumn Harvest\",\"Fall Harvesting\",\"Outdoor Education\",\"Outdoor Learning Experiences for Kids\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/\",\"name\":\"5 Outdoor Learning Experiences for Kids in the Fall \\\/ Autumn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg\",\"datePublished\":\"2015-10-20T14:59:19+00:00\",\"description\":\"Five Fun and Educational Outdoor Learning Concepts for Your Kids in the Autumn Season, Courtesy of the Plant a Seed and See What Grows Foundation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Outdoor Learning Experiences and Activities for Kids in the Fall Season\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/person\\\/2941b91ddd9a26badc98aadef946056c\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/es\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Outdoor Learning Experiences for Kids in the Fall \/ Autumn","description":"Five Fun and Educational Outdoor Learning Concepts for Your Kids in the Autumn Season, Courtesy of the Plant a Seed and See What Grows Foundation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/us\/es\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/","og_locale":"es_MX","og_type":"article","og_title":"5 Outdoor Learning Experiences for Kids in the Fall \/ Autumn","og_description":"Five Fun and Educational Outdoor Learning Concepts for Your Kids in the Autumn Season, Courtesy of the Plant a Seed and See What Grows Foundation.","og_url":"https:\/\/seewhatgrows.org\/us\/es\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2015-10-20T14:59:19+00:00","og_image":[{"width":2514,"height":1138,"url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"Escrito por":"Dennis Charland","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/person\/2941b91ddd9a26badc98aadef946056c"},"headline":"5 Outdoor Learning Experiences and Activities for Kids in the Fall Season","datePublished":"2015-10-20T14:59:19+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/"},"wordCount":790,"publisher":{"@id":"https:\/\/seewhatgrows.org\/us\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg","keywords":["Autumn Harvest","Fall Harvesting","Outdoor Education","Outdoor Learning Experiences for Kids"],"articleSection":["Blogs"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/","url":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/","name":"5 Outdoor Learning Experiences for Kids in the Fall \/ Autumn","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/us\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg","datePublished":"2015-10-20T14:59:19+00:00","description":"Five Fun and Educational Outdoor Learning Concepts for Your Kids in the Autumn Season, Courtesy of the Plant a Seed and See What Grows Foundation.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/#primaryimage","url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg","contentUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2015\/10\/Screen-Shot-2015-10-10-at-11.44.35-AM-1024x464.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/us\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/us\/"},{"@type":"ListItem","position":2,"name":"5 Outdoor Learning Experiences and Activities for Kids in the Fall Season"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/us\/#website","url":"https:\/\/seewhatgrows.org\/us\/","name":"Conectando a las comunidades con la tierra","description":"Cultivando comunidades m\u00e1s saludables, una semilla a la vez con la Fundaci\u00f3n Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/us\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/us\/#organization","name":"Conectando a las comunidades con la tierra","url":"https:\/\/seewhatgrows.org\/us\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/person\/2941b91ddd9a26badc98aadef946056c","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/us\/es\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts\/2043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/comments?post=2043"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/posts\/2043\/revisions"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/media?parent=2043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/categories?post=2043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/tags?post=2043"}],"curies":[{"name":"\u00a1Buen juego!","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}