{"id":399591,"date":"2025-04-01T09:33:20","date_gmt":"2025-04-01T16:33:20","guid":{"rendered":"https:\/\/seewhatgrows.org\/?page_id=399591"},"modified":"2025-04-07T17:30:13","modified_gmt":"2025-04-08T00:30:13","slug":"concours-de-photos-du-jour-et-de-la-semaine-de-la-terre","status":"publish","type":"page","link":"https:\/\/seewhatgrows.org\/us\/es\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/","title":{"rendered":"Concurso de fotograf\u00eda del D\u00eda y de la Semana de la Tierra"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/04\/Photo-Contest-Header-French.png&#8221; title_text=&#8221;Photo Contest Header &#8211; French&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Concours de photos pour c\u00e9l\u00e9brer le Jour de la Terre!&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_color=&#8221;#ee705f&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; hover_enabled=&#8221;0&#8243; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"font-weight: 400;\"><span>Le Jour de la Terre 2025 est une belle occasion pour vos \u00e9l\u00e8ves de d\u00e9ployer leur cr\u00e9ativit\u00e9 pour exprimer leur attachement pour les milieux naturels qui les entourent. Invitez-les \u00e0 dessiner ou \u00e0 prendre des photos pendant vos c\u00e9l\u00e9brations du Jour de la Terre. Qu\u2019elles soient men\u00e9es \u00e0 l\u2019int\u00e9rieur ou \u00e0 l\u2019ext\u00e9rieur, ce type d\u2019activit\u00e9s enseigne aux \u00e9l\u00e8ves des moyens de rendre notre plan\u00e8te encore plus agr\u00e9able \u00e0 vivre.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span>Envoyez-nous vos photos et illustrations inspir\u00e9es des c\u00e9l\u00e9brations du Jour de la Terre organis\u00e9es dans votre \u00e9cole et courez la chance d\u2019obtenir une bourse de jardinage d\u2019une valeur variant entre 250 $ et 1 000 $!<\/span><\/p>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;Quelques id\u00e9es d\u2019activit\u00e9s &#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_color=&#8221;#0f4761&#8243; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|3%|0px|3%|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221;]<\/p>\n<ul>\n<li>Plantation de semis<\/li>\n<li><span>Randonn\u00e9e en for\u00eat ou visite au parc<span>\u00a0 <\/span><\/span><\/li>\n<li><span>Ramassage de d\u00e9chets et de sacs en plastique <span>\u00a0<\/span><\/span><\/li>\n<li><span>Planifier des activit\u00e9s de jardinage (fines herbes, potager, etc.)<\/span><\/li>\n<li><span>Pr\u00e9paration de repas ou de collations sant\u00e9<\/span><\/li>\n<li><span>Autres, car ce ne sont pas les id\u00e9es qui manquent! Nous avons h\u00e2te de d\u00e9couvrir vos fa\u00e7ons tout \u00e0 fait uniques et originales de souligner le Jour et la Semaine de la Terre! <\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e8e8e8&#8243; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|false|true&#8221; custom_padding=&#8221;0px|10%|0px|10%|false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;5%|0px|5%|0px|true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;\u00c0 gagner!&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_color=&#8221;#ee705f&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"font-weight: 400;\"><span>Ces bourses peuvent servir \u00e0 financer votre projet de jardin en milieu scolaire:<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|3%|0px|3%|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221;]<\/p>\n<ul>\n<li><span>Une\u00a0bourse d\u2019une valeur de 1\u00a0000\u00a0$ <\/span><\/li>\n<li><span>Cinq bourses de 500\u00a0$ <\/span><\/li>\n<li><span>Dix bourses de 250\u00a0$ <\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/03\/Photo-Contest-Photo-Collage.jpg&#8221; title_text=&#8221;Microsoft Word &#8211; Earth Day 2025 Webpage&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|1%|2%|1%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;R\u00e8gles du concours&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_color=&#8221;#0f4761&#8243; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|3%|0px|3%|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221;]<\/p>\n<ul>\n<li><span>Ce concours est ouvert \u00e0 toutes les \u00e9coles publiques du Canada.<\/span><\/li>\n<li><span>Nous acceptons jusqu\u2019\u00e0 10 illustrations ou photos par classe.<\/span><\/li>\n<li><span>Soumettez vos images ou photos en haute r\u00e9solution (300 dpi) au format JPEG, GIF ou PNG.<\/span><\/li>\n<li><span>Envoyez-nous une br\u00e8ve description (maximum de 500 mots) de la fa\u00e7on dont vos \u00e9l\u00e8ves ont c\u00e9l\u00e9br\u00e9 le Jour de la Terre 2025. <\/span><\/li>\n<li><span>Date limite de participation\u00a0:\u00a030 avril 2025<\/span><\/li>\n<li><span>Les gagnants seront annonc\u00e9s le 15 juin 2025 par courriel et sur les r\u00e9seaux sociaux.<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;Crit\u00e8res de s\u00e9lection&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_color=&#8221;#0f4761&#8243; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|3%|0px|3%|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221;]<\/p>\n<ul>\n<li><span>Creativit\u00e9\u00a0:\u00a0originalit\u00e9 et caract\u00e8re novateur des activit\u00e9s<\/span><\/li>\n<li><span>Participation\u00a0: les activit\u00e9s \u00e9taient-elles engageantes et rassembleuses? <\/span><\/li>\n<li><span>Sensibilisation\u00a0: les activit\u00e9s ont-elles fait valoir l\u2019importance de prot\u00e9ger la nature et l\u2019environnement aupr\u00e8s des jeunes? <\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;&#8212;&#8212;&#8212;-   FORMULAIRE DE PARTICIPATION    &#8212;&#8212;&#8212;-&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#0f4761&#8243; title_font_size=&#8221;20px&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;25px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;\u00c0 REMPLIR PAR L\u2019ENSEIGNANT(E)&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#0f4761&#8243; title_font_size=&#8221;16px&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][dvppl_cf7_styler cf7=&#8221;399598&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; submit_button_bg_color=&#8221;#ee705f&#8221; submit_button_border_radius=&#8221;0px&#8221; submit_button_letter_spacing=&#8221;0px&#8221; submit_button_font=&#8221;|600|||||||&#8221; submit_button_custom_padding=&#8221;10px|20px|10px|20px|true|true&#8221; submit_button_text_size_tablet=&#8221;&#8221; submit_button_text_size_phone=&#8221;18px&#8221; submit_button_text_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; submit_button_bg_color__hover=&#8221;#0f4761&#8243; submit_button_bg_enable_color__hover=&#8221;on&#8221; submit_button_bg_color__hover_enabled=&#8221;on|desktop&#8221;][\/dvppl_cf7_styler][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;150px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;Bonnes c\u00e9l\u00e9brations du Jour et de la Semaine de la Terre 2025! &#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#ee705f&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/03\/iStock-1135947405-RFS.jpg&#8221; title_text=&#8221;iStock-1135947405 &#8211; RFS&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/04\/Photo-Contest-Header-French.png&#8221; title_text=&#8221;Photo Contest Header &#8211; French&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Concours de photos [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-399591","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concours de photos du Jour et de la Semaine de la Terre - Connecting Communities to the Land<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/us\/es\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concours de photos du Jour et de la Semaine de la Terre - Connecting Communities to the Land\" \/>\n<meta property=\"og:description\" content=\"[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/04\/Photo-Contest-Header-French.png&#8221; title_text=&#8221;Photo Contest Header &#8211; French&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Concours de photos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/us\/es\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T00:30:13+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\\\/\",\"name\":\"Concours de photos du Jour et de la Semaine de la Terre - Connecting Communities to the Land\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#website\"},\"datePublished\":\"2025-04-01T16:33:20+00:00\",\"dateModified\":\"2025-04-08T00:30:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concours de photos du Jour et de la Semaine de la Terre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concours de photos du Jour et de la Semaine de la Terre - Connecting Communities to the Land","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/us\/es\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/","og_locale":"es_MX","og_type":"article","og_title":"Concours de photos du Jour et de la Semaine de la Terre - Connecting Communities to the Land","og_description":"[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2025\/04\/Photo-Contest-Header-French.png&#8221; title_text=&#8221;Photo Contest Header &#8211; French&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Concours de photos [&hellip;]","og_url":"https:\/\/seewhatgrows.org\/us\/es\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/","og_site_name":"Connecting Communities to the Land","article_modified_time":"2025-04-08T00:30:13+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/us\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/","url":"https:\/\/seewhatgrows.org\/us\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/","name":"Concours de photos du Jour et de la Semaine de la Terre - Connecting Communities to the Land","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/us\/#website"},"datePublished":"2025-04-01T16:33:20+00:00","dateModified":"2025-04-08T00:30:13+00:00","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/us\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/us\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/us\/concours-de-photos-du-jour-et-de-la-semaine-de-la-terre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/us\/"},{"@type":"ListItem","position":2,"name":"Concours de photos du Jour et de la Semaine de la Terre"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/us\/#website","url":"https:\/\/seewhatgrows.org\/us\/","name":"Conectando a las comunidades con la tierra","description":"Cultivando comunidades m\u00e1s saludables, una semilla a la vez con la Fundaci\u00f3n Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/us\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/us\/#organization","name":"Conectando a las comunidades con la tierra","url":"https:\/\/seewhatgrows.org\/us\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/us\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/us\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/pages\/399591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/comments?post=399591"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/pages\/399591\/revisions"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/us\/es\/wp-json\/wp\/v2\/media?parent=399591"}],"curies":[{"name":"\u00a1Buen juego!","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}