{"id":4581,"date":"2017-03-22T16:49:15","date_gmt":"2017-03-22T23:49:15","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=4581"},"modified":"2017-04-28T19:10:07","modified_gmt":"2017-04-29T02:10:07","slug":"childrens-films-seeds-plants-get-excited-sustainability","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/childrens-films-seeds-plants-get-excited-sustainability\/","title":{"rendered":"Films pour enfants populaires sur les graines, les plantes et la durabilit\u00e9"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4584\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants.png\" alt=\"Children's Movies About Seeds and Plants\" width=\"640\" height=\"329\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants.png 2000w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants-300x154.png 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants-768x395.png 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants-1024x526.png 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants-24x12.png 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants-36x19.png 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants-48x25.png 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><em>image : Universal Pictures<\/em><\/p>\n<p>&nbsp;<\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Il y a de bons et de mauvais films pour les enfants. En tant que parent ou tuteur, vous \u00eates constamment \u00e0 la recherche de films qui non seulement divertissent vos enfants, mais offrent \u00e9galement une opportunit\u00e9 d'apprendre. Lorsque vous pouvez lier cet apprentissage \u00e0 l'\u00e9cran \u00e0 <a href=\"https:\/\/seewhatgrows.org\/fr\/key-benefits-outdoor-learning-education-children-teens\/\">exp\u00e9riences d'apprentissage en plein air<\/a>, meilleure est son application en tant qu'outil p\u00e9dagogique compl\u00e9mentaire. Il existe de nombreux films pour enfants v\u00e9hiculant un message sous-jacent sur l'environnement, mais parmi tous ces \u201c films verts \u201d, y en a-t-il qui encouragent \u00e9galement la main verte ? C'est certain ! Voici donc notre liste de films populaires pour enfants sur les graines, les plantes et la durabilit\u00e9 :<\/p>\n<\/div>\n<\/div>\n<\/div>\n<h2>4 films populaires qui aideront \u00e0 int\u00e9resser vos enfants au jardinage et \u00e0 l'agriculture durable<\/h2>\n<p><!--more--><\/p>\n<p><strong>Le Lorax<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4585\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seed-and-Plants-2.png\" alt=\"Children's Movies About Seeds\" width=\"640\" height=\"301\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seed-and-Plants-2.png 2000w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seed-and-Plants-2-300x141.png 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seed-and-Plants-2-768x361.png 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seed-and-Plants-2-1024x481.png 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seed-and-Plants-2-24x11.png 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seed-and-Plants-2-36x17.png 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seed-and-Plants-2-48x23.png 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>&nbsp;<\/p>\n<p>Bien avant <em>durabilit\u00e9<\/em> \u00e9tait un hashtag populaire chez les mill\u00e9niaux, Dr. Seuss a publi\u00e9 un livre intitul\u00e9 Le Lorax en 1971, avertissant les jeunes lecteurs que nous, les humains, devons prendre soin de notre plan\u00e8te. C'\u00e9tait <a href=\"https:\/\/greenglobaltravel.com\/10-eco-lessons-we-can-learn-from-the-lorax\/\">riche en le\u00e7ons \u00e9cologiques<\/a>.<\/p>\n<p>Sautant directement en 2012, Le Lorax a fait son arriv\u00e9e sur grand \u00e9cran, d\u00e9livrant un message devenu plus important que jamais. Le th\u00e8me ici n'est pas sous-jacent. Il trace un lien direct entre la destruction de notre environnement (les plantes et les arbres, en particulier) et son impact sur notre capacit\u00e9 \u00e0 mener une existence durable. La perte de la vie v\u00e9g\u00e9tale (et donc de la photosynth\u00e8se) sur cette plan\u00e8te imaginaire entra\u00eene la cr\u00e9ation d'une communaut\u00e9 confin\u00e9e, Thneedville, o\u00f9 les habitants doivent acheter de l'air respirable. Il n'y a ni fruits ni l\u00e9gumes cultiv\u00e9s naturellement dans ce monde, seulement des moules g\u00e9latineux artificiels pour le petit-d\u00e9jeuner, le d\u00e9jeuner et le d\u00eener. Le concept de la graine \u00e0 l'assiette n'existe pas. Du moins, jusqu'\u00e0 ce que le jeune protagoniste (Ted Wiggins) se lance dans une mission pour d\u00e9couvrir ce qui est arriv\u00e9 aux plantes et aux arbres. \u00c0 travers une s\u00e9rie de r\u00e9cits du pass\u00e9 et diverses p\u00e9rip\u00e9ties, il entre en possession de la derni\u00e8re graine. Sa mission ? Prot\u00e9ger cette graine, la planter et voir ce qui pousse.<\/p>\n<p>Le Lorax donnera envie \u00e0 vos enfants de s'int\u00e9resser au concept de <a href=\"https:\/\/seewhatgrows.org\/fr\/our-causes\/seed-preservations\/\">conservation des graines<\/a> et le jardinage\/l'agriculture durable.<\/p>\n<p><strong>FernGully : Les Derniers Rois de la for\u00eat<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4587\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-Plants-Sustainability.jpg\" alt=\"Children's Movies About Sustainability\" width=\"640\" height=\"364\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-Plants-Sustainability.jpg 2090w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-Plants-Sustainability-300x171.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-Plants-Sustainability-768x437.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-Plants-Sustainability-1024x583.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-Plants-Sustainability-24x14.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-Plants-Sustainability-36x20.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-Plants-Sustainability-48x27.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><em>image : 20th Century Fox<\/em><\/p>\n<p style=\"text-align: left;\">Sorti en 1992, Les Aventures de FernGully est d\u00e9sormais un classique et un pionnier parmi les films pour enfants sur le d\u00e9veloppement durable. Bien que les personnages principaux soient des f\u00e9es, le th\u00e8me n'est malheureusement pas rare : la destruction des for\u00eats tropicales.&nbsp;<\/p>\n<p style=\"text-align: left;\">La motivation humaine pour abattre des arbres (le d\u00e9veloppement urbain) est attis\u00e9e par l'antagoniste principal du film,&nbsp;<em>Hexxus<\/em>, dont la puissance cro\u00eet en se nourrissant de la pollution. \u00c0 mesure que davantage d'arbres sont d\u00e9truits, le protagoniste principal,&nbsp;<em>Crysta<\/em>, se souvient d'un ancien proverbe, d\u00e9clarant \u201c<strong>toute la magie de la cr\u00e9ation existe au sein d'une seule et unique petite graine<\/strong>\u201dElle sort une graine de l'un des derniers morceaux de fruit restants, et pi\u00e8ge Hexxus en l'amenant \u00e0 l'avaler, elle et la graine. La graine, avec la magie de la f\u00e9e et l'aide de ses amis de la for\u00eat, fait en sorte que Hexxus redevienne un arbre. La graine enchant\u00e9e est r\u00e9cup\u00e9r\u00e9e, plant\u00e9e, et pour r\u00e9sumer, des le\u00e7ons sont tir\u00e9es par tous (b\u00fbcherons compris) qui mettront fin \u00e0 la destruction de la for\u00eat tropicale. Une fois de plus, nous avons un film qui montre aux enfants comment une seule graine peut sauver toute une communaut\u00e9. Ils se pr\u00e9cipiteront hors de la maison vers votre propre jardin ou jardin communautaire d\u00e8s que le g\u00e9n\u00e9rique commencera.&nbsp;<\/p>\n<p><strong>Bee Movie<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4593\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Gardening.jpg\" alt=\"Children's Movies About Gardening\" width=\"640\" height=\"295\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Gardening.jpg 2170w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Gardening-300x138.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Gardening-768x354.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Gardening-1024x472.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Gardening-24x11.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Gardening-36x17.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Gardening-48x22.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><em>image : Paramount Pictures<\/em><\/p>\n<p>Bee Movie, sorti en 2007, parle du pr\u00e9f\u00e9r\u00e9 du monde <a href=\"https:\/\/seewhatgrows.org\/fr\/kids-guide-beneficial-bugs-garden\/\">insecte b\u00e9n\u00e9fique<\/a>. Cet insecte est essentiel non seulement pour les jardins communautaires locaux et les fermes urbaines, mais aussi pour la sant\u00e9 agricole (et donc humaine) de la plan\u00e8te enti\u00e8re. Bee Movie, malgr\u00e9 l'esprit et le sarcasme classiques de Jerry Seinfeld (qui pr\u00eate sa voix au personnage principal), fait passer ce message haut et fort. Le film est m\u00eame <a href=\"http:\/\/krennscience.weebly.com\/uploads\/2\/2\/6\/8\/22680566\/bee_movie.pdf\">utilis\u00e9 dans les fiches p\u00e9dagogiques pour enseignants<\/a>, posant aux jeunes \u00e9l\u00e8ves des questions telles que \u201c<em>Comment le film montre-t-il que la pollinisation a lieu ?<\/em>\u201det\u201c<em>En r\u00e9alit\u00e9, quelle partie de la vie des plantes serait affect\u00e9e par la disparition des abeilles et que se passerait-il ?<\/em>\u201c.<\/p>\n<p>Regardez le film avec vos enfants et prenez des notes. Ensuite, cr\u00e9ez votre propre fiche d'activit\u00e9s afin de pouvoir faire un suivi et enseigner aux enfants comment les programmes de jardinage locaux ont besoin d'abeilles, ainsi que des notes sur<a href=\"https:\/\/seewhatgrows.org\/fr\/how-protect-beneficial-bugs-winter-garden\/\"> comment les prot\u00e9ger en toutes saisons<\/a>.<\/p>\n<p>Pour en savoir plus sur l'\u00e9tat actuel des abeilles et sur les raisons pour lesquelles nous devons agir d\u00e8s maintenant, veuillez lire notre article de blog invit\u00e9 de <a href=\"https:\/\/seewhatgrows.org\/fr\/time-bee-aware\/\">Contributrice du Huffington Post, Asha Mior<\/a>.<\/p>\n<p><strong>Vaiana<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4588\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Sustainability.jpg\" alt=\"Childrens-Movies-About-Sustainability\" width=\"640\" height=\"266\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Sustainability.jpg 1480w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Sustainability-300x125.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Sustainability-768x320.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Sustainability-1024x426.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Sustainability-24x10.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Sustainability-36x15.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Sustainability-48x20.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: center;\"><em>image : Walt Disney Pictures<\/em><\/p>\n<p>Ce film \u00e0 succ\u00e8s r\u00e9cent a fait une entr\u00e9e fracassante fin 2016, avec un message tr\u00e8s clair (tant dans les chansons que dans les dialogues) sur les communaut\u00e9s durables, v\u00e9hicul\u00e9 peu apr\u00e8s le g\u00e9n\u00e9rique d'ouverture. Le film commence sur une petite \u00eele polyn\u00e9sienne, o\u00f9 les jeunes spectateurs peuvent imm\u00e9diatement saisir l'essence de l'agriculture durable. La communaut\u00e9 insulaire cultive la racine de taro, des bananes et des noix de coco, cultures vitales pour son peuple. Mais lorsqu'un \u00e9l\u00e9ment menace la sant\u00e9 des cultures, les jeunes <em>Vaiana Waialiki<\/em>, fille et h\u00e9riti\u00e8re du chef, prend sur elle de sauver son peuple. Alors que l'introduction de l'arrogant mais agr\u00e9ablement exub\u00e9rant <em>Maui&nbsp;<\/em>injecte de l'humour et une aventure palpitante dans le film, le th\u00e8me principal n'est jamais perdu. Nous n'entrerons pas dans les d\u00e9tails (puisque vous n'avez peut-\u00eatre pas encore vu cette nouveaut\u00e9), mais cela se conclut par un message tr\u00e8s positif sur la fa\u00e7on dont tout ce que nous faisons a un impact sur le monde naturel qui nous entoure, y compris l'agriculture communautaire durable.<\/p>\n<p>Avez-vous d\u00e9couvert des films pour enfants, connus ou m\u00e9connus, qui inciteront les jeunes \u00e0 s'investir dans le jardinage ou l'agriculture durable ? Nous aimerions beaucoup en entendre parler ! Suivez notre Fondation sur&nbsp;<a href=\"https:\/\/www.facebook.com\/Plant-A-Seed-Foundation-264903080380435\/timeline\/\">Facebook<\/a>,&nbsp;<a href=\"https:\/\/twitter.com\/seewhatgrows\">Twitter<\/a>, et\/ou&nbsp;<a href=\"https:\/\/plus.google.com\/+SeewhatgrowsOrg\/posts\">Google+<\/a>, trouvez cet article dans nos publications r\u00e9centes et laissez un commentaire.<\/p>\n<p><a href=\"https:\/\/seewhatgrows.org\/fr\/friends\/9\/\">Veuillez visiter ce lien<\/a>&nbsp;pour en savoir plus sur notre travail au Canada et devenir un Ami de la Fondation.<\/p>","protected":false},"excerpt":{"rendered":"<p>image: Universal Pictures &nbsp; There are good films and bad films for kids. As a parent or guardian you are constantly on the hunt for movies that not only entertain your children, but offer an opportunity to learn. When you can tie that on-screen learning to outdoor learning experiences, the better its application as an [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[235,221,220,237,222,234,236,204,233],"class_list":["post-4581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-bee-movie","tag-childrens-movies-about-plants","tag-childrens-movies-about-seeds","tag-fern-gully","tag-kids-movies-about-sustainability","tag-lorax","tag-moana","tag-seeds","tag-sustainability"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Children&#039;s Movies About Seeds and Plants that Get them Excited About Sustainability<\/title>\n<meta name=\"description\" content=\"4 Popular Films that Will Help Get Your Kids Interested in Sustainable Gardening and Farming, Courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/childrens-films-seeds-plants-get-excited-sustainability\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Children&#039;s Movies About Seeds and Plants that Get them Excited About Sustainability\" \/>\n<meta property=\"og:description\" content=\"4 Popular Films that Will Help Get Your Kids Interested in Sustainable Gardening and Farming, Courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/childrens-films-seeds-plants-get-excited-sustainability\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-22T23:49:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-29T02:10:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants-1024x526.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"Popular Children&#8217;s Films About Seeds, Plants &#038; Sustainability\",\"datePublished\":\"2017-03-22T23:49:15+00:00\",\"dateModified\":\"2017-04-29T02:10:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/\"},\"wordCount\":980,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Childrens-Movies-About-Seeds-and-Plants.png\",\"keywords\":[\"Bee Movie\",\"Children's Movies About Plants\",\"Children's Movies About Seeds\",\"Fern Gully\",\"Kid's Movies About Sustainability\",\"Lorax\",\"Moana\",\"seeds\",\"sustainability\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/\",\"name\":\"Children's Movies About Seeds and Plants that Get them Excited About Sustainability\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Childrens-Movies-About-Seeds-and-Plants.png\",\"datePublished\":\"2017-03-22T23:49:15+00:00\",\"dateModified\":\"2017-04-29T02:10:07+00:00\",\"description\":\"4 Popular Films that Will Help Get Your Kids Interested in Sustainable Gardening and Farming, Courtesy of the Plant a Seed and See What Grows Foundation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Childrens-Movies-About-Seeds-and-Plants.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/Childrens-Movies-About-Seeds-and-Plants.png\",\"width\":2000,\"height\":1028,\"caption\":\"Children's Movies About Seeds and Plants\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/childrens-films-seeds-plants-get-excited-sustainability\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Popular Children&#8217;s Films About Seeds, Plants &#038; Sustainability\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Films pour enfants sur les graines et les plantes qui les passionnent pour le d\u00e9veloppement durable","description":"4 films populaires qui aideront \u00e0 int\u00e9resser vos enfants au jardinage et \u00e0 l'agriculture durable, avec l'aimable collaboration de la fondation \u00ab Plant a Seed and See What Grows \u00bb.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/childrens-films-seeds-plants-get-excited-sustainability\/","og_locale":"fr_CA","og_type":"article","og_title":"Children's Movies About Seeds and Plants that Get them Excited About Sustainability","og_description":"4 Popular Films that Will Help Get Your Kids Interested in Sustainable Gardening and Farming, Courtesy of the Plant a Seed and See What Grows Foundation.","og_url":"https:\/\/seewhatgrows.org\/fr\/childrens-films-seeds-plants-get-excited-sustainability\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2017-03-22T23:49:15+00:00","article_modified_time":"2017-04-29T02:10:07+00:00","og_image":[{"width":1024,"height":526,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants-1024x526.png","type":"image\/png"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"Popular Children&#8217;s Films About Seeds, Plants &#038; Sustainability","datePublished":"2017-03-22T23:49:15+00:00","dateModified":"2017-04-29T02:10:07+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/"},"wordCount":980,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants.png","keywords":["Bee Movie","Children's Movies About Plants","Children's Movies About Seeds","Fern Gully","Kid's Movies About Sustainability","Lorax","Moana","seeds","sustainability"],"articleSection":["Blogs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/","url":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/","name":"Films pour enfants sur les graines et les plantes qui les passionnent pour le d\u00e9veloppement durable","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants.png","datePublished":"2017-03-22T23:49:15+00:00","dateModified":"2017-04-29T02:10:07+00:00","description":"4 films populaires qui aideront \u00e0 int\u00e9resser vos enfants au jardinage et \u00e0 l'agriculture durable, avec l'aimable collaboration de la fondation \u00ab Plant a Seed and See What Grows \u00bb.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2017\/02\/Childrens-Movies-About-Seeds-and-Plants.png","width":2000,"height":1028,"caption":"Children's Movies About Seeds and Plants"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/childrens-films-seeds-plants-get-excited-sustainability\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"Popular Children&#8217;s Films About Seeds, Plants &#038; Sustainability"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/4581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=4581"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/4581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/4584"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=4581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=4581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=4581"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}