{"id":400960,"date":"2025-05-21T11:48:24","date_gmt":"2025-05-21T18:48:24","guid":{"rendered":"https:\/\/seewhatgrows.org\/?p=400960"},"modified":"2025-05-21T11:48:30","modified_gmt":"2025-05-21T18:48:30","slug":"how-to-boost-the-self-esteem-of-a-child-with-disabilities","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/","title":{"rendered":"Comment renforcer l'estime de soi d'un enfant en situation de handicap"},"content":{"rendered":"<h1 class=\"wp-block-heading\"><strong>Comment renforcer l'estime de soi d'un enfant en situation de handicap pendant les vacances d'\u00e9t\u00e9<\/strong><\/h1>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"797\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg\" alt=\"How to Boost the Self Esteem of a Child with Disabilities\" class=\"wp-image-400962\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg 1200w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities-300x199.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities-1024x680.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities-768x510.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities-1080x717.jpg 1080w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities-980x651.jpg 980w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities-480x319.jpg 480w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tu te souviens des vacances d'\u00e9t\u00e9 de notre jeunesse ? Bien s\u00fbr que oui, car non seulement ces siestes scolaires \u00e9taient le point culminant de notre exp\u00e9rience d'adolescents, mais elles offraient aussi l'opportunit\u00e9 de nous r\u00e9inventer. Tu pouvais quitter une classe en juin et revenir en tant que version \u201c nouvelle et am\u00e9lior\u00e9e \u201d de toi-m\u00eame d\u00e8s le premier jour de la rentr\u00e9e en septembre. Lorsque ces deux mois et demi (qui semblent durer une \u00e9ternit\u00e9 quand on est jeune) sont bien mis \u00e0 profit, les enfants b\u00e9n\u00e9ficient d'un bien-\u00eatre physique et mental accru, d'un d\u00e9veloppement des comp\u00e9tences sociales et d'une plus grande ind\u00e9pendance. La pause par rapport aux pressions acad\u00e9miques et des cercles sociaux permet le repos, l'exploration de centres d'int\u00e9r\u00eat et l'occasion de d\u00e9velopper la r\u00e9silience ainsi que de pr\u00e9cieuses comp\u00e9tences de vie. Tout cela m\u00e8ne \u00e0 <strong>estime de soi am\u00e9lior\u00e9e<\/strong> qui est finalement au c\u0153ur de tout d\u00e9sir de r\u00e9invention. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors que l'estime de soi de chaque enfant peut b\u00e9n\u00e9ficier d'unS vacances d'\u00e9t\u00e9 soigneusement planifi\u00e9es par les parents, ceux qui vivent avec un handicap ont encore plus besoin de l'intervention de leurs parents. De nombreuses \u00e9tudes indiquent que les enfants handicap\u00e9s (physiques ou ayant des difficult\u00e9s d'apprentissage) ont une estime de soi plus faible que leurs pairs qui ne pr\u00e9sentent pas les m\u00eames difficult\u00e9s. Des facteurs tels que les difficult\u00e9s scolaires, l'\u00e9tiquetage, l'isolement social et les stigmatisations associ\u00e9es au fait d'avoir un handicap contribuent tous \u00e0 une plus faible estime de soi au sein de cette tranche de la population adolescente. Alors, comment pouvez-vous, en tant que parent d'un enfant qui vit avec un handicap, profiter pleinement de ses prochaines vacances d'\u00e9t\u00e9 pour lui donner une haute opinion de lui-m\u00eame tout en brisant les perceptions mal con\u00e7ues de certains de ses pairs ? En suivant les trois \u00e9tapes puissantes que nous avons d\u00e9finies ci-dessous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3 \u00e9tapes pour transformer vos vacances d'\u00e9t\u00e9 en une source durable de confiance en soi pour un enfant dont l'estime de soi est mise \u00e0 l'\u00e9preuve par un handicap<\/strong> <\/h2>\n\n\n\n<!--more-->\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c9tape 1 : Voyage, voyage, voyage<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voyagez aussi souvent et aussi loin que possible avec votre enfant cet \u00e9t\u00e9. Que ce soit en avion, en train, en voiture, ou une combinaison des trois, l'essentiel est de vous \u00e9loigner de chez vous d\u00e8s que se pr\u00e9sente la moindre opportunit\u00e9. Vous ne pouvez pas partir deux semaines ou plus ? M\u00eame un court voyage chaque week-end tout au long de l'\u00e9t\u00e9 peut faire une grande diff\u00e9rence. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des chercheurs confirment que les exp\u00e9riences de voyage peuvent avoir un impact positif sur l'estime de soi et la confiance en soi d'un adolescent. Cela se produit par le biais des \u00e9l\u00e9ments suivants :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Surmonter les difficult\u00e9s li\u00e9es aux voyages :<\/strong> Voyager en tant que personne en situation de handicap implique de faire face \u00e0 des situations et \u00e0 des d\u00e9fis inhabituels. Nous savons que cela peut vous sortir de votre zone de confort (en tant que parent), mais lorsque votre enfant voit que vous abordez chaque d\u00e9fi avec un calme calcul\u00e9, il adoptera la m\u00eame r\u00e9action \u00e9motionnelle et le m\u00eame comportement. En naviguant avec succ\u00e8s dans de nouveaux environnements et de nouvelles cultures tout en g\u00e9rant les \u00e9v\u00e9nements impr\u00e9vus li\u00e9s aux voyages, la confiance et le sentiment de comp\u00e9tence de votre enfant s'en trouveront am\u00e9lior\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Meilleure conscience de soi et autonomie :<\/strong> Les voyages exposeront votre enfant \u00e0 de nouvelles exp\u00e9riences et perspectives. Cela l'incitera \u00e0 devenir plus conscient de lui-m\u00eame et plus ind\u00e9pendant, \u00e0 condition que vous cessiez de jouer les \u201c micromanagers \u201d et que vous lui ayez permis de prendre des d\u00e9cisions, de suivre des instructions ou de demander de l'aide, lorsque cela est raisonnable pour lui de le faire. Cela renforcera son sentiment d'autonomie !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comp\u00e9tences sociales am\u00e9lior\u00e9es :<\/strong> Les voyages exposeront vos enfants \u00e0 de nouvelles personnes (et cultures) qui, \u00e0 leur connaissance, ignorent tout de leur handicap (quand il n'est pas visible) et\/ou n'ont pas d'a priori \u00e0 ce sujet. Les interactions avec ces nouvelles personnes favoriseront le d\u00e9veloppement de leurs comp\u00e9tences sociales et de leur capacit\u00e9 \u00e0 nouer des relations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Adaptabilit\u00e9 am\u00e9lior\u00e9e :<\/strong> Les voyages augmentent l'exposition \u00e0 des territoires inconnus et \u00e0 des diff\u00e9rences culturelles. Naviguer \u00e0 travers ceux-ci peut aider votre enfant \u00e0 d\u00e9velopper son adaptabilit\u00e9 et sa r\u00e9silience \u00e0 mesure qu'il s'adapte \u00e0 des circonstances changeantes et embrasse de nouvelles exp\u00e9riences. Encore une fois, cela exigera que vous le laissiez (dans la mesure du raisonnable) agir et prendre des d\u00e9cisions par lui-m\u00eame, ou du moins de lui donner un l\u00e9ger coup de pouce dans ce sens. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9sir accru d'explorer et d'en apprendre davantage :<\/strong> Voyager en terre inconnue \u00e9veillera la curiosit\u00e9 de votre enfant qui est probablement habitu\u00e9 \u00e0 une routine assez standardis\u00e9e \u00e0 la maison. Cette curiosit\u00e9 allumera un d\u00e9sir d'en savoir plus sur de \u201c nouveaux mondes \u201d et le motivera \u00e0 s'engager dans de futures activit\u00e9s d'apprentissage lorsque l'occasion se pr\u00e9sentera. C'est \u00e9galement un catalyseur pour renforcer l'estime de soi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Des liens familiaux plus forts :<\/strong> Tout ce qui pr\u00e9c\u00e8de permettra non seulement de cr\u00e9er des souvenirs durables pour votre foyer, mais aussi de favoriser un sentiment mutuel de s\u00e9curit\u00e9 et de confiance entre vous et votre enfant. De plus, les fr\u00e8res et s\u0153urs de votre enfant (le cas \u00e9ch\u00e9ant) rayonneront de fiert\u00e9 en le voyant accomplir des choses qu\u2019ils n\u2019avaient pas eu l\u2019occasion de voir auparavant. En fin de compte, les liens familiaux seront renforc\u00e9s, ce qui constitue un facteur de confiance pour tous.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c9tape 2 : Initiez-vous \u00e0 l'aventure en plein air adapt\u00e9e<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Oh, alors vous pensiez que voyager en soi suffisait pour faire l'affaire ? C'est mignon, mais non ! Il est temps de passer \u00e0 la vitesse sup\u00e9rieure en choisissant des destinations qui offreront \u00e0 votre formidable enfant (et \u00e0 vous-m\u00eame) l'occasion de vivre des aventures inoubliables ! Une fois de plus, nous vous demandons, \u00e0 vous et \u00e0 votre enfant, de sortir de votre zone de confort et d'essayer de nouvelles choses, en plein air. Le <strong>\u00c9cole de l'environnement de Yale<\/strong> <a href=\"https:\/\/e360.yale.edu\/features\/ecopsychology-how-immersion-in-nature-benefits-your-health#:~:text=These%20studies%20have%20shown%20that,and%20lifted%20mood%20among%20patients.\">rapports<\/a> que la pratique d'activit\u00e9s de plein air peut avoir un impact positif sur l'estime de soi des enfants handicap\u00e9s. Cela sera n\u00e9cessaire pour la suite !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Partout au Canada, en Am\u00e9rique du Nord et dans le monde, il existe des programmes d'aventure en plein air qui int\u00e8grent, ou visent sp\u00e9cifiquement, \u00e0 offrir aux enfants vivant avec un handicap l'acc\u00e8s \u00e0 des activit\u00e9s qu'ils n'auraient peut-\u00eatre jamais cru possibles. Des exemples de cela se trouvent partout o\u00f9 les foyers canadiens se rendent pendant leurs vacances d'\u00e9t\u00e9. Par exemple, une organisation extraordinaire \u00e0 Hawa\u00ef connue sous le nom de <a href=\"https:\/\/www.accessurf.org\/\">AccessSurf<\/a> permet aux enfants souffrant de divers handicaps physiques (peu importe leur \u201c gravit\u00e9 \u201d) de se sentir \u00e0 l'aise dans l'oc\u00e9an. Et si vous pensez qu'il s'agit simplement de flotter dans l'eau avec des poissons color\u00e9s, d\u00e9trompez-vous, car l'organisation leur apprend en fait (y compris \u00e0 ceux qui sont confin\u00e9s en fauteuil roulant) \u00e0 surfer ! Pendant ce temps, un certain nombre de <strong>parcs d'aventure tyrolienne<\/strong> <a href=\"https:\/\/www.wildplay.com\/niagara-falls\">tel que WildPlay<\/a> avec des op\u00e9rations en Colombie-Britannique et en Ontario, offrent aux enfants handicap\u00e9s l'acc\u00e8s \u00e0 des \u00e9quipements adapt\u00e9s qui leur permettent de s'\u00e9lancer sur des parcours enti\u00e8rement accessibles ou modifi\u00e9s. Un autre populaire est dirig\u00e9 par <a href=\"https:\/\/tead.on.ca\/\">Centre d'\u00e9quith\u00e9rapie TEAD<\/a>\u00a0en Ontario. TEAD propose aux enfants handicap\u00e9s des programmes d'\u00e9quitation th\u00e9rapeutique ax\u00e9s sur l'am\u00e9lioration des capacit\u00e9s physiques et cognitives, le d\u00e9veloppement social et \u00e9motionnel, ainsi que sur l'augmentation de l'estime de soi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Faites des recherches sur les destinations de plein air o\u00f9 vous voyagez cet \u00e9t\u00e9 pour trouver des programmes d'aventure en plein air adapt\u00e9s. Votre enfant sortira des vacances d'\u00e9t\u00e9 transform\u00e9 en star des sports extr\u00eames avec une estime de soi si haute qu'il lui faudra un parachute !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c9tape 3 : Demandez \u00e0 votre enfant de documenter ses exp\u00e9riences et de partager<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mettez votre enfant aux commandes du catalogage et de la documentation de toutes ses aventures de voyage en plein air cet \u00e9t\u00e9 prochain. Encouragez-le \u00e0 <strong>journal<\/strong> sur leurs exp\u00e9riences (\u00e9crites et\/ou enregistrement vocal) et ont <strong>photos<\/strong> et <strong>vid\u00e9os<\/strong> pris en cours de route. Cela servira non seulement de rappel des choses incroyables qu'ils ont accomplies tout au long de l'\u00e9t\u00e9 \u00e0 mesure que la nouvelle ann\u00e9e scolaire avance, mais ils pourront <strong>partager leurs aventures et leurs nouveaux pouvoirs<\/strong> avec les amis et pairs actuels et nouveaux. Les enfants d'un \u00e2ge appropri\u00e9 peuvent \u00e9galement partager leurs exp\u00e9riences sur leurs r\u00e9seaux sociaux respectifs. Cela montrera \u00e0 leurs pairs qu'ils sont capables de faire des choses extraordinaires. Faire cela n'est pas seulement un facteur de confiance en soi pour eux, c'est un <a href=\"https:\/\/seewhatgrows.org\/fr\/how-kids-can-inspire-other-kids\/\">m\u00e9thode \u00e9prouv\u00e9e pour inspirer les autres enfants<\/a> qui ont du mal avec des probl\u00e8mes d'estime de soi similaires.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous esp\u00e9rons que tout ce qui pr\u00e9c\u00e8de vous a \u00e9t\u00e9 utile, et n'oubliez pas de partager les exp\u00e9riences estivales de votre enfant avec la fondation Plant a Seed &amp; See What Grows <a href=\"https:\/\/www.facebook.com\/SeeWhatGrows\">sur notre Facebook<\/a>. Pendant ce temps, veuillez noter que la fondation \u00ab Plant a Seed &amp; See What Grows \u00bb inspire et promeut un mode de vie sain et l'apprentissage pour les enfants partout au Canada. Vous pouvez nous aider \u00e0 aider la prochaine g\u00e9n\u00e9ration en promettant votre soutien vous aussi ! En voir plus sur\u00a0<a href=\"https:\/\/seewhatgrows.org\/fr\/get-involved\/\">comment vous pouvez participer<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>How to Boost the Self Esteem of a Child with Disabilities this Summer Vacation Remember summer vacations from our youth? Of course you do, because not only were those school siestas the highlight of our adolescent experience, they provided the opportunity to reinvent ourselves. You could leave a grade in June and return as a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":400962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[489,909],"class_list":["post-400960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-children-with-disabilities","tag-how-to-boost-the-self-esteem-of-a-child"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boost the Self Esteem of a Child with a Disability this Summer<\/title>\n<meta name=\"description\" content=\"3 steps to turning your family summer vacation into a lasting confidence-builder for a child whose self esteem is challenged by a disability.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boost the Self Esteem of a Child with a Disability this Summer\" \/>\n<meta property=\"og:description\" content=\"3 steps to turning your family summer vacation into a lasting confidence-builder for a child whose self esteem is challenged by a disability.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-21T18:48:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T18:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"797\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"How to Boost the Self Esteem of a Child with Disabilities\",\"datePublished\":\"2025-05-21T18:48:24+00:00\",\"dateModified\":\"2025-05-21T18:48:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/\"},\"wordCount\":1313,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg\",\"keywords\":[\"Children with Disabilities\",\"How to Boost the Self Esteem of a Child\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/\",\"name\":\"Boost the Self Esteem of a Child with a Disability this Summer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg\",\"datePublished\":\"2025-05-21T18:48:24+00:00\",\"dateModified\":\"2025-05-21T18:48:30+00:00\",\"description\":\"3 steps to turning your family summer vacation into a lasting confidence-builder for a child whose self esteem is challenged by a disability.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg\",\"width\":1200,\"height\":797,\"caption\":\"How to Boost the Self Esteem of a Child with Disabilities\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Boost the Self Esteem of a Child with Disabilities\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renforcer l'estime de soi d'un enfant en situation de handicap cet \u00e9t\u00e9","description":"3 \u00e9tapes pour transformer vos vacances d'\u00e9t\u00e9 en famille en une source durable de confiance en soi pour un enfant dont l'estime de soi est mise \u00e0 l'\u00e9preuve par un handicap.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/","og_locale":"fr_CA","og_type":"article","og_title":"Boost the Self Esteem of a Child with a Disability this Summer","og_description":"3 steps to turning your family summer vacation into a lasting confidence-builder for a child whose self esteem is challenged by a disability.","og_url":"https:\/\/seewhatgrows.org\/fr\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2025-05-21T18:48:24+00:00","article_modified_time":"2025-05-21T18:48:30+00:00","og_image":[{"width":1200,"height":797,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"How to Boost the Self Esteem of a Child with Disabilities","datePublished":"2025-05-21T18:48:24+00:00","dateModified":"2025-05-21T18:48:30+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/"},"wordCount":1313,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg","keywords":["Children with Disabilities","How to Boost the Self Esteem of a Child"],"articleSection":["Blogs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/","url":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/","name":"Renforcer l'estime de soi d'un enfant en situation de handicap cet \u00e9t\u00e9","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg","datePublished":"2025-05-21T18:48:24+00:00","dateModified":"2025-05-21T18:48:30+00:00","description":"3 \u00e9tapes pour transformer vos vacances d'\u00e9t\u00e9 en famille en une source durable de confiance en soi pour un enfant dont l'estime de soi est mise \u00e0 l'\u00e9preuve par un handicap.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/05\/How-to-Boost-the-Self-Esteem-of-a-Child-with-Disabilities.jpg","width":1200,"height":797,"caption":"How to Boost the Self Esteem of a Child with Disabilities"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/how-to-boost-the-self-esteem-of-a-child-with-disabilities\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"How to Boost the Self Esteem of a Child with Disabilities"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/400960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=400960"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/400960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/400962"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=400960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=400960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=400960"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}