{"id":33631,"date":"2022-11-22T13:10:00","date_gmt":"2022-11-22T21:10:00","guid":{"rendered":"https:\/\/seewhatgrows.org\/?p=33631"},"modified":"2022-12-12T16:44:34","modified_gmt":"2022-12-13T00:44:34","slug":"what-to-do-with-all-of-that-snow","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/what-to-do-with-all-of-that-snow\/","title":{"rendered":"Que faire de toute cette neige"},"content":{"rendered":"<p class=\"wp-block-paragraph\">L'hiver est arriv\u00e9 et la neige tombe partout au Canada. Si le premier r\u00e9flexe de vos enfants (ou \u00e9l\u00e8ves) est de bonhomme de neige et d'un arsenal de boules de neige, il y a des exp\u00e9riences d'apprentissage en plein air \u00e0 r\u00e9aliser, dont certaines peuvent \u00eatre b\u00e9n\u00e9fiques pour votre jardin. Jetons un coup d'\u0153il \u00e0 quelques motivations suppl\u00e9mentaires pour sortir avec vos jeunes pendant le pays des merveilles hivernal de cette saison.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3 choses utiles, durables et amusantes que vos enfants peuvent faire avec la neige cet hiver au Canada<\/strong><\/h2>\n\n\n\n<!--more-->\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>R\u00e9colter la neige<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pourquoi diable vos enfants r\u00e9colteraient-ils de la neige ? \u00c7a finit par fondre. Eh bien, c'est pr\u00e9cis\u00e9ment le but ! De la m\u00eame mani\u00e8re que nous encourageons les foyers, les agriculteurs urbains et les jardiniers scolaires \u00e0 <a href=\"https:\/\/seewhatgrows.org\/fr\/water-community-garden-summer-short-supply\/\">installer des r\u00e9cup\u00e9rateurs d'eau de pluie pour collecter l'eau de pluie<\/a> pour les r\u00e9coltes, nous esp\u00e9rons inspirer vos enfants \u00e0 faire de m\u00eame avec la neige. Nous sommes presque certains qu'ils seront ravis de le faire \u2013 n'importe quelle excuse est bonne pour sortir et ramasser cette substance blanche et duveteuse !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez les aider \u00e0 utiliser tous les r\u00e9cup\u00e9rateurs d'eau de pluie existants que vous pourriez avoir pour attraper la neige lorsque cela est pr\u00e9vu. De plus, ils peuvent r\u00e9utiliser des contenants vides de la garde-manger (c'est-\u00e0-dire le seau de prot\u00e9ine en poudre vide du grand fr\u00e8re, etc.) ou de la classe et sortir pour ramasser de la neige et la placer \u00e0 l'int\u00e9rieur. Scellez les contenants et rangez-les en lieu s\u00fbr jusqu'aux prochaines journ\u00e9es prolong\u00e9es sans pr\u00e9cipitations au printemps. Avec le printemps\/l'\u00e9t\u00e9 <a href=\"https:\/\/seewhatgrows.org\/fr\/household-guide-to-planting-a-drought-resistant-garden\/\">conditions de s\u00e9cheresse<\/a> persistant au cours des deux derni\u00e8res ann\u00e9es, la r\u00e9cup\u00e9ration de l'eau (sous toutes ses formes) est devenue tr\u00e8s importante. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus de plaisir, vos enfants peuvent conserver quelques boules de neige dans un coffre de cong\u00e9lation (si vous en avez un) jusqu'au printemps. Le moment venu d'arroser la pelouse ou le jardin, envoyez-les s'entra\u00eener \u00e0 lancer des boules de neige sur un piquet dans le jardin, ce qui aidera \u00e0 humidifier le sol. N'h\u00e9sitez pas \u00e0 remplacer le piquet, si vous l'osez. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construisez une forteresse pour prot\u00e9ger votre jardin d'hiver<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Au-del\u00e0 des bonhommes de neige et des boules de neige, les enfants adorent fabriquer des igloos et d'autres constructions de blocs de neige. Demandez-leur de le faire pour prot\u00e9ger votre jardin d'hiver. Une solide forteresse de neige peut prot\u00e9ger le compost d'hiver (ou m\u00eame les plantes rustiques) contre un certain nombre de menaces. Le vent en est une. <a href=\"https:\/\/seewhatgrows.org\/fr\/how-to-climate-proof-your-family-garden\/\">Consulter ce guide<\/a> ce qui inclut des conseils pour identifier la direction du vent dans votre communaut\u00e9, puis demandez \u00e0 vos enfants de construire une barri\u00e8re de blocs de neige pour le maintenir \u00e0 distance. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, il y a des animaux sauvages qui descendent des montagnes et des collines en hiver. L'un des <a href=\"https:\/\/seewhatgrows.org\/fr\/how-to-keep-wild-animals-out-of-your-garden\/\">\u00e9tapes pour les emp\u00eacher d'entrer dans le jardin<\/a> est de construire une barri\u00e8re. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que la barri\u00e8re contre le vent et les nuisibles ne dure qu'autant que le permettent les temp\u00e9ratures glaciales, elle offre un refuge temporaire \u00e0 vos plantes au repos et \u00e0 votre sol en d\u00e9composition. Plus important encore, elle enseigne \u00e0 vos enfants l'importance de prot\u00e9ger les plantes et les cultures contre les intemp\u00e9ries.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pr\u00e9parez des granitas 100 % naturelles et sant\u00e9<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vos enfants associent peut-\u00eatre les granit\u00e9s \u00e0 l'\u00e9t\u00e9. Cependant, la plupart de ces c\u00f4nes achet\u00e9s dans les camions de glaces d\u00e9bordent de sirops sucr\u00e9s et de conservateurs tels que le benzoate de sodium et bien d'autres. Optez pour le 100 % naturel cet hiver en profitant de la g\u00e9n\u00e9rosit\u00e9 de M\u00e8re Nature venue du ciel. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Commencez par fabriquer vos propres \u201c sirops \u201d et \u201c \u00e9dulcorants \u201d \u00e0 partir de <strong>sources organiques<\/strong> la prochaine fois que de la neige est annonc\u00e9e. Avec une centrifugeuse, vous pouvez faire du jus d'orange, d'ananas, de fraise, de mangue et bien plus encore \u2014 aucun ingr\u00e9dient ajout\u00e9 n'est n\u00e9cessaire. Cela dit, pour une texture plus cr\u00e9meuse, vous pouvez ajouter du lait (de vache, d'amande, d'avoine, etc.) et pour la garniture, vous pouvez vous procurer du miel biologique dans votre magasin d'alimentation naturelle. Mettez les sirops\/\u00e9dulcorants faits maison de c\u00f4t\u00e9 et attendez. Quand la neige tombe, envoyez les enfants dehors pour r\u00e9colter de la fra\u00eeche neige tombante (avant qu'elle ne touche le sol) dans une tasse ou un bol. Lorsqu'ils rentrent \u00e0 l'int\u00e9rieur, demandez-leur de verser les ingr\u00e9dients sains et sucr\u00e9s par-dessus et regardez la d\u00e9licieuse mixture s'infiltrer. C'est la friandise d'hiver 100 % naturelle par excellence !<\/p>","protected":false},"excerpt":{"rendered":"<p>Winter is upon us and snow is falling all across Canada. While your kids&#8217; (children or students) first instinct is to build a snowman and an arsenal of snowballs, there are some outdoor learning experiences to be had, including a few that can be beneficial for your garden. Let&#8217;s have a look at some added [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":33633,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-33631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>What to do With All of That Snow<\/title>\n<meta name=\"description\" content=\"Three helpful, sustainable, fun, and engaging things your kids can do with snow this winter season across Canada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/what-to-do-with-all-of-that-snow\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What to do With All of That Snow\" \/>\n<meta property=\"og:description\" content=\"Three helpful, sustainable, fun, and engaging things your kids can do with snow this winter season across Canada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/what-to-do-with-all-of-that-snow\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-22T21:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-13T00:44:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/11\/What-to-do-With-All-of-That-Snow.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"What to do With All of That Snow\",\"datePublished\":\"2022-11-22T21:10:00+00:00\",\"dateModified\":\"2022-12-13T00:44:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/\"},\"wordCount\":647,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/What-to-do-With-All-of-That-Snow.jpg\",\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/\",\"name\":\"What to do With All of That Snow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/What-to-do-With-All-of-That-Snow.jpg\",\"datePublished\":\"2022-11-22T21:10:00+00:00\",\"dateModified\":\"2022-12-13T00:44:34+00:00\",\"description\":\"Three helpful, sustainable, fun, and engaging things your kids can do with snow this winter season across Canada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/What-to-do-With-All-of-That-Snow.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/What-to-do-With-All-of-That-Snow.jpg\",\"width\":1200,\"height\":612,\"caption\":\"What to do With All of That Snow\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/what-to-do-with-all-of-that-snow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What to do With All of That Snow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que faire de toute cette neige","description":"Trois activit\u00e9s utiles, durables, amusantes et stimulantes que vos enfants peuvent faire avec la neige cet hiver partout au Canada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/what-to-do-with-all-of-that-snow\/","og_locale":"fr_CA","og_type":"article","og_title":"What to do With All of That Snow","og_description":"Three helpful, sustainable, fun, and engaging things your kids can do with snow this winter season across Canada.","og_url":"https:\/\/seewhatgrows.org\/fr\/what-to-do-with-all-of-that-snow\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2022-11-22T21:10:00+00:00","article_modified_time":"2022-12-13T00:44:34+00:00","og_image":[{"width":1200,"height":612,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/11\/What-to-do-With-All-of-That-Snow.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"What to do With All of That Snow","datePublished":"2022-11-22T21:10:00+00:00","dateModified":"2022-12-13T00:44:34+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/"},"wordCount":647,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/11\/What-to-do-With-All-of-That-Snow.jpg","articleSection":["Blogs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/","url":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/","name":"Que faire de toute cette neige","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/11\/What-to-do-With-All-of-That-Snow.jpg","datePublished":"2022-11-22T21:10:00+00:00","dateModified":"2022-12-13T00:44:34+00:00","description":"Trois activit\u00e9s utiles, durables, amusantes et stimulantes que vos enfants peuvent faire avec la neige cet hiver partout au Canada.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/11\/What-to-do-With-All-of-That-Snow.jpg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/11\/What-to-do-With-All-of-That-Snow.jpg","width":1200,"height":612,"caption":"What to do With All of That Snow"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/what-to-do-with-all-of-that-snow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"What to do With All of That Snow"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/33631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=33631"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/33631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/33633"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=33631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=33631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=33631"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}