{"id":32735,"date":"2022-01-18T13:19:12","date_gmt":"2022-01-18T21:19:12","guid":{"rendered":"https:\/\/seewhatgrows.org\/?p=32735"},"modified":"2022-01-18T13:20:12","modified_gmt":"2022-01-18T21:20:12","slug":"how-to-celebrate-international-day-of-education-2022","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-international-day-of-education-2022\/","title":{"rendered":"Comment c\u00e9l\u00e9brer la Journ\u00e9e internationale de l'\u00e9ducation 2022"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La Journ\u00e9e internationale de l'\u00e9ducation des Nations Unies approche (24 janvier 2022). Le th\u00e8me de cette ann\u00e9e est le suivant :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cLa Journ\u00e9e internationale de l'\u00e9ducation de cette ann\u00e9e servira de plateforme pour pr\u00e9senter les transformations les plus importantes qui doivent \u00eatre encourag\u00e9es afin de concr\u00e9tiser le droit fondamental de chacun \u00e0 l'\u00e9ducation et de b\u00e2tir des avenirs plus durables, inclusifs et pacifiques. Elle stimulera le d\u00e9bat sur la mani\u00e8re de renforcer l'\u00e9ducation en tant qu'entreprise publique et bien commun, de guider la transformation num\u00e9rique, de soutenir les enseignants, de pr\u00e9server la plan\u00e8te et de lib\u00e9rer le potentiel de chaque individu pour contribuer au bien-\u00eatre collectif et \u00e0 notre maison commune.\u201d<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Afin de fournir \u00e0 nos propres communaut\u00e9s (au Canada) des id\u00e9es sur la mani\u00e8re de reconna\u00eetre cette journ\u00e9e importante, nous nous tournons vers les objectifs d\u00e9clar\u00e9s de l'ONU.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong>OBJECTIF 1<\/strong><\/h3>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong><em>\u201cComment renforcer l'\u00e9ducation en tant qu'entreprise publique et bien commun\u201d<\/em><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tout d'abord, il est important que nous nous unissions tous pour am\u00e9liorer l'\u00e9ducation dans nos propres communaut\u00e9s. Cela peut commencer \u00e0 la maison, en faisant d\u00e9couvrir \u00e0 vos enfants des supports qui les encourageront \u00e0 continuer d'apprendre en dehors de la classe. La fondation Plant a Seed &amp; See What Grows propose des jeux, des guides d'activit\u00e9s et des cahiers d'exercices t\u00e9l\u00e9chargeables pour offrir \u00e0 vos enfants des activit\u00e9s amusantes, stimulantes et \u00e9ducatives. D\u00e9couvrez-en davantage sur notre <a href=\"https:\/\/seewhatgrows.org\/fr\/kids-corner\/\">Le coin des enfants<\/a>. Assurez-vous de partager ceux-ci <strong>outils gratuits<\/strong> avec vos amis, vos voisins et les autres parents d'\u00e9l\u00e8ves. Au-del\u00e0 de votre propre foyer, <a href=\"https:\/\/seewhatgrows.org\/fr\/get-involved\/\">montrer son soutien<\/a> pour les organisations qui offrent un meilleur acc\u00e8s \u00e0 <a href=\"https:\/\/seewhatgrows.org\/fr\/our-causes\/outdoor-learning-experiences\/\">exp\u00e9riences d'apprentissage au Canada<\/a>. Nous ne pouvons tout simplement pas compter uniquement sur les \u00e9coles traditionnelles pour renforcer l'\u00e9ducation dans nos villes et nos villages. Cela doit \u00eatre un effort communautaire !<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong>OBJECTIF 2<\/strong><\/h3>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong><em>\u201cComment piloter la transformation num\u00e9rique\u201d<\/em><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que parents et \u00e9ducateurs, nous marchons souvent sur des \u0153ufs face aux m\u00e9dias num\u00e9riques, sachant qu'ils peuvent tout aussi bien nuire \u00e0 nos enfants qu'ils ne peuvent favoriser leur \u00e9ducation. Comment garantir ce dernier point ? Comment tirer parti de la transformation num\u00e9rique pour qu'elle serve leur sant\u00e9 physique, \u00e9motionnelle et intellectuelle ? Pour commencer, faites-leur d\u00e9couvrir des applications \u00e0 la fois ludiques et \u00e9ducatives. Au fil des ans, notre Fondation a s\u00e9lectionn\u00e9 des listes d'applications mobiles pour enseigner des concepts importants aux enfants. Bien de nouvelles applications sortent tous les quelques mois, la liste suivante constitue une bonne base :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/seewhatgrows.org\/fr\/10-best-health-nutrition-apps-kids\/\">Les 10 meilleures applications de sant\u00e9 et d&#x27;\u00e9ducation pour les enfants<\/a><\/li><li><a href=\"https:\/\/seewhatgrows.org\/fr\/top-apps-teaching-kids-environment-sustainability\/\">Meilleures applications pour enseigner aux enfants l'environnement et le d\u00e9veloppement durable<\/a><\/li><li><a href=\"https:\/\/seewhatgrows.org\/fr\/best-outdoor-learning-apps-for-kids-2018\/\">Les meilleures applications d&#x27;apprentissage en plein air<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En plus des applications pour smartphone et tablette, vos enfants ou \u00e9l\u00e8ves passent probablement beaucoup de temps \u00e0 regarder des programmes en streaming \u00e0 la t\u00e9l\u00e9vision. Bien qu'ils aient certainement le droit de profiter d'une \u00e9vasion cin\u00e9matographique de temps en temps, veillez \u00e0 int\u00e9grer les \u00e9l\u00e9ments suivants dans le programme de votre famille ou de votre classe :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/seewhatgrows.org\/fr\/childrens-films-seeds-plants-get-excited-sustainability\/\">Films pour enfants populaires sur les graines, les plantes et le d\u00e9veloppement durable<\/a><\/li><li><a href=\"https:\/\/seewhatgrows.org\/fr\/gardening-and-farming-shows-for-the-family\/\">\u00c9missions de jardinage et d'agriculture pour la famille<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">De nombreux parents et \u00e9coles ont trouv\u00e9 utile d'examiner comment utiliser la transformation num\u00e9rique <a href=\"https:\/\/seewhatgrows.org\/fr\/spread-word-community-garden-get-support\/\">pour promouvoir les jardins scolaires et communautaires<\/a>, auxquelles vous pouvez faire participer vos enfants ou vos \u00e9l\u00e8ves.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong>OBJECTIF 3<\/strong><\/h3>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong><em>\u201c Comment soutenir les enseignants \u201d<\/em><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nous n'avons peut-\u00eatre pas le pouvoir d'augmenter les salaires des enseignants au Canada, mais nous pouvons contribuer \u00e0 leur fournir des outils pour leur faciliter la t\u00e2che et mieux mobiliser leurs \u00e9l\u00e8ves. Par exemple, notre Fondation a lanc\u00e9 le <a href=\"https:\/\/seewhatgrows.org\/fr\/plantaseed-read\/\"><strong>Plante une graine, lis !<\/strong><\/a> et <a href=\"https:\/\/seewhatgrows.org\/fr\/seeds-of-inspiration\/\"><strong>Semences d\u2019inspiration<\/strong><\/a> programmes \u00e0 travers le Canada <a href=\"https:\/\/seewhatgrows.org\/fr\/plant-a-seed-see-what-grows-grows-beyond-expectations-in-2020\/\">qui a remport\u00e9 un franc succ\u00e8s<\/a>. <strong>Gr\u00e2ce \u00e0 votre soutien<\/strong>, nous pourrons continuer \u00e0 cr\u00e9er et \u00e0 mettre \u00e0 disposition des outils p\u00e9dagogiques afin de soutenir l&#x27;excellent travail des enseignants aux quatre coins du pays. <a href=\"https:\/\/seewhatgrows.org\/fr\/get-involved\/\">D\u00e9couvrez comment vous pouvez aider<\/a>.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong>OBJECTIF 4<\/strong><\/h3>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong><em>\u201cPr\u00e9server la plan\u00e8te et lib\u00e9rer le potentiel de chaque personne pour contribuer au bien-\u00eatre collectif et \u00e0 notre foyer partag\u00e9.\u201d<\/em><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le dernier point est majeur et tout le monde peut y adh\u00e9rer. Et comme pour toutes les initiatives tourn\u00e9es vers l'avenir, cela commence par nos enfants. Il est de notre devoir de leur transmettre les connaissances, les comp\u00e9tences et les outils n\u00e9cessaires pour voler de leurs propres ailes un jour. C'est cela, la durabilit\u00e9 en action ! Alors, comment pouvez-vous contribuer \u00e0 la protection de la plan\u00e8te et lib\u00e9rer le potentiel des g\u00e9n\u00e9rations futures ? Permettez-nous de rappeler les mesures que nous avons mentionn\u00e9es ci-dessus. La meilleure chose \u00e0 faire est de t\u00e9moigner votre soutien aux organisations \u00e9tablies qui aident les jeunes en se concentrant sur la mani\u00e8re dont ils peuvent agir <em>avec<\/em> leur environnement afin de contribuer \u00e0 un monde meilleur. Prenons l&#x27;exemple de la fondation \u00ab Plant a Seed &amp; See What Grows \u00bb. Notre <a href=\"https:\/\/seewhatgrows.org\/fr\/programs\/\">programmes financ\u00e9s<\/a> inclure<strong> les jardins scolaires et communautaires<\/strong>, et <strong>exp\u00e9riences d'apprentissage en plein air<\/strong>, <strong>bourses d'\u00e9tudes<\/strong>. En savoir plus <a href=\"https:\/\/seewhatgrows.org\/fr\/get-involved\/\">comment vous pouvez participer<\/a> avec la Fondation.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ensemble, nous pouvons \u0153uvrer \u00e0 la r\u00e9alisation de l&#x27;objectif des Nations unies visant \u00e0 garantir \u00e0 chacun le droit fondamental \u00e0 l&#x27;\u00e9ducation et \u00e0 b\u00e2tir un avenir plus durable, plus inclusif et plus pacifique.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><strong><em>~ Joyeuse Journ\u00e9e internationale de l'\u00e9ducation (chaque jour) ~<\/em><\/strong><\/h3>","protected":false},"excerpt":{"rendered":"<p>The United Nation&#8217;s International Day of Education is upon us (January 24 2022). The theme this year is as follows: &#8220;This year\u2019s International Day of Education will be a platform to showcase the most important transformations that have to be nurtured to realize everyone\u2019s fundamental right to education and build a more sustainable, inclusive and [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":32737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[728],"class_list":["post-32735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-international-day-of-education-2022"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to Celebrate International Day of Education 2022<\/title>\n<meta name=\"description\" content=\"Helpful guide for how parents and teachers can help recognize this year&#039;s International Day of Education with their kids.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-international-day-of-education-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Celebrate International Day of Education 2022\" \/>\n<meta property=\"og:description\" content=\"Helpful guide for how parents and teachers can help recognize this year&#039;s International Day of Education with their kids.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-international-day-of-education-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T21:19:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-18T21:20:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/01\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1012\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"How to Celebrate International Day of Education 2022\",\"datePublished\":\"2022-01-18T21:19:12+00:00\",\"dateModified\":\"2022-01-18T21:20:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/\"},\"wordCount\":776,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg\",\"keywords\":[\"International Day of Education 2022\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/\",\"name\":\"How to Celebrate International Day of Education 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg\",\"datePublished\":\"2022-01-18T21:19:12+00:00\",\"dateModified\":\"2022-01-18T21:20:12+00:00\",\"description\":\"Helpful guide for how parents and teachers can help recognize this year's International Day of Education with their kids.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg\",\"width\":1800,\"height\":1012,\"caption\":\"International Day of Education 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-international-day-of-education-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Celebrate International Day of Education 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment c\u00e9l\u00e9brer la Journ\u00e9e internationale de l'\u00e9ducation 2022","description":"Guide utile pour aider les parents et les enseignants \u00e0 c\u00e9l\u00e9brer la Journ\u00e9e internationale de l'\u00e9ducation de cette ann\u00e9e avec leurs enfants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-international-day-of-education-2022\/","og_locale":"fr_CA","og_type":"article","og_title":"How to Celebrate International Day of Education 2022","og_description":"Helpful guide for how parents and teachers can help recognize this year's International Day of Education with their kids.","og_url":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-international-day-of-education-2022\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2022-01-18T21:19:12+00:00","article_modified_time":"2022-01-18T21:20:12+00:00","og_image":[{"width":1800,"height":1012,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/01\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"How to Celebrate International Day of Education 2022","datePublished":"2022-01-18T21:19:12+00:00","dateModified":"2022-01-18T21:20:12+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/"},"wordCount":776,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/01\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg","keywords":["International Day of Education 2022"],"articleSection":["Blogs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/","url":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/","name":"Comment c\u00e9l\u00e9brer la Journ\u00e9e internationale de l'\u00e9ducation 2022","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/01\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg","datePublished":"2022-01-18T21:19:12+00:00","dateModified":"2022-01-18T21:20:12+00:00","description":"Guide utile pour aider les parents et les enseignants \u00e0 c\u00e9l\u00e9brer la Journ\u00e9e internationale de l'\u00e9ducation de cette ann\u00e9e avec leurs enfants.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/01\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2022\/01\/How-to-Celebrate-International-Day-of-Education-2022-.jpeg","width":1800,"height":1012,"caption":"International Day of Education 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-international-day-of-education-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"How to Celebrate International Day of Education 2022"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/32735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=32735"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/32735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/32737"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=32735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=32735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=32735"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}