{"id":31875,"date":"2021-03-25T10:23:31","date_gmt":"2021-03-25T17:23:31","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=31875"},"modified":"2021-03-25T10:23:36","modified_gmt":"2021-03-25T17:23:36","slug":"5-mood-boosting-foods-to-grow-to-make-your-kids-happy","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/","title":{"rendered":"5 aliments (\u00e0 cultiver) pour booster l'humeur et rendre vos enfants HEUREUX"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Journ\u00e9e internationale du bonheur<\/strong> \u00e9tait le 20 mars, mais nous avons attendu pour publier cet article car il est important de poursuivre le <em>sentiment<\/em> les 364 autres jours de l'ann\u00e9e aussi. Bien qu'il y ait beaucoup de choses qui font sourire votre enfant, comme un<a href=\"https:\/\/shop.seewhatgrows.flywheelstaging.com\"> bon livre<\/a> ou <a href=\"https:\/\/seewhatgrows.org\/fr\/family-day-activities-for-2021\/\">une journ\u00e9e en famille<\/a>, les moments peuvent \u00eatre fugaces, en particulier lors des \u00e9v\u00e9nements des derniers mois. Pour un chemin plus durable vers le bien-\u00eatre int\u00e9rieur, nous vous encourageons \u00e0 vous tourner vers la nutrition. Vous trouverez ci-dessous une liste d'aliments favorisant la bonne humeur \u00e0 cultiver dans votre jardin pour aider vos enfants \u00e0 ressentir des ondes positives.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Cinq fruits et l\u00e9gumes d\u00e9licieux pour les enfants aux propri\u00e9t\u00e9s inductrices de bonheur<\/strong><\/h2>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Myrtilles<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"402\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Blueberries.jpg\" alt=\"\" class=\"wp-image-31877\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Blueberries.jpg 900w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Blueberries-300x134.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Blueberries-768x343.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Blueberries-24x11.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Blueberries-36x16.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Blueberries-48x21.jpg 48w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ils ont un go\u00fbt d\u00e9licieux et les plus petits adorent se teindre les doigts en bleu Schtroumpf lorsqu'ils plongent leurs mains dans un bol de ces baies sucr\u00e9es. Les bleuets poss\u00e8dent une vari\u00e9t\u00e9 de <strong>antioxydants<\/strong> et regorgent d'anthocyanes et de polyph\u00e9nols. Ces compos\u00e9s jouent un r\u00f4le dans <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3355196\/\">combattre le stress oxydatif<\/a> qui fait partie int\u00e9grante de l'am\u00e9lioration de l'humeur. Les myrtilles sont en t\u00eate de notre liste de <a href=\"https:\/\/seewhatgrows.org\/fr\/grow-your-own-antioxidants-in-your-backyard-or-community-garden\/\">antioxydants que vous pouvez cultiver dans votre jardin<\/a> et prenez aussi le g\u00e2teau comme en-cas pour faire le bonheur de vos enfants !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Citrouilles<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tu te souviens quand nous avons sugg\u00e9r\u00e9 que tu <a href=\"https:\/\/seewhatgrows.org\/fr\/what-to-do-with-used-pumpkins-learning-projects-for-your-kids\/\">r\u00e9colter les graines de citrouille<\/a> Quand les festivit\u00e9s d'automne se sont-elles achev\u00e9es ? Peut-\u00eatre vous souvenez-vous de notre article sur <a href=\"https:\/\/seewhatgrows.org\/fr\/how-to-use-pumpkins-to-teach-kids-about-food-security\/\">comment les citrouilles peuvent enseigner aux enfants la s\u00e9curit\u00e9 alimentaire<\/a>? C'est exact, ce super-aliment d'un orange \u00e9clatant regorge de toutes sortes de bienfaits nutritionnels, et il s'av\u00e8re qu'il am\u00e9liore aussi l'humeur. Les citrouilles contiennent du tryptophane, un acide amin\u00e9 et neurotransmetteur qui produit l'am\u00e9liorateur d'humeur naturel du corps connu sous le nom de <strong>s\u00e9rotonine<\/strong>. Cette nourriture aide \u00e0 cr\u00e9er un <strong>\u00e9tat de bonheur d\u00e9tendu<\/strong> chez vos enfants, ce qui peut AUSSI vous offrir une agr\u00e9able pause.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Graines de tournesol\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les tournesols sont un \u00e9l\u00e9ment familier dans les arri\u00e8re-cours des maisons partout au Canada et ils devraient \u00e9galement occuper une place de choix dans votre am\u00e9nagement paysager. Tout comme les citrouilles, ils sont faciles \u00e0 cultiver sous notre climat temp\u00e9r\u00e9 et leurs graines contiennent du tryptophan ainsi que son <strong>producteur de s\u00e9rotonine<\/strong> propri\u00e9t\u00e9. De plus, leurs petites graines puissantes procurent une dose saine de <strong>magn\u00e9sium<\/strong> qui est connu pour moduler l'activit\u00e9 du syst\u00e8me de r\u00e9ponse au stress de l'organisme. En fait, <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/16846101\/\">des \u00e9tudes montrent<\/a> que le magn\u00e9sium est associ\u00e9 \u00e0 l'am\u00e9lioration des troubles neurocomportementaux chez les enfants. Et bien s\u00fbr, les tournesols ont simplement un <strong>aspect enjou\u00e9<\/strong> \u2013 ce qui peut rendre votre enfant heureux en regardant par la fen\u00eatre les jours de pluie les plus sombres.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>L\u00e9gumes verts \u00e0 feuilles sombres<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les l\u00e9gumes-feuilles sombres sont riches en <strong>Vitamine B-12,<\/strong> <strong>B9<\/strong> (\u00e9galement connu sous le nom de folate) et <strong>autres vitamines B<\/strong>. Les vitamines B obtiennent un \u201c A+ \u201d lorsqu'il s'agit de produire des substances chimiques naturelles dans le cerveau qui affectent positivement l'humeur et d'autres fonctions c\u00e9r\u00e9brales. Les l\u00e9gumes-feuilles courants que vous pouvez cultiver dans votre jardin comprennent le chou fris\u00e9 et les \u00e9pinards. Vous avez peur de donner envie \u00e0 vos enfants de manger ces l\u00e9gumes qui remontent le moral ? Vous pouvez en acheter un abordable<strong> friteuse sans huile<\/strong>, saupoudrez quelques-unes des herbes et des \u00e9pices pr\u00e9f\u00e9r\u00e9es de vos enfants, et faites <strong>chips de chou fris\u00e9 ou d'\u00e9pinards croustillantes<\/strong> en quelques minutes !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Avocats<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Comparables \u00e0 leurs cousins de couleur similaire, les l\u00e9gumes verts \u00e0 feuilles sombres, les avocats sont riches en folate, qui am\u00e9liore l'humeur. Mais cette merveille verte en forme d'\u0153uf est \u00e9galement riche en <strong>acide gras essentiel (AGE) om\u00e9ga-3<\/strong> ce qui est excellent pour l'humeur et la sant\u00e9 du cerveau. De plus, les nutriments pr\u00e9sents dans les avocats sont efficaces pour <strong>r\u00e9gulation des parois de l'estomac irritable<\/strong>. Nous savons tous \u00e0 quel point un mal de ventre peut rendre un enfant malheureux, alors utilisez ce fruit <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC4882728\/\" target=\"_blank\" rel=\"noreferrer noopener\">pour potentiellement aider<\/a> \u00e9vitez que cela ne se produise. De plus, tout ce dont vous avez besoin, c'est d'un avocat de votre \u00e9picerie locale pour obtenir le noyau n\u00e9cessaire <a href=\"https:\/\/seewhatgrows.org\/fr\/easiest-vegetables-grow-seed-indoors\/\">en cultiver un autre \u00e0 l'int\u00e9rieur<\/a>. C'est un <strong>friandise qui remonte le moral et activit\u00e9 de jardinage tout en un<\/strong> que vos enfants puissent en profiter.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Restez \u00e0 l'\u00e9coute pour en savoir plus sur <strong>Fondation Planter une Graine et Voir Ce Qui Pousse<\/strong> alors que nous offrons des moyens de soutenir des enfants plus heureux (et en meilleure sant\u00e9 !) partout au Canada. Apprenez-en davantage sur la fa\u00e7on dont vous aussi <a href=\"https:\/\/seewhatgrows.org\/fr\/get-involved\/\">peut s'impliquer<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>International Day of Happiness was on March 20 but we waited to release this article because it\u2019s important to chase the feeling on the other 364 days of the year too. While there are a lot of things that make your child smile, such as a good book or a day out with family, the [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":31879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[694],"class_list":["post-31875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-mood-boosting-foods"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 Mood Boosting Foods to Grow to Make Your Kids Happy<\/title>\n<meta name=\"description\" content=\"Five delicious fruits and vegetables for kids that have happiness-inducing properties, courtesy of Plant a Seed and See What Grows.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Mood Boosting Foods to Grow to Make Your Kids Happy\" \/>\n<meta property=\"og:description\" content=\"Five delicious fruits and vegetables for kids that have happiness-inducing properties, courtesy of Plant a Seed and See What Grows.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-25T17:23:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-25T17:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2550\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"5 Mood Boosting Foods (to Grow) to Make Your Kids HAPPY\",\"datePublished\":\"2021-03-25T17:23:31+00:00\",\"dateModified\":\"2021-03-25T17:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/\"},\"wordCount\":636,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg\",\"keywords\":[\"Mood Boosting Foods\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/\",\"name\":\"5 Mood Boosting Foods to Grow to Make Your Kids Happy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg\",\"datePublished\":\"2021-03-25T17:23:31+00:00\",\"dateModified\":\"2021-03-25T17:23:36+00:00\",\"description\":\"Five delicious fruits and vegetables for kids that have happiness-inducing properties, courtesy of Plant a Seed and See What Grows.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg\",\"width\":2550,\"height\":1700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Mood Boosting Foods (to Grow) to Make Your Kids HAPPY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 aliments qui am\u00e9liorent l'humeur \u00e0 cultiver pour rendre vos enfants heureux","description":"Cinq d\u00e9licieux fruits et l\u00e9gumes pour les enfants qui procurent le bonheur, gracieuset\u00e9 de Plant a Seed and See What Grows.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/","og_locale":"fr_CA","og_type":"article","og_title":"5 Mood Boosting Foods to Grow to Make Your Kids Happy","og_description":"Five delicious fruits and vegetables for kids that have happiness-inducing properties, courtesy of Plant a Seed and See What Grows.","og_url":"https:\/\/seewhatgrows.org\/fr\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2021-03-25T17:23:31+00:00","article_modified_time":"2021-03-25T17:23:36+00:00","og_image":[{"width":2550,"height":1700,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"5 Mood Boosting Foods (to Grow) to Make Your Kids HAPPY","datePublished":"2021-03-25T17:23:31+00:00","dateModified":"2021-03-25T17:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/"},"wordCount":636,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg","keywords":["Mood Boosting Foods"],"articleSection":["Blogs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/","url":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/","name":"5 aliments qui am\u00e9liorent l'humeur \u00e0 cultiver pour rendre vos enfants heureux","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg","datePublished":"2021-03-25T17:23:31+00:00","dateModified":"2021-03-25T17:23:36+00:00","description":"Cinq d\u00e9licieux fruits et l\u00e9gumes pour les enfants qui procurent le bonheur, gracieuset\u00e9 de Plant a Seed and See What Grows.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2021\/03\/Mood-Boosting-Foods-Sunflower-Seeds-1.jpg","width":2550,"height":1700},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/5-mood-boosting-foods-to-grow-to-make-your-kids-happy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"5 Mood Boosting Foods (to Grow) to Make Your Kids HAPPY"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/31875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=31875"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/31875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/31879"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=31875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=31875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=31875"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}