{"id":31528,"date":"2020-10-28T18:34:08","date_gmt":"2020-10-29T01:34:08","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=31528"},"modified":"2020-11-19T07:37:05","modified_gmt":"2020-11-19T15:37:05","slug":"how-to-celebrate-national-child-day-with-your-children","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-national-child-day-with-your-children\/","title":{"rendered":"Comment f\u00eater la Journ\u00e9e nationale de l&#x27;enfance avec vos enfants"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La Journ\u00e9e nationale de l'enfant est c\u00e9l\u00e9br\u00e9e au Canada le 20 novembre de chaque ann\u00e9e. Elle rend hommage \u00e0 <strong>D\u00e9claration des droits de l'enfant des Nations Unies<\/strong> qui fournit une feuille de route sur ce qui est n\u00e9cessaire pour \u00e9lever des enfants et des jeunes heureux et en bonne sant\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre Fondation vit selon cette mission 365 jours par an. Cependant, nous encourageons les parents \u00e0 consid\u00e9rer cette journ\u00e9e comme une opportunit\u00e9 d'enseigner \u00e0 leurs enfants comment <em>ils<\/em> m\u00e8nera la charge pour un changement positif dans le monde. C'est un concept que nous devrions tous c\u00e9l\u00e9brer ! Voici comment.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment votre famille peut c\u00e9l\u00e9brer la Journ\u00e9e nationale de l'enfant tout en enseignant \u00e0 vos enfants leur valeur pour la communaut\u00e9<\/strong><\/h2>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Passez au BLEU pour sensibiliser&nbsp;<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le bleu est la couleur officielle de la Journ\u00e9e nationale de l'enfant, ce qui offre \u00e0 votre famille l'occasion id\u00e9ale de sensibiliser la communaut\u00e9 \u00e0 cette cause. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il ne faut pas grand-chose pour allumer l'\u00e9tincelle \u2013 en fait, vous pouvez commencer par ce qui se trouve dans votre placard. Habillez-vous de la t\u00eate aux pieds dans vos bleus pr\u00e9f\u00e9r\u00e9s ce 20 novembre, et sortez en famille vers un march\u00e9 fermier local, un march\u00e9 d'artisans saisonnier ou un autre endroit o\u00f9 les gens le remarqueront. Lorsqu'ils poseront des questions, faites-leur savoir qu'il s'agit de la Journ\u00e9e nationale de l'enfant et donnez-leur un bref aper\u00e7u de <a href=\"https:\/\/www.nationalchildday.ca\">\u00e0 quoi sert cette journ\u00e9e sp\u00e9ciale<\/a>. Ils peuvent marquer leurs calendriers d\u00e8s maintenant et, tr\u00e8s bient\u00f4t, le 20 novembre sera une journ\u00e9e d\u00e9licieusement bleue dans tout le pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous n\u2019avez pas de tenue bleue pour tout le monde dans la famille ? Parfait ! Cela permet \u00e0 vos enfants de faire preuve de cr\u00e9ativit\u00e9, rendant l'\u00e9v\u00e9nement encore plus amusant. Ils peuvent utiliser de la peinture sur tissu bleue respectueuse de l'environnement pour teindre de vieux t-shirts et sweats \u00e0 capuche blancs (ou gris clair). Mieux encore, les enfants peuvent se tourner vers votre jardin ou un magasin d'alimentation biologique pour teindre leurs v\u00eatements comme le faisaient leurs anc\u00eatres. C'est exact, <strong>Les l\u00e9gumes peuvent \u00eatre utilis\u00e9s pour teindre les v\u00eatements<\/strong>, avec <a href=\"https:\/\/www.architecturaldigest.com\/story\/how-to-naturally-dye-using-foods\">les haricots noirs donnent au tissu une teinte bleue crayeuse<\/a>. C'est trop cool !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, vos enfants peuvent fabriquer des affiches en utilisant du papier de construction bleu, des autocollants et tout ce que leur c\u0153ur d\u00e9sire. <strong>Collez les affiches<\/strong> sur les fen\u00eatres de votre maison donnant sur la rue, et agrafez-les sur les poteaux t\u00e9l\u00e9phoniques de votre quartier pour faire passer le message.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assurez-vous d'utiliser les r\u00e9seaux sociaux tout au long de la journ\u00e9e pour partager les histoires de vos activit\u00e9s familiales, de vos arts et de vos cr\u00e9ations en utilisant les hashtags d\u00e9sign\u00e9s de <strong>#NationalChildDay<\/strong> et <strong>#NCD2020<\/strong> (ou quelle que soit l'ann\u00e9e o\u00f9 vous vous trouvez).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque bonne action commence par la prise de conscience qu'une bonne action doit \u00eatre accomplie. En passant au BLEU ce 20 novembre, votre foyer peut jouer un r\u00f4le cl\u00e9 dans la sensibilisation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Aidez les enfants dans le besoin<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle meilleure fa\u00e7on pour votre foyer de c\u00e9l\u00e9brer la Journ\u00e9e nationale de l'enfant que d'identifier les enfants dans le besoin et de leur apporter du soutien ? Bien s\u00fbr, en tant que foyer, vous n'avez ni le temps ni les ressources pour les chercher, c'est pourquoi vous avez besoin de l'aide d'une fondation comme la n\u00f4tre.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fondation Plant a Seed &amp; See What Grows finance un certain nombre de programmes qui soutiennent les causes des enfants \u00e0 travers le pays. Ceux-ci incluent <a href=\"https:\/\/seewhatgrows.org\/fr\/our-causes\/outdoor-learning-experiences\/\">exp\u00e9riences d'apprentissage en plein air<\/a>, le <a href=\"https:\/\/seewhatgrows.org\/fr\/plantaseed-read\/\">Plantez une graine \u2013 Lisez !<\/a> programme, <a href=\"https:\/\/seewhatgrows.org\/fr\/our-causes\/community-gardens-seed-preservation\/\">projets de jardins scolaires<\/a>, et plus encore. En savoir plus sur nos <a href=\"https:\/\/seewhatgrows.org\/fr\/programs\/\">programmes financ\u00e9s<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais comment faire participer les enfants lorsqu'il s'agit de faire un don ? Organisez un <strong>collecte de fonds de quartier ax\u00e9e sur la famille<\/strong>. Nous avons d\u00e9j\u00e0 fourni quelques id\u00e9es sur la fa\u00e7on dont vous et vos enfants pouvez <strong>lancer une collecte de charit\u00e9 communautaire et\/ou un d\u00e9fi de promesses de dons<\/strong>, que nous avons d\u00e9taill\u00e9 dans cet article sur <a href=\"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-international-day-of-charity\/\">comment c\u00e9l\u00e9brer la Journ\u00e9e internationale de la bienfaisance<\/a> \u2013 un autre jour de l'ann\u00e9e que vous voudrez marquer sur vos calendriers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rassemblez-vous en famille ce 20 novembre et discutez <a href=\"https:\/\/seewhatgrows.org\/fr\/get-involved\/\">comment vous pouvez tous participer<\/a> en ce jour (et aux alentours de ce jour) si important de l'ann\u00e9e.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><em>Joyeuse Journ\u00e9e nationale de l'enfant au Canada !<\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>National Child Day is celebrated in Canada on November 20th of each year. It honors the UN Declaration of the Rights of the Child which provides a road map of what is needed to raise healthy and happy children and youth.&nbsp; Our Foundation lives by this mission 365 days of the year. However, we encourage [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":31530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[688],"class_list":["post-31528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-how-to-celebrate-national-child-day"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to Celebrate National Child Day, With Your Children<\/title>\n<meta name=\"description\" content=\"How your family can celebrate National Child Day while teaching your kids about their value to the community.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-national-child-day-with-your-children\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Celebrate National Child Day, With Your Children\" \/>\n<meta property=\"og:description\" content=\"How your family can celebrate National Child Day while teaching your kids about their value to the community.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-national-child-day-with-your-children\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-29T01:34:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-19T15:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/10\/How-to-Celebrate-National-Child-Day.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"How to Celebrate National Child Day, With Your Children\",\"datePublished\":\"2020-10-29T01:34:08+00:00\",\"dateModified\":\"2020-11-19T15:37:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/How-to-Celebrate-National-Child-Day.jpg\",\"keywords\":[\"How to Celebrate National Child Day\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/\",\"name\":\"How to Celebrate National Child Day, With Your Children\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/How-to-Celebrate-National-Child-Day.jpg\",\"datePublished\":\"2020-10-29T01:34:08+00:00\",\"dateModified\":\"2020-11-19T15:37:05+00:00\",\"description\":\"How your family can celebrate National Child Day while teaching your kids about their value to the community.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/How-to-Celebrate-National-Child-Day.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/How-to-Celebrate-National-Child-Day.jpg\",\"width\":2200,\"height\":1182,\"caption\":\"How to Celebrate National Child Day\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-national-child-day-with-your-children\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Celebrate National Child Day, With Your Children\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment f\u00eater la Journ\u00e9e nationale de l&#x27;enfance avec vos enfants","description":"Comment votre famille peut c\u00e9l\u00e9brer la Journ\u00e9e nationale de l'enfant tout en enseignant \u00e0 vos enfants leur valeur au sein de la communaut\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-national-child-day-with-your-children\/","og_locale":"fr_CA","og_type":"article","og_title":"How to Celebrate National Child Day, With Your Children","og_description":"How your family can celebrate National Child Day while teaching your kids about their value to the community.","og_url":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-national-child-day-with-your-children\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2020-10-29T01:34:08+00:00","article_modified_time":"2020-11-19T15:37:05+00:00","og_image":[{"width":2200,"height":1182,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/10\/How-to-Celebrate-National-Child-Day.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"How to Celebrate National Child Day, With Your Children","datePublished":"2020-10-29T01:34:08+00:00","dateModified":"2020-11-19T15:37:05+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/"},"wordCount":661,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/10\/How-to-Celebrate-National-Child-Day.jpg","keywords":["How to Celebrate National Child Day"],"articleSection":["Uncategorized"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/","url":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/","name":"Comment f\u00eater la Journ\u00e9e nationale de l&#x27;enfance avec vos enfants","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/10\/How-to-Celebrate-National-Child-Day.jpg","datePublished":"2020-10-29T01:34:08+00:00","dateModified":"2020-11-19T15:37:05+00:00","description":"Comment votre famille peut c\u00e9l\u00e9brer la Journ\u00e9e nationale de l'enfant tout en enseignant \u00e0 vos enfants leur valeur au sein de la communaut\u00e9.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/10\/How-to-Celebrate-National-Child-Day.jpg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/10\/How-to-Celebrate-National-Child-Day.jpg","width":2200,"height":1182,"caption":"How to Celebrate National Child Day"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-national-child-day-with-your-children\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"How to Celebrate National Child Day, With Your Children"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/31528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=31528"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/31528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/31530"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=31528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=31528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=31528"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}