{"id":31345,"date":"2020-07-03T13:48:46","date_gmt":"2020-07-03T20:48:46","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=31345"},"modified":"2020-07-03T13:48:50","modified_gmt":"2020-07-03T20:48:50","slug":"seeds-of-inspiration-continue-to-grow-in-schools-across-canada","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/","title":{"rendered":"Les graines de l'inspiration continuent de grandir dans les \u00e9coles \u00e0 travers le Canada"},"content":{"rendered":"<p class=\"wp-block-paragraph\">L'ann\u00e9e derni\u00e8re, nous avons fourni <a href=\"https:\/\/seewhatgrows.org\/fr\/seeds-inspiration-plant-seed-read-2019-success-story\/\">un avis<\/a> de notre <strong>Semences d\u2019inspiration<\/strong> <strong>(SOI)<\/strong> programme alors que nous avons atteint plus d'un millier d'\u00e9coles \u00e0 travers le pays. Vous pouvez en lire plus sur l'historique de SOI <a href=\"https:\/\/seewhatgrows.org\/fr\/seeds-inspiration-plant-seed-read-2019-success-story\/\">ici<\/a>, mais permettez-nous de partager un extrait de la d\u00e9claration de mission du programme :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cUne graine, comme toute bonne id\u00e9e, a besoin des conditions ad\u00e9quates pour grandir. Elle est plant\u00e9e avec amour et attention. Le sol partage ses riches nutriments et c\u00e8de aux racines tendres et croissantes de la graine. Encourag\u00e9e par l'eau et nourrie par la chaleur du soleil, elle fleurit d\u00e9licatement d'abord, puis s'\u00e9panouit avec force. Ancr\u00e9e \u00e0 la terre, elle \u00e9merge pleine de vie et de possibilit\u00e9s.<\/em><\/p><p><em>Des choses merveilleuses peuvent na\u00eetre d'une minuscule graine.&nbsp;<\/em><\/p><p><em>Nous pensons qu'il en va de m\u00eame pour les enfants. Nous voulons que les enfants s'ancrent solidement dans un monde de possibilit\u00e9s, d'\u00e9merveillement et de fascination, o\u00f9 leurs id\u00e9es et leurs r\u00eaves peuvent \u00eatre cultiv\u00e9s, et o\u00f9 ils peuvent apprendre \u00e0 respecter et \u00e0 prendre soin de la terre pendant que leurs esprits sont encore ouverts et r\u00e9ceptifs.<\/em><\/p><p><em>La Fondation Plant a Seed est l\u00e0 pour les soutenir dans leur croissance. Notre objectif est de faire briller nos enfants. Pour atteindre leur plein potentiel, les enfants ont besoin d'\u00eatre encourag\u00e9s et inspir\u00e9s ; nous sommes l\u00e0 pour les aider \u00e0 devenir une g\u00e9n\u00e9ration plus saine gr\u00e2ce \u00e0 des exp\u00e9riences qui les connectent \u00e0 la terre et \u00e0 des opportunit\u00e9s qui am\u00e9liorent leur communaut\u00e9.\u201c<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Alors que nous en sommes \u00e0 la troisi\u00e8me ann\u00e9e du programme SOI, il est temps de faire le point. L'ann\u00e9e 2020 a certes pr\u00e9sent\u00e9 son lot de d\u00e9fis pour les programmes scolaires, mais les enseignants et les \u00e9l\u00e8ves ont fait preuve de r\u00e9silience et ont trouv\u00e9 des moyens cr\u00e9atifs de d\u00e9velopper le programme au-del\u00e0 de nos attentes les plus folles. Au moment d'aller sous presse, <strong>SOI a atteint 93 818 \u00e9tudiants<\/strong> au Canada ! Mais au lieu d'offrir des donn\u00e9es suppl\u00e9mentaires (il y en a beaucoup !), nous avons pens\u00e9 qu'il valait mieux laisser la parole aux enseignants. \u00c0 la fin de cet article, nous fournissons \u00e9galement des liens pour obtenir plus d'informations sur nos programmes et sur la mani\u00e8re dont vous pouvez vous aussi vous impliquer. Faisons le point !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ce que les \u00e9ducateurs ont \u00e0 dire sur le programme \u201c Seeds of Inspiration \u201d<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"521\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--1024x521.jpg\" alt=\"\" class=\"wp-image-31347\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--1024x521.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--300x153.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--768x391.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--1536x782.jpg 1536w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--1080x550.jpg 1080w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--24x12.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--36x18.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration--48x24.jpg 48w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-.jpg 2016w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Division scolaire Pembina Trails, Manitoba<\/figcaption><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Melissa Dundas, enseignante de maternelle, Mission, Colombie-Britannique<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Cette histoire de l'\u00e9ducatrice de jardin d'enfants Melissa Dundas est si belle que nous devions la partager dans son int\u00e9gralit\u00e9. Elle montre qu'avec du d\u00e9vouement et une pinc\u00e9e de cr\u00e9ativit\u00e9, rien ne peut emp\u00eacher d'inspirer notre jeunesse :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cJ'ai re\u00e7u mon colis \u00e0 l'automne 2019 et j'avais pr\u00e9vu de commencer ce programme apr\u00e8s les vacances de printemps en 2020. Malheureusement, la pand\u00e9mie de COVID a frapp\u00e9 et il a \u00e9t\u00e9 demand\u00e9 aux \u00e9l\u00e8ves de rester chez eux. J'ai pu envoyer des dossiers de travail \u00e0 tous mes \u00e9l\u00e8ves et faire des appels en visioconf\u00e9rence avec eux depuis chez moi. J'ai envoy\u00e9 de nombreuses choses chez eux, notamment deux graines sans \u00e9tiquette dans une enveloppe et leur cahier d'exercices \u2018 Plante une graine et vois ce qui pousse \u2019.<\/em><\/p><p><em>Mes \u00e9l\u00e8ves recevaient des instructions toutes les semaines ou presque, leur demandant d'examiner leurs \u2018 graines myst\u00e8res \u00bb, de les planter, de s'en occuper au fur et \u00e0 mesure de leur croissance et de remplir les pages de leur cahier d'exercices. J'ai \u00e9galement pu lire les deux histoires fournies avec le kit Seeds of Inspiration par visioconf\u00e9rence.<\/em><\/p><p><em>Les \u00e9l\u00e8ves font pousser leurs graines depuis environ un mois maintenant, et aujourd'hui je leur ai enfin dit ce qu'ils font pousser ! Certains d'entre eux avaient devin\u00e9 ce que c'\u00e9taient, mais beaucoup ont \u00e9t\u00e9 surpris. &nbsp;<\/em><\/p><p><em>J'ai vraiment beaucoup aim\u00e9 ce programme et je r\u00e9utiliserai certainement les documents l'ann\u00e9e prochaine avec mes \u00e9l\u00e8ves. Les livres \u00e9taient magnifiquement illustr\u00e9s et la langue utilis\u00e9e \u00e9tait parfaite pour mes \u00e9l\u00e8ves de maternelle.<\/em><\/p><p><em>\u201d Merci beaucoup pour cette opportunit\u00e9 et pour le mat\u00e9riel fourni, qui a permis de susciter l\u2019enthousiasme de mes \u00e9l\u00e8ves \u00e0 l\u2019id\u00e9e de cultiver leurs propres aliments. Ils ont ador\u00e9 avoir leur propre plante \u00e0 entretenir et j\u2019encouragerai sans aucun doute les \u00e9l\u00e8ves de l\u2019ann\u00e9e prochaine \u00e0 s\u2019occuper eux aussi de leur propre plante. \u00bb<\/em><\/p><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Julie Davidsen, administratrice, directrice principale de l'\u00e9l\u00e9mentaire inf\u00e9rieur et conseill\u00e8re en programmes d'\u00e9tudes, Brilliant Star Montessori School, Saskatoon, SK<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"152\" height=\"87\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/07\/Julie-Davidsen.jpg\" alt=\"\" class=\"wp-image-31369\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/07\/Julie-Davidsen.jpg 152w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/07\/Julie-Davidsen-150x87.jpg 150w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/07\/Julie-Davidsen-24x14.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/07\/Julie-Davidsen-36x21.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/07\/Julie-Davidsen-48x27.jpg 48w\" sizes=\"auto, (max-width: 152px) 100vw, 152px\" \/><figcaption>Julie Davidsen<\/figcaption><\/figure><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cNous avons re\u00e7u notre colis aujourd'hui et nous sommes absolument ravis des livres et des graines. Quels beaux mat\u00e9riaux qui seront appr\u00e9ci\u00e9s immens\u00e9ment. Merci ! Nous sommes tr\u00e8s excit\u00e9s de faire pousser nos graines et de lire les livres avec nos classes. Notre \u00e9cole a d\u00e9j\u00e0 des potagers que nous plantons et r\u00e9coltons chaque ann\u00e9e avec nos \u00e9l\u00e8ves et cette initiative s'int\u00e8gre si bien dans notre programmation. Nous vous remercions sinc\u00e8rement pour cette merveilleuse opportunit\u00e9 !\u201d<\/em><\/p><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Jason Chow, professeur de physique et de sciences, au lyc\u00e9e de Richmond<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Il a \u00e9t\u00e9 r\u00e9confortant d'entendre comment le programme SOI de notre Fondation a \u00e9t\u00e9 appliqu\u00e9 pour enseigner des comp\u00e9tences de vie \u00e0 des \u00e9l\u00e8ves \u00e0 faible taux de handicap de l'\u00e9cole secondaire Richmond, en Colombie-Britannique. Pour les non-initi\u00e9s, les \u00e9l\u00e8ves \u00e0 faible taux de handicap sont ceux qui pr\u00e9sentent des handicaps \u00e0 faible incidence tels qu'une d\u00e9ficience visuelle ou auditive, la surdic\u00e9cit\u00e9 et une d\u00e9ficience cognitive importante.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cMerci pour les graines, le cahier d'exercices et les livres ! Nos \u00e9l\u00e8ves en comp\u00e9tences de vie \u00e0 faible incidence ont pass\u00e9 un excellent moment \u00e0 planter les haricots nains et les radis ! Nos \u00e9l\u00e8ves \u00e0 faible incidence sont des \u00e9l\u00e8ves du secondaire ayant des besoins d'apprentissage et de d\u00e9veloppement importants. Sur le plan acad\u00e9mique, beaucoup d'entre eux fonctionnent au niveau de la 2e-3e ann\u00e9e ou en dessous. Beaucoup d'entre eux b\u00e9n\u00e9ficient d'une aide p\u00e9dagogique individuelle de la part d'un adulte tout au long de la journ\u00e9e. Ma classe de sciences de 11e ann\u00e9e travaille souvent en collaboration avec leur classe de comp\u00e9tences de vie dans notre jardin scolaire. Nous essayons de favoriser les connexions, l'empathie et l'amiti\u00e9 entre ces \u00e9l\u00e8ves aux capacit\u00e9s tr\u00e8s diff\u00e9rentes.\u201d<\/em><\/p><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Michelle Carlos, consultante en alphab\u00e9tisation pour la petite enfance et les ann\u00e9es interm\u00e9diaires \/ enseignante-biblioth\u00e9caire, Whyte Ridge School, Winnipeg, MB<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"785\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/09\/Michelle-Carlos.jpg\" alt=\"Seeds of Inspiration\" class=\"wp-image-30721\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/09\/Michelle-Carlos.jpg 900w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/09\/Michelle-Carlos-300x262.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/09\/Michelle-Carlos-768x670.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/09\/Michelle-Carlos-24x21.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/09\/Michelle-Carlos-36x31.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/09\/Michelle-Carlos-48x42.jpg 48w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201c Les ressources p\u00e9dagogiques propos\u00e9es par Seeds of Inspiration \u00e9taient d\u2019excellente qualit\u00e9 et comportaient des illustrations captivantes pour nos \u00e9l\u00e8ves de la petite enfance. L\u2019accent mis sur l\u2019environnement correspondait parfaitement aux besoins de notre programme scolaire, et nos \u00e9l\u00e8ves ont ador\u00e9 les activit\u00e9s pratiques consistant \u00e0 planter et \u00e0 identifier diff\u00e9rentes graines. Chaque enseignant de maternelle de notre acad\u00e9mie a re\u00e7u les livres en anglais ou en fran\u00e7ais afin de les ajouter \u00e0 la biblioth\u00e8que de sa classe. Nos enseignants du programme d\u2019immersion en fran\u00e7ais \u00e9taient ravis de disposer de ce magnifique livre illustr\u00e9 et de ce livret d\u2019activit\u00e9s d\u00e9j\u00e0 traduits pour eux. \u201d<\/em><\/p><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Voici des photos d'\u00e9l\u00e8ves de partout au Canada qui profitent des ressources \u00e9ducatives Graines d'inspiration<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u00c9cole comm\u00e9morative Clark Rutherford, N.-\u00c9.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-1-1.jpg\" alt=\"\" class=\"wp-image-31349\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-1-1.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-1-1-300x150.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-1-1-768x384.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-1-1-24x12.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-1-1-36x18.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-1-1-48x24.jpg 48w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u00c9cole \u00e9l\u00e9mentaire Taylor, MB<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"511\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-2-1.jpg\" alt=\"\" class=\"wp-image-31351\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-2-1.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-2-1-300x150.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-2-1-768x383.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-2-1-24x12.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-2-1-36x18.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-2-1-48x24.jpg 48w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">LaSalle Elementary Junior, QC<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"566\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3-1024x566.jpg\" alt=\"\" class=\"wp-image-31352\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3-1024x566.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3-300x166.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3-768x425.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3-1080x597.jpg 1080w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3-24x13.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3-36x20.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3-48x27.jpg 48w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-3.jpg 1210w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u00c9cole Victory, MB<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-4.jpg\" alt=\"\" class=\"wp-image-31354\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-4.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-4-300x150.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-4-768x384.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-4-24x12.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-4-36x18.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-4-48x24.jpg 48w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u00c9cole primaire Westpark, QC<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"508\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/SOI-1.jpg\" alt=\"\" class=\"wp-image-31356\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/SOI-1.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/SOI-1-300x149.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/SOI-1-768x381.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/SOI-1-24x12.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/SOI-1-36x18.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/SOI-1-48x24.jpg 48w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspriation-5-2.jpg\" alt=\"\" class=\"wp-image-31358\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspriation-5-2.jpg 1024w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspriation-5-2-300x149.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspriation-5-2-768x382.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspriation-5-2-24x12.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspriation-5-2-36x18.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspriation-5-2-48x24.jpg 48w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous cherchez des ressources pour sensibiliser et \u00e9duquer vos jeunes \u00e9l\u00e8ves au cycle de la graine \u00e0 l'assiette et pour en faire des gardiens de l'environnement, nous avons le plaisir de vous offrir nos ressources \u00e9ducatives gratuites. Notre programme \u00ab Graines d'inspiration \u00bb vise \u00e0 rejoindre les jeunes par le biais d'histoires et de plantations dans les \u00e9coles. Depuis 2017, plus de 93 000 \u00e9l\u00e8ves r\u00e9partis dans plus de 1 000 \u00e9coles canadiennes y ont particip\u00e9. Ne laissez pas vos \u00e9l\u00e8ves passer \u00e0 c\u00f4t\u00e9 de ces ressources magnifiques et gratuites ! <a href=\"https:\/\/seewhatgrows.org\/fr\/seeds-of-inspiration\/\">En savoir plus sur le programme SOI<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Last year we provided a review of our Seeds of Inspiration (SOI) program as we reached over a thousand schools throughout the country. You can read more on the background of SOI here, but allow us to share a snippet from the program\u2019s mission statement: \u201cA seed, like any good idea, needs the right conditions [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":31359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[612,512,683],"class_list":["post-31345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-school-gardening","tag-school-gardens","tag-seeds-of-inspiration"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seeds of Inspiration Continue to Grow in Schools Across Canada<\/title>\n<meta name=\"description\" content=\"What educators have to say about the Plant a Seed and See What Grows Foundation&#039;s Seeds of Inspiration and Plant a Seed, Read! program.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seeds of Inspiration Continue to Grow in Schools Across Canada\" \/>\n<meta property=\"og:description\" content=\"What educators have to say about the Plant a Seed and See What Grows Foundation&#039;s Seeds of Inspiration and Plant a Seed, Read! program.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-03T20:48:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-03T20:48:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-Cover.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2550\" \/>\n\t<meta property=\"og:image:height\" content=\"1289\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"Seeds of Inspiration Continue to Grow in Schools Across Canada\",\"datePublished\":\"2020-07-03T20:48:46+00:00\",\"dateModified\":\"2020-07-03T20:48:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/\"},\"wordCount\":1114,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Seeds-of-Inspiration-Cover.jpeg\",\"keywords\":[\"School Gardening\",\"School Gardens\",\"Seeds of Inspiration\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/\",\"name\":\"Seeds of Inspiration Continue to Grow in Schools Across Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Seeds-of-Inspiration-Cover.jpeg\",\"datePublished\":\"2020-07-03T20:48:46+00:00\",\"dateModified\":\"2020-07-03T20:48:50+00:00\",\"description\":\"What educators have to say about the Plant a Seed and See What Grows Foundation's Seeds of Inspiration and Plant a Seed, Read! program.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Seeds-of-Inspiration-Cover.jpeg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Seeds-of-Inspiration-Cover.jpeg\",\"width\":2550,\"height\":1289,\"caption\":\"Seeds of Inspiration\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seeds of Inspiration Continue to Grow in Schools Across Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les graines de l'inspiration continuent de grandir dans les \u00e9coles \u00e0 travers le Canada","description":"Ce que les \u00e9ducateurs ont \u00e0 dire sur les programmes Seeds of Inspiration et Plant a Seed, Read! de la Fondation Plant a Seed and See What Grows.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/","og_locale":"fr_CA","og_type":"article","og_title":"Seeds of Inspiration Continue to Grow in Schools Across Canada","og_description":"What educators have to say about the Plant a Seed and See What Grows Foundation's Seeds of Inspiration and Plant a Seed, Read! program.","og_url":"https:\/\/seewhatgrows.org\/fr\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2020-07-03T20:48:46+00:00","article_modified_time":"2020-07-03T20:48:50+00:00","og_image":[{"width":2550,"height":1289,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-Cover.jpeg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"Seeds of Inspiration Continue to Grow in Schools Across Canada","datePublished":"2020-07-03T20:48:46+00:00","dateModified":"2020-07-03T20:48:50+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/"},"wordCount":1114,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-Cover.jpeg","keywords":["School Gardening","School Gardens","Seeds of Inspiration"],"articleSection":["Uncategorized"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/","url":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/","name":"Les graines de l'inspiration continuent de grandir dans les \u00e9coles \u00e0 travers le Canada","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-Cover.jpeg","datePublished":"2020-07-03T20:48:46+00:00","dateModified":"2020-07-03T20:48:50+00:00","description":"Ce que les \u00e9ducateurs ont \u00e0 dire sur les programmes Seeds of Inspiration et Plant a Seed, Read! de la Fondation Plant a Seed and See What Grows.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-Cover.jpeg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2020\/06\/Seeds-of-Inspiration-Cover.jpeg","width":2550,"height":1289,"caption":"Seeds of Inspiration"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/seeds-of-inspiration-continue-to-grow-in-schools-across-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"Seeds of Inspiration Continue to Grow in Schools Across Canada"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/31345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=31345"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/31345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/31359"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=31345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=31345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=31345"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}