{"id":30476,"date":"2019-06-06T15:46:00","date_gmt":"2019-06-06T22:46:00","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=30476"},"modified":"2019-06-12T13:27:47","modified_gmt":"2019-06-12T20:27:47","slug":"kids-can-help-keep-plastic-ocean","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/kids-can-help-keep-plastic-ocean\/","title":{"rendered":"Comment les enfants peuvent aider \u00e0 garder le plastique hors de l'oc\u00e9an"},"content":{"rendered":"<p>Que vous trouviez cet article \u00e0 temps pour la Journ\u00e9e mondiale de l'oc\u00e9an 2019, ou des jours, des semaines ou des mois apr\u00e8s les faits, importe peu, puisque le th\u00e8me de cette ann\u00e9e s'appliquera tout autant.&nbsp;<strong>Conservation <\/strong><a href=\"https:\/\/www.worldoceansday.org\/below-the-surface\/2019-theme-conservation-focus\" target=\"_blank\" rel=\"noopener\">est la mise au point<\/a>, avec pour mandat de \u201c faire preuve de leadership dans la pr\u00e9vention de la pollution plastique et de partager des solutions qui inspirent et mobilisent la communaut\u00e9 mondiale \u201d. Plus important encore, c'est l'appel lanc\u00e9 aux jeunes pour qu'ils s'impliquent davantage, car&nbsp;<a href=\"http:\/\/www.worldoceansday.org\/youth-advisory-council\" target=\"_blank\" rel=\"noopener\">Conseil consultatif des jeunes pour la Journ\u00e9e mondiale des oc\u00e9ans<\/a>&nbsp;\u0153uvre \u00e0 la fois dans les coulisses et sur le terrain pour contribuer \u00e0 stopper la crise croissante de la pollution plastique dans les oc\u00e9ans. Bien s\u00fbr, plus t\u00f4t nous touchons les jeunes, mieux c'est, car les graines du changement sont plant\u00e9es d\u00e8s le plus jeune \u00e2ge. Aujourd'hui, nous proposons aux parents des conseils pratiques pour sensibiliser les jeunes enfants \u00e0 l'\u00e9pid\u00e9mie de plastique dans les oc\u00e9an afin que les g\u00e9n\u00e9rations futures n'aient pas \u00e0 faire face aux m\u00eames pr\u00e9occupations critiques d'aujourd'hui.<\/p>\n<h2><strong>5 choses que vous pouvez faire pour sensibiliser les jeunes enfants \u00e0 l'impact du plastique sur l'oc\u00e9an<\/strong><\/h2>\n<p><!--more--><\/p>\n<h3><strong>1. Expliquer pourquoi nous avons besoin des oc\u00e9ans du monde<\/strong><\/h3>\n<p>Les jeunes enfants ont une affinit\u00e9 pour l'oc\u00e9an parce qu'il leur offre une aire de jeux sal\u00e9e. C'est un endroit pour s'\u00e9battre dans les vagues, ramasser des coquillages, d\u00e9couvrir des crabes et d'autres petites b\u00eates du littoral, et bien plus encore. D\u00e8s le d\u00e9part, vous avez leur attention, ce qui rend l'introduction du tutoriel suivant encore plus facile.&nbsp;<\/p>\n<p>C'est une chose d'entendre dire que le monde a besoin d'oc\u00e9ans en bonne sant\u00e9, mais comprendre pourquoi est la seule fa\u00e7on d'inspirer les jeunes esprits \u00e0 faire une r\u00e9elle diff\u00e9rence. C'est un plan p\u00e9dagogique que vous voudrez mener \u00e0 l'ext\u00e9rieur (ne devraient-ils pas l'\u00eatre tous ?) pour accro\u00eetre l'engagement, alors <a href=\"https:\/\/oceanservice.noaa.gov\/facts\/why-care-about-ocean.html\" target=\"_blank\" rel=\"noopener\">imprimer ou t\u00e9l\u00e9charger l'infographie de la National Oceanic and Atmospheric Administration<\/a>&nbsp;et rendez-vous sur une plage pr\u00e8s de chez vous et\/ou pendant vos vacances d'\u00e9t\u00e9 pour enseigner \u00e0 vos enfants pourquoi le monde d\u00e9pend des oc\u00e9ans pour sa survie :<\/p>\n<h3 style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30482\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/our-ocean.jpg\" alt=\"keep plastic out of the ocean\" width=\"900\" height=\"680\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/our-ocean.jpg 900w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/our-ocean-300x227.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/our-ocean-768x580.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/our-ocean-24x18.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/our-ocean-36x27.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/our-ocean-48x36.jpg 48w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/h3>\n<h3><strong>2. La Guerre des pailles<\/strong><\/h3>\n<p>L'un des pires pollueurs des oc\u00e9ans par le plastique est le gobelet m\u00eame que vos enfants utilisent pour consommer des briques de jus, des smoothies, des granit\u00e9s et bien plus encore. Apprenez \u00e0 vos enfants l'impact n\u00e9gatif des pailles, ce qui les rendra \u00e0 leur tour plus vigilants \u00e0 la maison et \u00e0 l'ext\u00e9rieur.&nbsp;<\/p>\n<p>De petits changements peuvent faire une grande diff\u00e9rence. <strong>\u00c9vitez d'acheter des briques de jus avec des pailles<\/strong> et de ne plus les utiliser du tout. <strong>Acheter des pailles r\u00e9utilisables et \u00e9cologiques<\/strong> pour vos enfants, disponibles dans de nombreux magasins et en ligne, avec des motifs amusants qui les raviront. Gr\u00e2ce \u00e0 cette alternative plus durable, ils pourront les emporter avec eux dans les restaurants et caf\u00e9s du coin, ainsi que partout o\u00f9 ils auront besoin de boire avec une paille. Si un \u00e9tablissement sert \u00e0 votre famille des boissons avec des pailles avant que vous n\u2019ayez le temps de les en emp\u00eacher, acceptez-les (sinon, ils les jetteront) et demandez \u00e0 vos enfants <strong>Gardez les pailles pour les r\u00e9utiliser \u00e0 la maison<\/strong>. Les vieilles pailles peuvent m\u00eame<strong> utilis\u00e9 pour des projets artistiques color\u00e9s<\/strong> qui transmet un message sur la durabilit\u00e9.&nbsp;<\/p>\n<h3><strong>3. Limiter l&#x27;utilisation des bouteilles en plastique<\/strong><\/h3>\n<p>Les bouteilles en plastique constituent une autre source majeure de pollution marine et font partie des objets courants dont vos enfants peuvent apprendre \u00e0 se passer. \u00c0 partir d\u2019aujourd\u2019hui, n\u2019apportez plus jamais de bouteille en plastique \u00e0 la maison ni lorsque vous sortez avec vos enfants. Ils ont probablement d\u00e9j\u00e0 un <strong>bouteille r\u00e9utilisable sans BPA<\/strong> qu'ils emportent \u00e0 l'\u00e9cole, alors achetez-en un de plus qu'ils pourront utiliser \u00e0 la maison, en vacances et lorsqu'ils sortent jouer avec des amis. Non seulement vous contribuerez \u00e0 sauver les oc\u00e9ans,<strong> tu \u00e9conomiseras de l'argent<\/strong>!<\/p>\n<h3><strong>4. \u201c Sacs de cr\u00e9ateur \u201d (au lieu de sacs en plastique)<\/strong><\/h3>\n<p>Les sacs en plastique compl\u00e8tent le triptyque des ennemis en plastique de l'oc\u00e9an. Non seulement ils <strong>introduire des substances chimiques nocives<\/strong> dans la mer et sur le r\u00e9cif (le cas \u00e9ch\u00e9ant), ils sont <strong>pris pour de la nourriture par les animaux et mammif\u00e8res marins<\/strong>. Flottant dans l'oc\u00e9an, un sac en plastique<strong> on dirait une m\u00e9duse app\u00e9tissante<\/strong> aux tortues de mer, aux thons, aux s\u00e9bastes, aux requins, aux espadons, aux saumons, aux manchots et \u00e0 toute une vari\u00e9t\u00e9 d\u2019oiseaux marins. Expliquez \u00e0 vos enfants quelles esp\u00e8ces marines se nourrissent de m\u00e9duses et comment un sac en plastique pr\u00e9sent dans l\u2019oc\u00e9an peut se retrouver dans leur syst\u00e8me digestif.<\/p>\n<p>Avec ces informations, vos enfants auront envie d'en savoir plus sur les alternatives. Apr\u00e8s tout, ils ont toujours besoin de quelque chose \u00e0 emporter au centre commercial et au march\u00e9 fermier du week-end. Il y a <a href=\"https:\/\/shop.seewhatgrows.flywheelstaging.com\/\">sacs r\u00e9utilisables<\/a> disponible partout pour qu'ils puissent choisir, mais vous pouvez aussi en profiter pour r\u00e9aliser un projet d'art fonctionnel. Prenez un sac en tissu r\u00e9utilisable uni et, avec vos enfants, cousez des \u00e9cussons de leurs personnages pr\u00e9f\u00e9r\u00e9s (etc.) et\/ou utilisez de la peinture sur tissu \u00e9cologique pour faire \u201cressortir\u201d leurs sacs avec des couleurs vibrantes et des designs amusants.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30495\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Screen-Shot-2019-06-12-at-12.55.34-PM.png\" alt=\"\" width=\"184\" height=\"294\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Screen-Shot-2019-06-12-at-12.55.34-PM.png 390w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Screen-Shot-2019-06-12-at-12.55.34-PM-188x300.png 188w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Screen-Shot-2019-06-12-at-12.55.34-PM-15x24.png 15w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Screen-Shot-2019-06-12-at-12.55.34-PM-23x36.png 23w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Screen-Shot-2019-06-12-at-12.55.34-PM-30x48.png 30w\" sizes=\"auto, (max-width: 184px) 100vw, 184px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Vous recherchez de jolis sacs de courses recycl\u00e9s, r\u00e9utilisables et recyclables (#5) qui soutiennent l&#x27;action de la Fondation ? Cliquez ici pour <a href=\"https:\/\/shop.seewhatgrows.flywheelstaging.com\/\">Rendez-vous sur la page de notre boutique<\/a>.<\/span><\/p>\n<h3>&nbsp;<\/h3>\n<p>&nbsp;<\/p>\n<h3><strong>5. Organisez un nettoyage hebdomadaire de la plage<\/strong><\/h3>\n<p>Cette activit\u00e9 peut \u00eatre consid\u00e9r\u00e9e comme une conclusion in\u00e9vitable, d\u2019autant plus que nous l\u2019avons d\u00e9j\u00e0 incluse dans nos listes pr\u00e9c\u00e9dentes de <a href=\"https:\/\/seewhatgrows.org\/fr\/celebrate-world-oceans-day-2018\/\">comment c\u00e9l\u00e9brer la Journ\u00e9e mondiale de l'oc\u00e9an<\/a> et d'autres id\u00e9es d'activit\u00e9s d'apprentissage en plein air. Mais h\u00e9las, il n'y a pas de moyen plus captivant d'enthousiasmer vos jeunes enfants pour la protection des oc\u00e9ans contre le plastique. En apprenant tout ce qui pr\u00e9c\u00e8de, ils savent d\u00e9sormais quoi surveiller le long du rivage et, arm\u00e9s d'un sac recyclable (pas en plastique), de gants et de pinces \u00e0 d\u00e9chets, ils peuvent se rendre sur la plage en famille et\/ou entre amis et ramasser tout plastique qu'ils croisent. Non seulement cette activit\u00e9 hebdomadaire aura un impact direct sur la sant\u00e9 de l'oc\u00e9an pr\u00e8s de chez eux, mais ils constateront que leurs actions sont pour le moins contagieuses, car les plagistes remarquent leurs bonnes actions, les remercient de faire une diff\u00e9rence et s'inspirent eux-m\u00eames pour suivre le mouvement et faire de m\u00eame. Ces retours de la communaut\u00e9 locale de la plage insuffleront \u00e0 vos jeunes enfants un sentiment de fiert\u00e9 qui r\u00e9sonnera pendant des ann\u00e9es, voire des d\u00e9cennies, leur offrant une exp\u00e9rience absolument inestimable.&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><em><strong>~ Joyeuse Journ\u00e9e mondiale des oc\u00e9ans, chaque jour ~<\/strong><\/em><\/h3>\n<p>========================================================<\/p>\n<p>Pour en savoir plus sur le travail de la Fondation, veuillez visiter notre <a href=\"https:\/\/seewhatgrows.org\/fr\/programs\/\">Page des programmes financ\u00e9s<\/a>. Il existe de nombreuses fa\u00e7ons de vous impliquer aupr\u00e8s de la fondation \u00ab Plant a Seed &amp; See What Grows \u00bb : vous pouvez consulter notre&nbsp;<strong><a href=\"https:\/\/seewhatgrows.org\/fr\/get-involved\/\">Participez<\/a><\/strong> page,&nbsp;<strong><a href=\"https:\/\/www.classy.org\/campaign\/create-a-garden-inspire-a-generation-creatagarden17\/c104179\">Aidez \u00e0 collecter des fonds<\/a><\/strong>, ou&nbsp;<strong><a href=\"https:\/\/www.classy.org\/give\/63857\/#!\/donation\/checkout\">Faites un don maintenant<\/a><\/strong>.<\/p>\n<hr \/>\n<p><em><strong>Vous cherchez des jeunes militants pour trouver l&#x27;inspiration ? D\u00e9couvrez-les sur <a href=\"https:\/\/twitter.com\/RachelsNews\/\">@RachelsNews<\/a> <a href=\"https:\/\/twitter.com\/AshafortheWorld\">@AshafortheWorld<\/a> &nbsp;&nbsp;<\/strong><\/em><\/p>\n<p><em><strong> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ou de jeunes mod\u00e8les qui font bouger les choses d\u00e8s maintenant ?<\/strong><\/em><\/p>\n<p><em><strong>En savoir plus sur eux <a href=\"https:\/\/seewhatgrows.org\/fr\/3-positive-role-models-child\/\">ici<\/a>.<\/strong><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Whether you find this article in time for World Oceans Day 2019, or days, weeks, or months after the fact is beside the point, as this year&#8217;s theme will apply all the same.&nbsp;Conservation is the&nbsp;focus, with a mandate to &#8220;demonstrate leadership in preventing plastic pollution and share solutions that inspire and activate the global community&#8221;. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":30478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[647,649,648],"class_list":["post-30476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-keep-plastic-out-of-the-ocean","tag-save-the-oceans","tag-world-oceans-day-2019"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Keep Plastic Out of the Ocean - How Kids Can Help Save the Oceans<\/title>\n<meta name=\"description\" content=\"5 things you can do to teach young children about the impact of plastic on the ocean, courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/kids-can-help-keep-plastic-ocean\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Keep Plastic Out of the Ocean - How Kids Can Help Save the Oceans\" \/>\n<meta property=\"og:description\" content=\"5 things you can do to teach young children about the impact of plastic on the ocean, courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/kids-can-help-keep-plastic-ocean\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-06T22:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-12T20:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"How Kids Can Help Keep Plastic Out of the Ocean\",\"datePublished\":\"2019-06-06T22:46:00+00:00\",\"dateModified\":\"2019-06-12T20:27:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/\"},\"wordCount\":1098,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg\",\"keywords\":[\"Keep Plastic Out of the Ocean\",\"Save the Oceans\",\"World Oceans Day 2019\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/\",\"name\":\"Keep Plastic Out of the Ocean - How Kids Can Help Save the Oceans\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg\",\"datePublished\":\"2019-06-06T22:46:00+00:00\",\"dateModified\":\"2019-06-12T20:27:47+00:00\",\"description\":\"5 things you can do to teach young children about the impact of plastic on the ocean, courtesy of the Plant a Seed and See What Grows Foundation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg\",\"width\":2200,\"height\":1304,\"caption\":\"Keep Plastic Out of the Ocean - How Kids Can Help Save the Oceans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/kids-can-help-keep-plastic-ocean\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Kids Can Help Keep Plastic Out of the Ocean\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gardons le plastique hors de l'oc\u00e9an - Comment les enfants peuvent aider \u00e0 sauver les oc\u00e9ans","description":"5 choses que vous pouvez faire pour sensibiliser les jeunes enfants \u00e0 l'impact du plastique sur l'oc\u00e9an, gracieuset\u00e9 de la Fondation Plant a Seed and See What Grows.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/kids-can-help-keep-plastic-ocean\/","og_locale":"fr_CA","og_type":"article","og_title":"Keep Plastic Out of the Ocean - How Kids Can Help Save the Oceans","og_description":"5 things you can do to teach young children about the impact of plastic on the ocean, courtesy of the Plant a Seed and See What Grows Foundation.","og_url":"https:\/\/seewhatgrows.org\/fr\/kids-can-help-keep-plastic-ocean\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2019-06-06T22:46:00+00:00","article_modified_time":"2019-06-12T20:27:47+00:00","og_image":[{"width":2200,"height":1304,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"How Kids Can Help Keep Plastic Out of the Ocean","datePublished":"2019-06-06T22:46:00+00:00","dateModified":"2019-06-12T20:27:47+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/"},"wordCount":1098,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg","keywords":["Keep Plastic Out of the Ocean","Save the Oceans","World Oceans Day 2019"],"articleSection":["Blogs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/","url":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/","name":"Gardons le plastique hors de l'oc\u00e9an - Comment les enfants peuvent aider \u00e0 sauver les oc\u00e9ans","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg","datePublished":"2019-06-06T22:46:00+00:00","dateModified":"2019-06-12T20:27:47+00:00","description":"5 choses que vous pouvez faire pour sensibiliser les jeunes enfants \u00e0 l'impact du plastique sur l'oc\u00e9an, gracieuset\u00e9 de la Fondation Plant a Seed and See What Grows.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/06\/Keep-Plastic-Out-of-the-Ocean-How-Kids-Can-Help-Save-the-Oceans.jpg","width":2200,"height":1304,"caption":"Keep Plastic Out of the Ocean - How Kids Can Help Save the Oceans"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/kids-can-help-keep-plastic-ocean\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"How Kids Can Help Keep Plastic Out of the Ocean"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/30476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=30476"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/30476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/30478"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=30476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=30476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=30476"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}