{"id":30312,"date":"2019-02-25T11:42:09","date_gmt":"2019-02-25T19:42:09","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=30312"},"modified":"2019-02-25T11:42:09","modified_gmt":"2019-02-25T19:42:09","slug":"how-to-celebrate-world-wildlife-day-with-your-kids","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-world-wildlife-day-with-your-kids\/","title":{"rendered":"Comment c\u00e9l\u00e9brer la Journ\u00e9e mondiale de la vie sauvage avec vos enfants"},"content":{"rendered":"<p>La Journ\u00e9e mondiale de la vie sauvage est un \u00e9v\u00e9nement d\u00e9sign\u00e9 par les Nations Unies pour c\u00e9l\u00e9brer et sensibiliser aux animaux et aux plantes sauvages de la plan\u00e8te. Elle a lieu le 3 mars de chaque ann\u00e9e et, bien que les esp\u00e8ces de notre plan\u00e8te m\u00e9ritent de l'attention chaque jour, nous vous sugg\u00e9rons de r\u00e9server cette date pour planifier des activit\u00e9s avec vos enfants afin de leur enseigner comment les animaux de la plan\u00e8te d\u00e9pendent de notre soutien, et vice versa.<\/p>\n<h2><strong>4 activit\u00e9s que vous et vos enfants\/\u00e9l\u00e8ves pouvez faire pour c\u00e9l\u00e9brer la Journ\u00e9e mondiale de la vie sauvage<\/strong><\/h2>\n<p><!--more--><\/p>\n<h3><strong>1. Se connecter au th\u00e8me<\/strong><\/h3>\n<p>L'ONU d\u00e9signe un nouveau th\u00e8me chaque an. Cela vous donne l'inspiration n\u00e9cessaire pour adapter une activit\u00e9 en cons\u00e9quence. Par exemple, en 2019, le th\u00e8me \u00e9tait \u201c<strong>La vie aquatique : pour l'humanit\u00e9 et la plan\u00e8te<\/strong>\u201c, ce qui s'aligne sur les Objectifs de d\u00e9veloppement durable des Nations unies. \u00c9tant donn\u00e9 que la faune marine a soutenu la civilisation et le d\u00e9veloppement humains pendant des milliers d'ann\u00e9es, fournissant nourriture, subsistance, m\u00e9dicaments et mat\u00e9riaux de construction, en plus d'offrir un enrichissement culturel, r\u00e9cr\u00e9atif et spirituel aux gens de tant de mani\u00e8res, il est certainement temps de rendre la pareille.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30319\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/World-Wildlife-Day.jpg\" alt=\"World Wildlife Day 2019\" width=\"900\" height=\"528\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/World-Wildlife-Day.jpg 900w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/World-Wildlife-Day-300x176.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/World-Wildlife-Day-768x451.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/World-Wildlife-Day-24x14.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/World-Wildlife-Day-36x21.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/World-Wildlife-Day-48x28.jpg 48w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>Si vous habitez pr\u00e8s de l'oc\u00e9an, les possibilit\u00e9s d'apprentissage en plein air sont infinies. Vous pouvez emmener vos enfants participer au nettoyage d'une plage ou \u00e9tudier la vie marine que l'on trouve le long du rivage (crabes, \u00e9toiles de mer, etc.) tout en leur donnant des cours sur leur place dans l'\u00e9cosyst\u00e8me local et mondial. Si vous ne vivez pas pr\u00e8s de l'oc\u00e9an, un lac ou m\u00eame un \u00e9tang fera tr\u00e8s bien l'affaire. Vous pouvez \u00e9galement inclure une visite \u00e0 votre aquarium local.<\/p>\n<h3><strong>2. Faites une excursion \u00e9cologique<\/strong><\/h3>\n<p>Si vous habitez au Canada, il y a de fortes chances qu'il y ait une excursion \u00e9cotouristique officielle pr\u00e8s de votre ville ou de votre village. Certaines sont en groupe et d'autres se r\u00e9servent en visite priv\u00e9e. Besoin d'exemples ? En Colombie-Britannique, de nombreuses entreprises proposent <strong>excursions dans la for\u00eat tropicale<\/strong>. Ils proposent aux participants des aventures guid\u00e9es \u00e0 travers les \u00e9tendues \u00e0 couper le souffle des for\u00eats tropicales de la Colombie-Britannique, couvrant tout, des canop\u00e9es foresti\u00e8res luxuriantes aux cascades cach\u00e9es, en passant par les grottes et bien plus encore, avec une faune diversifi\u00e9e rencontr\u00e9e (et abord\u00e9e) partout en chemin.<\/p>\n<p>Peu importe l'endroit o\u00f9 vous vivez dans notre grand pays, car il existe d'immenses possibilit\u00e9s d'observer la faune et d'en apprendre davantage sur son habitat et son lien avec nous en tant que population. Par exemple, saviez-vous que le Manitoba est l'un des meilleurs endroits au monde pour observer <strong>ours polaires<\/strong> dans leur environnement naturel ? Il vous suffit de faire un peu de recherche pour offrir \u00e0 vos enfants une le\u00e7on en plein air sur la faune locale qui les \u00e9patera !<\/p>\n<h3><strong>3. Parlez-leur de la reproduction<\/strong><\/h3>\n<p>Attendez, ce n'est pas sorti comme \u00e7a. Non, ce n'est pas le moment d'avoir cette conversation inconfortable. Au lieu de cela, nous sommes litt\u00e9raux puisqu'il n'y a gu\u00e8re de sujet plus important \u00e0 aborder que celui-ci \u2013 <strong>pollinisateurs<\/strong>. Apr\u00e8s tout, la mission officielle de la Journ\u00e9e mondiale de la faune est de \u201c sensibiliser le public aux animaux et plantes sauvages de la plan\u00e8te et <em>plantes<\/em>\u201c.<\/p>\n<p>Notre monde d\u00e9pend des cr\u00e9atures pollinisatrices bien plus que la plupart ne pourraient jamais l'imaginer. Sans certaines esp\u00e8ces d'oiseaux en plus des abeilles et d'autres insectes, notre<strong> plantes produisant de la nourriture et de l'oxyg\u00e8ne<\/strong> cesserait d'exister. C'est pourquoi il est essentiel d'enseigner \u00e0 nos enfants la faune et les insectes utiles, afin que les g\u00e9n\u00e9rations futures comprennent l'importance de les prot\u00e9ger.<\/p>\n<p>Bien que cela puisse \u00eatre une t\u00e2che assez simple pour ceux d'entre vous qui vivent dans des communaut\u00e9s rurales avec des fermes locales et des jardins \u00e0 chaque coin de rue, ceux qui vivent et enseignent dans des communaut\u00e9s urbaines peuvent se sentir impuissants lorsqu'il s'agit de trouver l'inspiration. Ne vous inqui\u00e9tez pas, car notre Fondation a d\u00e9j\u00e0 fourni un guide sur <a href=\"https:\/\/seewhatgrows.org\/fr\/how-to-introduce-pollinators-into-an-urban-environment\/\">comment introduire des pollinisateurs dans un environnement urbain<\/a>, aussi densifi\u00e9e et b\u00e9tonn\u00e9e soit-elle. En plus de s'impliquer (ou de lancer) <strong>jardins scolaires ou communautaires<\/strong>, vous pouvez visiter un site local <strong>rucher<\/strong> ou <strong>r\u00e9serve ornithologique<\/strong>.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30317\" src=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day-Pollinators.jpg\" alt=\"How to Celebrate World Wildlife Day\" width=\"900\" height=\"528\" srcset=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day-Pollinators.jpg 900w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day-Pollinators-300x176.jpg 300w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day-Pollinators-768x451.jpg 768w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day-Pollinators-24x14.jpg 24w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day-Pollinators-36x21.jpg 36w, https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day-Pollinators-48x28.jpg 48w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>Notre Fondation a \u00e9galement fourni d'autres guides sur les pollinisateurs que vous pouvez utiliser pour inspirer de nombreuses activit\u00e9s de la Journ\u00e9e mondiale de la vie sauvage dans votre communaut\u00e9 :<\/p>\n<ul>\n<li><a href=\"https:\/\/seewhatgrows.org\/fr\/make-pollinator-garden\/\">Comment cr\u00e9er un jardin pour pollinisateurs<\/a><\/li>\n<li><a href=\"https:\/\/seewhatgrows.org\/fr\/time-bee-aware\/\">Crise des abeilles : il est temps de prendre conscience<\/a><\/li>\n<li><a href=\"https:\/\/seewhatgrows.org\/fr\/how-protect-beneficial-bugs-winter-garden\/\">Comment garder les insectes utiles dans votre jardin toute l'ann\u00e9e<\/a><\/li>\n<li><a href=\"https:\/\/seewhatgrows.org\/fr\/community-garden-needs-bees\/\">Pourquoi votre jardin a besoin d'abeilles et de gu\u00eapes<\/a><\/li>\n<\/ul>\n<h3><strong>4. Visite de la ferme<\/strong><\/h3>\n<p>Vous n'avez pas besoin d'aller dans un zoo pour d\u00e9couvrir les merveilles de la faune, surtout si vous voulez que vos enfants comprennent comment les animaux sont li\u00e9s au concept d'une communaut\u00e9 autonome. Il y a peut-\u00eatre des exploitations agricoles dans votre r\u00e9gion qui non seulement permettent des visites de classes, mais proposent des programmes pour une exp\u00e9rience plus immersive, permettant aux enfants de voir comment les animaux font partie de la production agricole de notre pays. En fait, gr\u00e2ce au soutien de son membre fondateur, Natural Factors, notre Fondation propose un programme de <a href=\"https:\/\/seewhatgrows.org\/fr\/our-causes\/outdoor-learning-experiences\/\">visites de la ferme gratuites<\/a> aux \u00e9coles primaires et secondaires de la r\u00e9gion de l'Okanagan en Colombie-Britannique.<\/p>\n<hr \/>\n<p>Si vous souhaitez en savoir plus sur le travail de la Fondation, veuillez vous inscrire \u00e0 <a href=\"https:\/\/seewhatgrows.org\/fr\/friends\/\">devenir un Ami de la Fondation<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>World Wildlife Day is a&nbsp;United Nations designated affair to celebrate and raise awareness of the world\u2019s wild animals and plants. It lands on March 3 of each year, and while the species of our planet deserve attention every day, we suggest saving the date to slot in activities with your kids to teach them about [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":30316,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[633,83,560,632],"class_list":["post-30312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-canadian-wildlife","tag-outdoor-learning-experiences","tag-pollinators","tag-world-wildlife-day"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to Celebrate World Wildlife Day With Your Kids<\/title>\n<meta name=\"description\" content=\"Four activities you and your children-students can do to recognize World Wildlife Day on March 3, courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-world-wildlife-day-with-your-kids\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Celebrate World Wildlife Day With Your Kids\" \/>\n<meta property=\"og:description\" content=\"Four activities you and your children-students can do to recognize World Wildlife Day on March 3, courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-world-wildlife-day-with-your-kids\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-25T19:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"How to Celebrate World Wildlife Day With Your Kids\",\"datePublished\":\"2019-02-25T19:42:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/\"},\"wordCount\":814,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/How-to-Celebrate-World-Wildlife-Day.jpg\",\"keywords\":[\"Canadian Wildlife\",\"Outdoor Learning Experiences\",\"Pollinators\",\"World Wildlife Day\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/\",\"name\":\"How to Celebrate World Wildlife Day With Your Kids\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/How-to-Celebrate-World-Wildlife-Day.jpg\",\"datePublished\":\"2019-02-25T19:42:09+00:00\",\"description\":\"Four activities you and your children-students can do to recognize World Wildlife Day on March 3, courtesy of the Plant a Seed and See What Grows Foundation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/How-to-Celebrate-World-Wildlife-Day.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/How-to-Celebrate-World-Wildlife-Day.jpg\",\"width\":2200,\"height\":1295,\"caption\":\"How to Celebrate World Wildlife Day\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/how-to-celebrate-world-wildlife-day-with-your-kids\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Celebrate World Wildlife Day With Your Kids\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment c\u00e9l\u00e9brer la Journ\u00e9e mondiale de la vie sauvage avec vos enfants","description":"Quatre activit\u00e9s que vous et vos enfants ou \u00e9l\u00e8ves pouvez faire pour c\u00e9l\u00e9brer la Journ\u00e9e mondiale de la vie sauvage le 3 mars, une courtoisie de la fondation Plante une graine et vois ce qui pousse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-world-wildlife-day-with-your-kids\/","og_locale":"fr_CA","og_type":"article","og_title":"How to Celebrate World Wildlife Day With Your Kids","og_description":"Four activities you and your children-students can do to recognize World Wildlife Day on March 3, courtesy of the Plant a Seed and See What Grows Foundation.","og_url":"https:\/\/seewhatgrows.org\/fr\/how-to-celebrate-world-wildlife-day-with-your-kids\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2019-02-25T19:42:09+00:00","og_image":[{"width":2200,"height":1295,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"How to Celebrate World Wildlife Day With Your Kids","datePublished":"2019-02-25T19:42:09+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/"},"wordCount":814,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day.jpg","keywords":["Canadian Wildlife","Outdoor Learning Experiences","Pollinators","World Wildlife Day"],"articleSection":["Blogs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/","url":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/","name":"Comment c\u00e9l\u00e9brer la Journ\u00e9e mondiale de la vie sauvage avec vos enfants","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day.jpg","datePublished":"2019-02-25T19:42:09+00:00","description":"Quatre activit\u00e9s que vous et vos enfants ou \u00e9l\u00e8ves pouvez faire pour c\u00e9l\u00e9brer la Journ\u00e9e mondiale de la vie sauvage le 3 mars, une courtoisie de la fondation Plante une graine et vois ce qui pousse.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day.jpg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2019\/02\/How-to-Celebrate-World-Wildlife-Day.jpg","width":2200,"height":1295,"caption":"How to Celebrate World Wildlife Day"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/how-to-celebrate-world-wildlife-day-with-your-kids\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"How to Celebrate World Wildlife Day With Your Kids"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/30312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=30312"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/30312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/30316"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=30312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=30312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=30312"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}