{"id":29955,"date":"2018-10-26T18:46:08","date_gmt":"2018-10-27T01:46:08","guid":{"rendered":"http:\/\/seewhatgrows.flywheelsites.com\/?p=29955"},"modified":"2018-10-26T18:46:08","modified_gmt":"2018-10-27T01:46:08","slug":"celebrate-universal-childrens-day-school-home","status":"publish","type":"post","link":"https:\/\/seewhatgrows.org\/fr\/celebrate-universal-childrens-day-school-home\/","title":{"rendered":"Comment c\u00e9l\u00e9brer la Journ\u00e9e universelle des enfants \u00e0 l'\u00e9cole et \u00e0 la maison"},"content":{"rendered":"<p>Si vous avez suivi <a href=\"https:\/\/seewhatgrows.org\/fr\/international-days-celebration-inspire-kids-2018\/\">notre calendrier des Journ\u00e9es internationales de reconnaissance<\/a> (2018), alors vous savez que la Journ\u00e9e universelle de l'enfance approche. Cette journ\u00e9e reconnue par l'ONU plaide, promeut et c\u00e9l\u00e8bre les droits des enfants en ouvrant le dialogue et en encourageant des actions qui b\u00e2tiront un monde meilleur pour eux. Dans l'esprit de cet \u00e9v\u00e9nement mondial, nous offrons aux \u00e9ducateurs comme aux parents des id\u00e9es sur la mani\u00e8re de c\u00e9l\u00e9brer cette journ\u00e9e avec les enfants, afin de passer le relais aux futurs gardiens de notre pr\u00e9cieuse plan\u00e8te.<\/p>\n<h2><strong>5 fa\u00e7ons dont vous et vos enfants pouvez reconna\u00eetre et apprendre de la Journ\u00e9e universelle de l'enfance<\/strong><\/h2>\n<p><!--more--><\/p>\n<p><strong>Donnez vie \u00e0 un jardin scolaire<\/strong><\/p>\n<p>Pour les non-initi\u00e9s, un jardin scolaire est le prolongement du concept de jardin communautaire \/ d'agriculture urbaine que vous voyez d\u00e9j\u00e0 en action quelque part dans votre r\u00e9gion. La diff\u00e9rence, c'est qu'un jardin scolaire se trouve g\u00e9n\u00e9ralement sur ou pr\u00e8s des terrains de l'\u00e9cole, et qu'il est g\u00e9r\u00e9 par les \u00e9l\u00e8ves avec le corps enseignant et d'autres b\u00e9n\u00e9voles. Un jardin scolaire fournit non seulement des aliments sains et nutritifs aux \u00e9l\u00e8ves, mais c'est aussi une exp\u00e9rience d'apprentissage en plein air qui leur enseigne une grande vari\u00e9t\u00e9 de comp\u00e9tences qui leur seront inestimables de l'adolescence \u00e0 l'\u00e2ge adulte. Pourquoi ne pas utiliser la Journ\u00e9e universelle des enfants comme point de d\u00e9part pour votre propre projet ? Certes, nous sommes peut-\u00eatre en fin d'automne, mais vous pouvez certainement lancer les choses avec vos \u00e9l\u00e8ves d\u00e8s maintenant, d'autant plus qu'il faut du temps pour le mettre sur pied. Apprenez comment vous et vos \u00e9l\u00e8ves\/enfants pouvez commencer <a href=\"https:\/\/seewhatgrows.org\/fr\/start-school-garden-project-students\/\">ici<\/a>.<\/p>\n<p>M\u00eame si votre \u00e9tablissement d'enseignement poss\u00e8de d\u00e9j\u00e0 un jardin scolaire, vous pourriez vouloir regarder ceux-ci <a href=\"https:\/\/seewhatgrows.org\/fr\/6-school-garden-examples-to-inspire-your-own\/\">6 exemples d'autres programmes de jardins scolaires<\/a>, dont chacune met en \u0153uvre une initiative unique qui pourrait inspirer une excellente nouvelle id\u00e9e pour la v\u00f4tre, \u00e0 compter de cette Journ\u00e9e universelle des enfants.<\/p>\n<p><strong>Quitter la salle de classe pour la journ\u00e9e<\/strong><\/p>\n<p>Nous avons d\u00e9j\u00e0 mentionn\u00e9 l'apprentissage en plein air ci-dessus, mais cela vaut la peine de le r\u00e9p\u00e9ter. Ce 20 novembre (2018), sortez vos enfants de la classe et emmenez les le\u00e7ons dehors (si la m\u00e9t\u00e9o le permet). \u00c9tant donn\u00e9 le changement climatique, il est impossible de pr\u00e9dire quel temps il fera ce jour-l\u00e0, c'est pourquoi nous avons r\u00e9dig\u00e9 cet article d\u00e9taillant <a href=\"https:\/\/seewhatgrows.org\/fr\/family-outdoor-education-activities-four-seasons\/\">activit\u00e9s \u00e9ducatives en plein air pour les quatre saisons<\/a>. Et si c'est une journ\u00e9e d'automne typique, nous avons ce qu'il vous faut avec <a href=\"https:\/\/seewhatgrows.org\/fr\/5-outdoor-learning-experiences-and-activities-for-kids-in-the-fall-season\/\">ces 5 id\u00e9es<\/a>, ce qui comprend la participation \u00e0 une r\u00e9colte dans un jardin ou une ferme locale, la visite d'un labyrinthe de ma\u00efs, une excursion \u00e9cologique d'automne, et bien plus encore.<\/p>\n<p><strong>Leur faire la lecture (et encha\u00eener avec un film porteur d'un message)<\/strong><\/p>\n<p>Ceux d'entre vous qui ont des enfants ou des \u00e9l\u00e8ves particuli\u00e8rement jeunes peuvent utiliser la Journ\u00e9e universelle des enfants comme un excellent pr\u00e9texte pour prolonger l'heure du conte. Et nous avons deux excellentes suggestions ! D'une part, il y a le livre pour enfants classique de Roland Gahler, <a href=\"https:\/\/seewhatgrows.org\/fr\/plant-a-seed-see-what-grows-childrens-book\/\">S\u00e8me et vois ce qui adviendra<\/a>&nbsp;et la suite, <a href=\"https:\/\/seewhatgrows.org\/fr\/plant-a-seed-see-what-grows-childrens-book\/\">Que feras-tu de ta r\u00e9colte ?<\/a>. Une fois l'heure du conte termin\u00e9e (et si l'emploi du temps le permet), vous pouvez vraiment enthousiasmer les enfants en regardant un film ensemble, un film qui leur enseigne certains des m\u00eames concepts que ceux trouv\u00e9s dans les livres que vous venez de lire. Nous avons dress\u00e9 une liste de films populaires <a href=\"https:\/\/seewhatgrows.org\/fr\/childrens-films-seeds-plants-get-excited-sustainability\/\">films pour enfants sur les graines, les plantes et le d\u00e9veloppement durable<\/a> pour votre r\u00e9f\u00e9rence.<\/p>\n<p><strong>Apprenez-leur l'existence d'enfants d'une autre communaut\u00e9 de l'autre c\u00f4t\u00e9 du monde<\/strong><\/p>\n<p>\u00c9tant donn\u00e9 que <em>Universel<\/em> Journ\u00e9e des enfants, consacrez un peu de temps \u00e0 enseigner \u00e0 vos enfants les enfants d'un pays moins d\u00e9velopp\u00e9 ou qui fait face \u00e0 une autre menace importante pour la sant\u00e9, le bien-\u00eatre et\/ou l'\u00e9ducation de la jeunesse. Si votre \u00e9cole a une <strong>ville jumel\u00e9e<\/strong> Afin de promouvoir les liens culturels, vous pourriez envisager de vous concentrer sur ce que vivent les jeunes l\u00e0-bas. L'\u00e2ge de vos enfants\/de votre classe contribuera \u00e9galement \u00e0 dicter les sujets sur lesquels vous souhaitez vous concentrer, car certains probl\u00e8mes (c'est-\u00e0-dire le travail des enfants, ou pire) peuvent \u00eatre trop intenses pour les jeunes \u00e9l\u00e8ves. Les pr\u00e9occupations importantes qui conviennent \u00e0 tous les \u00e2ges incluent <strong>pauvret\u00e9 infantile<\/strong>, un manque de <strong>acc\u00e8s \u00e0 la nourriture et \u00e0 l'eau potable<\/strong>, et un manque de <strong>acc\u00e8s \u00e0 l'\u00e9ducation<\/strong>.<\/p>\n<p>Une autre activit\u00e9 connexe que vous pouvez envisager est de lancer un programme de correspondance avec des \u00e9l\u00e8ves de la r\u00e9gion sur laquelle vous vous concentrez (ou d'une autre), ce qui permettra \u00e0 vos enfants de mieux se connecter aux concepts abord\u00e9s. Voir les \u00e9coles participantes au programme de correspondance <a href=\"https:\/\/www.penpalschools.com\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n<p><strong>Aidez \u00e0 soutenir un programme de b\u00e9n\u00e9volat communautaire pour les enfants<\/strong><\/p>\n<p>Une fa\u00e7on dont vous et vos enfants pouvez r\u00e9ellement avoir un impact positif est de soutenir une initiative locale ou nationale qui a le m\u00eame objectif de favoriser la sant\u00e9, le bien-\u00eatre et l'apprentissage des jeunes au Canada. Par exemple, notre Fondation a une <a href=\"https:\/\/seewhatgrows.org\/fr\/get-involved\/\">gamme compl\u00e8te de programmes et d'opportunit\u00e9s<\/a> qui vous offrent, \u00e0 vous et \u00e0 votre classe ou foyer, l'occasion de montrer votre soutien en faisant don de biens, de temps et de talents. S'il n'y a pas de programme identifiable pr\u00e8s de chez vous pour orienter le travail b\u00e9n\u00e9vole, vous pouvez lancer une collecte de fonds ludique. Vous pouvez organiser les ventes de p\u00e2tisseries, collectes de recyclage, marches parrain\u00e9es, etc. habituelles, ou vous pouvez essayer l'outil de collecte de fonds en ligne simple et s\u00e9curis\u00e9 de la Fondation <a href=\"https:\/\/www.classy.org\/campaign\/create-a-garden-inspire-a-generation-createagarden17\/c104179\">ici,<\/a> trop. Les fonds r\u00e9colt\u00e9s sur notre page de collecte sont revers\u00e9s \u00e0 votre \u00e9cole et \u00e0 vos jardins communautaires. Bien entendu, votre soutien peut \u00e9galement aller \u00e0 toute autre initiative b\u00e9n\u00e9ficiant aux enfants, veillez simplement \u00e0 faire preuve de diligence raisonnable pour vous assurer que vos tr\u00e9sors, votre temps et\/ou vos talents susmentionn\u00e9s sont attribu\u00e9s \u00e0 une cause valable. Si vous avez des questions ou souhaitez savoir comment vous impliquer, <a href=\"https:\/\/seewhatgrows.org\/fr\/contact\/\">contacter la Fondation Plant a Seed &amp; See What Grows<\/a>.&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>~ Joyeuse Journ\u00e9e universelle des enfants 2018 ~<\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>If you&#8217;ve been following our International Days of Recognition calendar (2018) then you know that Universal Children&#8217;s Day is on the way. The UN sanctioned day advocates, promotes and celebrates children\u2019s rights by opening dialogues and encouraging actions that will build a better world for children. In the spirit of the global event, we&#8217;re providing [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":29964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[197,583,541],"class_list":["post-29955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs","tag-outdoor-learning","tag-school-garden","tag-universal-childrens-day"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to Celebrate Universal Children&#039;s Day in School and Home<\/title>\n<meta name=\"description\" content=\"5 Ways You and Your Kids Can Recognition and Learn from Universal Children&#039;s Day, courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/celebrate-universal-childrens-day-school-home\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to Celebrate Universal Children&#039;s Day in School and Home\" \/>\n<meta property=\"og:description\" content=\"5 Ways You and Your Kids Can Recognition and Learn from Universal Children&#039;s Day, courtesy of the Plant a Seed and See What Grows Foundation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/celebrate-universal-childrens-day-school-home\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-27T01:46:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2018\/10\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1298\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Charland\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Charland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/\"},\"author\":{\"name\":\"Dennis Charland\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\"},\"headline\":\"How to Celebrate Universal Children&#8217;s Day in School and at Home\",\"datePublished\":\"2018-10-27T01:46:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/\"},\"wordCount\":933,\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg\",\"keywords\":[\"Outdoor Learning\",\"school garden\",\"Universal Children's Day\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/\",\"name\":\"How to Celebrate Universal Children's Day in School and Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg\",\"datePublished\":\"2018-10-27T01:46:08+00:00\",\"description\":\"5 Ways You and Your Kids Can Recognition and Learn from Universal Children's Day, courtesy of the Plant a Seed and See What Grows Foundation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg\",\"width\":2200,\"height\":1298,\"caption\":\"How to Celebrate Universal Children's Day in School and at Home\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/celebrate-universal-childrens-day-school-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to Celebrate Universal Children&#8217;s Day in School and at Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/person\\\/b68aed2f630ae4c478c9855f63384764\",\"name\":\"Dennis Charland\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/fr\\\/author\\\/dennis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment c\u00e9l\u00e9brer la Journ\u00e9e universelle des enfants \u00e0 l'\u00e9cole et \u00e0 la maison","description":"5 fa\u00e7ons pour vous et vos enfants de reconna\u00eetre et d'apprendre de la Journ\u00e9e universelle des enfants, gracieuset\u00e9 de la Fondation Plantez une graine et voyez ce qui pousse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/celebrate-universal-childrens-day-school-home\/","og_locale":"fr_CA","og_type":"article","og_title":"How to Celebrate Universal Children's Day in School and Home","og_description":"5 Ways You and Your Kids Can Recognition and Learn from Universal Children's Day, courtesy of the Plant a Seed and See What Grows Foundation.","og_url":"https:\/\/seewhatgrows.org\/fr\/celebrate-universal-childrens-day-school-home\/","og_site_name":"Connecting Communities to the Land","article_published_time":"2018-10-27T01:46:08+00:00","og_image":[{"width":2200,"height":1298,"url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2018\/10\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg","type":"image\/jpeg"}],"author":"Dennis Charland","twitter_misc":{"\u00c9crit par":"Dennis Charland","Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/#article","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/"},"author":{"name":"Dennis Charland","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764"},"headline":"How to Celebrate Universal Children&#8217;s Day in School and at Home","datePublished":"2018-10-27T01:46:08+00:00","mainEntityOfPage":{"@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/"},"wordCount":933,"publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"image":{"@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2018\/10\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg","keywords":["Outdoor Learning","school garden","Universal Children's Day"],"articleSection":["Blogs"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/","url":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/","name":"Comment c\u00e9l\u00e9brer la Journ\u00e9e universelle des enfants \u00e0 l'\u00e9cole et \u00e0 la maison","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/#primaryimage"},"image":{"@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/#primaryimage"},"thumbnailUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2018\/10\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg","datePublished":"2018-10-27T01:46:08+00:00","description":"5 fa\u00e7ons pour vous et vos enfants de reconna\u00eetre et d'apprendre de la Journ\u00e9e universelle des enfants, gracieuset\u00e9 de la Fondation Plantez une graine et voyez ce qui pousse.","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/#primaryimage","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2018\/10\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2018\/10\/How-to-Celebrate-Universal-Childrens-Day-in-School.jpg","width":2200,"height":1298,"caption":"How to Celebrate Universal Children's Day in School and at Home"},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/celebrate-universal-childrens-day-school-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"How to Celebrate Universal Children&#8217;s Day in School and at Home"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/seewhatgrows.org\/#\/schema\/person\/b68aed2f630ae4c478c9855f63384764","name":"Dennis Charland","url":"https:\/\/seewhatgrows.org\/fr\/author\/dennis\/"}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/29955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=29955"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/posts\/29955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media\/29964"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=29955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/categories?post=29955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/tags?post=29955"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}