{"id":418970,"date":"2026-03-31T08:28:05","date_gmt":"2026-03-31T15:28:05","guid":{"rendered":"https:\/\/seewhatgrows.org\/?page_id=418970"},"modified":"2026-05-01T14:38:22","modified_gmt":"2026-05-01T21:38:22","slug":"jour-de-la-terre-2026-concours-de-dessins","status":"publish","type":"page","link":"https:\/\/seewhatgrows.org\/fr\/jour-de-la-terre-2026-concours-de-dessins\/","title":{"rendered":"JOUR DE LA TERRE 2026"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/03\/Art-Contest-Header-2026-French.png&#8221; title_text=&#8221;Art Contest Header 2026 &#8211; French&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|0px|5%|false|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;C\u00e9l\u00e9brez le Jour de la Terre avec cr\u00e9ativit\u00e9! &#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_color=&#8221;#ee705f&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221;]Le Jour de la Terre\u00a02026 est une belle occasion d\u2019encourager vos \u00e9l\u00e8ves \u00e0 laisser libre cours \u00e0 leur cr\u00e9ativit\u00e9 pour exprimer leur vision de la place qu\u2019occupe la Terre dans leur vie. Nous leur proposons de souligner le Jour de la Terre en dessinant ou en cr\u00e9ant des \u0153uvres artistiques originales en s\u2019inspirant du monde naturel qui les entoure. Ces activit\u00e9s et les conversations qui en d\u00e9couleront, qu\u2019elles se d\u00e9roulent en classe ou \u00e0 l\u2019ext\u00e9rieur, leur feront prendre conscience \u00e0 quel point tous les \u00eatres vivants sont interreli\u00e9s et que chaque personne a le pouvoir de faire une diff\u00e9rence dans la pr\u00e9servation du seul et unique habitat que nous ayons. Faites-nous parvenir leurs dessins, photos et autres cr\u00e9ations \u00e0 l\u2019aide du lien ci-apr\u00e8s et courez la chance de gagner une microbourse pour que votre \u00e9cole puisse d\u00e9marrer ou agrandir\/enrichir son potager![\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;0px||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/01\/NF-Image-from-Dennis-e-1200&#215;650-1.jpeg&#8221; title_text=&#8221;NF Image from Dennis-e 1200&#215;650&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;2%||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|4%|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;20 bourses offertes!&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_color=&#8221;#0f4761&#8243; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221;]Ces microbourses visent \u00e0 permettre aux \u00e9coles de d\u00e9marrer ou d\u2019enrichir un potager :[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|3%|0px|3%|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221;]<\/p>\n<ul>\n<li>Une bourse de 1 000 $ <\/li>\n<li>Quatre bourses de 500 $ <\/li>\n<li>15 bourses de 250 $<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#e8e8e8&#8243; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;5%|5%|5%|5%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|true&#8221; custom_padding=&#8221;||||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|5%|0px|0px|true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Id\u00e9es d\u2019activit\u00e9s artistiques&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_color=&#8221;#ee705f&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li><strong>Laissez-vous inspirer par la nature.<\/strong> Amorcez la journ\u00e9e par une promenade \u00e0 l\u2019ext\u00e9rieur pour observer et vous \u00e9merveiller de ce qui vous entoure. Tournez les yeux vers le ciel, observez le sol sous vos pieds\u2026 attardez-vous \u00e0 tout ce qui est petit et \u00e0 tout ce qui est grand. Vous vous sentirez renouvel\u00e9(e)s et inspir\u00e9(e)s au retour. Dessinez ce que vous aurez vu.<\/li>\n<li><strong>Recyclez et r\u00e9utilisez.<\/strong> Redonnez vie \u00e0 des bo\u00eetes d\u2019\u0153ufs en carton vides, de vieux magazines ou d\u2019autres mat\u00e9riaux usag\u00e9s pour en faire de magnifiques d\u00e9corations qui ensoleilleront votre classe.<\/li>\n<li><strong>Faites des recherches et partagez-les.<\/strong> \u00c9tudiez comment la Terre se recycle naturellement \u2013 le cycle de l\u2019eau ou encore les champignons ou insectes d\u00e9composeurs \u2013 et pr\u00e9sentez vos d\u00e9couvertes sous forme de dessin(s).<\/li>\n<li><strong>Collaborez.<\/strong> Vos projets artistiques peuvent \u00eatre individuels ou collectifs. Par exemple, unissez les efforts de toute une classe pour cr\u00e9er une murale \u00e0 l\u2019image de la beaut\u00e9 naturelle qui entoure les \u00e9l\u00e8ves au quotidien et leur engagement \u00e0 en prendre soin.<\/li>\n<li><strong>L\u2019imagination n\u2019a pas de limites!<\/strong> Nous avons h\u00e2te de voir vos tr\u00e9sors d\u2019imagination et vos projets artistiques tout \u00e0 fait uniques inspir\u00e9s du Jour de la Terre!<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|10%|true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/01\/iStock-1338989974-1200&#215;800-1.jpeg&#8221; title_text=&#8221;Children and smiling female teacher sitting in circle on grass i&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; height=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/01\/iStock-873546564-1200&#215;800-1.jpeg&#8221; title_text=&#8221;Photo of colorful drawing:  Autumn landscape, trees with yellow, orange and red leaves&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; height=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/01\/iStock-2224712707-cr-1200&#215;700-1.jpeg&#8221; title_text=&#8221;Wall, children and writing with chalk for education, cognitive development and creativity in school. Back, students and kids with learning for drawing mural, inspiration and outdoor in kindergarten&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; height=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/03\/iStock-2163025414_1200x800.jpeg&#8221; title_text=&#8221;Little preschool girl with earth globe painting with colorful chalks on ground. Positive toddler child. Happy earth day concept. Creation of children for saving world, environment and ecology.&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|1%|2%|1%|true|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;|5%|0px|5%|false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;R\u00e8gles du concours&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_color=&#8221;#0f4761&#8243; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|3%|0px|3%|true|true&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<ul>\n<li>Ce concours est ouvert \u00e0 toutes les \u00e9coles publiques du Canada.<\/li>\n<li>Nous acceptons jusqu\u2019\u00e0 10 dessins ou photos de projets artistiques par classe.<\/li>\n<li>Soumettez vos images num\u00e9ris\u00e9es ou photos en haute r\u00e9solution au format JPEG, GIF ou PNG.<\/li>\n<li>Envoyez-nous une br\u00e8ve description de la fa\u00e7on dont vos \u00e9l\u00e8ves auront c\u00e9l\u00e9br\u00e9 le Jour de la Terre 2026.<\/li>\n<li>Date limite de participation : 8 mai 2026<\/li>\n<li>Les laur\u00e9ats seront annonc\u00e9s le 21 mai 2026 par courriel et sur les r\u00e9seaux sociaux.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;Crit\u00e8res de s\u00e9lection&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_color=&#8221;#0f4761&#8243; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;0px|3%|0px|3%|true|true&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;18px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_font_size_phone=&#8221;28px&#8221;]<\/p>\n<ul>\n<li>Creativit\u00e9\u00a0:\u00a0originalit\u00e9 et caract\u00e8re novateur des activit\u00e9s.<\/li>\n<li>Participation\u00a0: les activit\u00e9s \u00e9taient-elles engageantes et rassembleuses? (envoyez-nous quelques photos des enfants dans le feu de l\u2019action).<\/li>\n<li>Sensibilisation\u00a0: les activit\u00e9s ont-elles fait valoir l\u2019importance de prot\u00e9ger la nature et l\u2019environnement aupr\u00e8s des jeunes?<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;&#8212;&#8212;&#8212;-   FORMULAIRE DE PARTICIPATION   &#8212;&#8212;&#8212;-&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#0f4761&#8243; title_font_size=&#8221;20px&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;\u00c0 remplir par l\u2019enseignant(e)&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#0f4761&#8243; title_font_size=&#8221;16px&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][wpforms_selector form_id=&#8221;418981&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|true&#8221; custom_padding_tablet=&#8221;|0px||0px|false|true&#8221; custom_padding_phone=&#8221;|0px||0px|false|true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][\/wpforms_selector][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;150px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_heading title=&#8221;Joyeux Jour de la Terre 2026!&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|700|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#ee705f&#8221; title_font_size=&#8221;40px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;0px|0px|10px|0px|false|true&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;28px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2025\/03\/iStock-1135947405-RFS.jpg&#8221; title_text=&#8221;iStock-1135947405 &#8211; RFS&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/03\/Art-Contest-Header-2026-French.png&#8221; title_text=&#8221;Art Contest Header 2026 &#8211; French&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|0px|5%|false|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;C\u00e9l\u00e9brez le [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-418970","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JOUR DE LA TERRE 2026 - Connecting Communities to the Land<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seewhatgrows.org\/fr\/jour-de-la-terre-2026-concours-de-dessins\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JOUR DE LA TERRE 2026 - Connecting Communities to the Land\" \/>\n<meta property=\"og:description\" content=\"[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/03\/Art-Contest-Header-2026-French.png&#8221; title_text=&#8221;Art Contest Header 2026 &#8211; French&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|0px|5%|false|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;C\u00e9l\u00e9brez le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seewhatgrows.org\/fr\/jour-de-la-terre-2026-concours-de-dessins\/\" \/>\n<meta property=\"og:site_name\" content=\"Connecting Communities to the Land\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-01T21:38:22+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/jour-de-la-terre-2026-concours-de-dessins\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/jour-de-la-terre-2026-concours-de-dessins\\\/\",\"name\":\"JOUR DE LA TERRE 2026 - Connecting Communities to the Land\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\"},\"datePublished\":\"2026-03-31T15:28:05+00:00\",\"dateModified\":\"2026-05-01T21:38:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/jour-de-la-terre-2026-concours-de-dessins\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seewhatgrows.org\\\/jour-de-la-terre-2026-concours-de-dessins\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/jour-de-la-terre-2026-concours-de-dessins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seewhatgrows.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JOUR DE LA TERRE 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#website\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"name\":\"Connecting Communities to the Land\",\"description\":\"Growing healthier communities, one seed at a time with Plant a Seed &amp; See What Grows Foundation\",\"publisher\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seewhatgrows.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#organization\",\"name\":\"Connecting Communities to the Land\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"contentUrl\":\"https:\\\/\\\/seewhatgrows.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Plant-a-Seed-Logo.png\",\"width\":600,\"height\":600,\"caption\":\"Connecting Communities to the Land\"},\"image\":{\"@id\":\"https:\\\/\\\/seewhatgrows.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JOUR DE LA TERRE 2026 - Connecter les communaut\u00e9s \u00e0 la terre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seewhatgrows.org\/fr\/jour-de-la-terre-2026-concours-de-dessins\/","og_locale":"fr_CA","og_type":"article","og_title":"JOUR DE LA TERRE 2026 - Connecting Communities to the Land","og_description":"[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/03\/Art-Contest-Header-2026-French.png&#8221; title_text=&#8221;Art Contest Header 2026 &#8211; French&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|true|true&#8221; custom_padding=&#8221;2%|5%|0px|5%|false|true&#8221; da_disable_devices=&#8221;off|off|off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||true|true&#8221; custom_padding=&#8221;||0px||false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;C\u00e9l\u00e9brez le [&hellip;]","og_url":"https:\/\/seewhatgrows.org\/fr\/jour-de-la-terre-2026-concours-de-dessins\/","og_site_name":"Connecting Communities to the Land","article_modified_time":"2026-05-01T21:38:22+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seewhatgrows.org\/jour-de-la-terre-2026-concours-de-dessins\/","url":"https:\/\/seewhatgrows.org\/jour-de-la-terre-2026-concours-de-dessins\/","name":"JOUR DE LA TERRE 2026 - Connecter les communaut\u00e9s \u00e0 la terre","isPartOf":{"@id":"https:\/\/seewhatgrows.org\/#website"},"datePublished":"2026-03-31T15:28:05+00:00","dateModified":"2026-05-01T21:38:22+00:00","breadcrumb":{"@id":"https:\/\/seewhatgrows.org\/jour-de-la-terre-2026-concours-de-dessins\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seewhatgrows.org\/jour-de-la-terre-2026-concours-de-dessins\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/seewhatgrows.org\/jour-de-la-terre-2026-concours-de-dessins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seewhatgrows.org\/"},{"@type":"ListItem","position":2,"name":"JOUR DE LA TERRE 2026"}]},{"@type":"WebSite","@id":"https:\/\/seewhatgrows.org\/#website","url":"https:\/\/seewhatgrows.org\/","name":"Connecter les communaut\u00e9s \u00e0 la terre","description":"Cultiver des communaut\u00e9s plus saines, une graine \u00e0 la fois avec la Fondation Plant a Seed &amp; See What Grows","publisher":{"@id":"https:\/\/seewhatgrows.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seewhatgrows.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/seewhatgrows.org\/#organization","name":"Connecter les communaut\u00e9s \u00e0 la terre","url":"https:\/\/seewhatgrows.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/","url":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","contentUrl":"https:\/\/seewhatgrows.org\/wp-content\/uploads\/2026\/06\/Plant-a-Seed-Logo.png","width":600,"height":600,"caption":"Connecting Communities to the Land"},"image":{"@id":"https:\/\/seewhatgrows.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/pages\/418970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/comments?post=418970"}],"version-history":[{"count":0,"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/pages\/418970\/revisions"}],"wp:attachment":[{"href":"https:\/\/seewhatgrows.org\/fr\/wp-json\/wp\/v2\/media?parent=418970"}],"curies":[{"name":"bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}